{"id":78,"count":26,"description":"","link":"https:\/\/collagensei.com\/ar\/category\/collagen\/","name":"\u0627\u0644\u0643\u0648\u0644\u0627\u062c\u064a\u0646","slug":"%d8%a7%d9%84%d9%83%d9%88%d9%84%d8%a7%d8%ac%d9%8a%d9%86","taxonomy":"category","parent":0,"meta":[],"_links":{"self":[{"href":"https:\/\/collagensei.com\/ar\/wp-json\/wp\/v2\/categories\/78","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/collagensei.com\/ar\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/collagensei.com\/ar\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/collagensei.com\/ar\/wp-json\/wp\/v2\/posts?categories=78"}],"curies":[{"name":"\u062f\u0628\u0644\u064a\u0648 \u0628\u064a","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}