{"id":14822,"date":"2026-01-08T13:38:53","date_gmt":"2026-01-08T05:38:53","guid":{"rendered":"https:\/\/collagensei.com\/?page_id=14822"},"modified":"2026-01-08T13:52:57","modified_gmt":"2026-01-08T05:52:57","slug":"poudre-de-resveratrol","status":"publish","type":"page","link":"https:\/\/collagensei.com\/fr\/specialty-ingredients\/resveratrol-powder\/","title":{"rendered":"Poudre de resv\u00e9ratrol"},"content":{"rendered":"<div data-elementor-type=\"wp-page\" data-elementor-id=\"14822\" class=\"elementor elementor-14822\" data-elementor-post-type=\"page\">\n\t\t\t\t<div class=\"elementor-element elementor-element-1c854d8a e-flex e-con-boxed e-con e-parent\" data-id=\"1c854d8a\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-7238b1ac e-con-full e-flex e-con e-child\" data-id=\"7238b1ac\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-41ff07be e-con-full e-flex e-con e-child\" data-id=\"41ff07be\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-2f301beb elementor-widget__width-initial elementor-widget elementor-widget-image\" data-id=\"2f301beb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"800\" height=\"800\" src=\"https:\/\/collagensei.com\/wp-content\/uploads\/2026\/01\/Resveratrol.webp\" class=\"attachment-large size-large wp-image-14737\" alt=\"Poudre de resv\u00e9ratrol\" srcset=\"https:\/\/collagensei.com\/wp-content\/uploads\/2026\/01\/Resveratrol.webp 800w, https:\/\/collagensei.com\/wp-content\/uploads\/2026\/01\/Resveratrol-300x300.webp 300w, https:\/\/collagensei.com\/wp-content\/uploads\/2026\/01\/Resveratrol-150x150.webp 150w, https:\/\/collagensei.com\/wp-content\/uploads\/2026\/01\/Resveratrol-768x768.webp 768w, https:\/\/collagensei.com\/wp-content\/uploads\/2026\/01\/Resveratrol-12x12.webp 12w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-51332989 e-con-full e-flex e-con e-child\" data-id=\"51332989\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-620975fc elementor-widget elementor-widget-heading\" data-id=\"620975fc\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">Exploiter le pouvoir de la long\u00e9vit\u00e9 avec la poudre de trans-resv\u00e9ratrol de Gensei<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6766455a elementor-widget elementor-widget-text-editor\" data-id=\"6766455a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Sur le march\u00e9 mondial des antioxydants naturels, Gensei s'est impos\u00e9 comme l'un des principaux fabricants de poudre de resv\u00e9ratrol, qui se consacre \u00e0 la fourniture d'un trans-resv\u00e9ratrol de la plus haute qualit\u00e9. Provenant principalement d'extraits de Polygonum cuspidatum (Renou\u00e9e g\u00e9ante) de premi\u00e8re qualit\u00e9, notre produit est soumis \u00e0 un processus de purification rigoureux afin d'isoler l'isom\u00e8re trans actif, qui est responsable de la puissante activit\u00e9 biologique du compos\u00e9.<\/p><p>Contrairement aux fournisseurs de produits g\u00e9n\u00e9riques, Gensei se concentre sur les d\u00e9tails critiques qui importent aux formulateurs. Nous sommes sp\u00e9cialis\u00e9s dans la production de poudre blanche de resv\u00e9ratrol haut de gamme (dosage &gt;99%), \u00e9liminant les teintes jaun\u00e2tres ou brun\u00e2tres que l'on trouve dans les produits de qualit\u00e9 inf\u00e9rieure. Notre produit est donc parfait pour les applications cosm\u00e9tiques soucieuses de l'esth\u00e9tique et les compl\u00e9ments alimentaires haut de gamme. Que vous recherchiez de la poudre d'extrait de resv\u00e9ratrol pour des formules de sant\u00e9 cardiaque ou des s\u00e9rums anti-\u00e2ge, Gensei garantit une faible teneur en r\u00e9sidus de solvants et une stabilit\u00e9 sup\u00e9rieure. En tant que source de confiance pour la poudre de resv\u00e9ratrol chinoise, nous comblons le foss\u00e9 entre la fabrication rentable et les normes de qualit\u00e9 internationales. Am\u00e9liorez votre marque avec la poudre de resv\u00e9ratrol en vrac de Gensei, o\u00f9 la puret\u00e9 rencontre la performance.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-1887f546 e-con-full e-flex e-con e-child\" data-id=\"1887f546\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-1cc10d51 elementor-widget elementor-widget-text-editor\" data-id=\"1cc10d51\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><i><b>A noter :<\/b>\u00a0Nous sommes un fournisseur en gros et les quantit\u00e9s command\u00e9es sont minimales.<\/i><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-748bb8ea elementor-align-left elementor-widget elementor-widget-button\" data-id=\"748bb8ea\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"#elementor-action%3Aaction%3Dpopup%3Aopen%26settings%3DeyJpZCI6IjQ5OTIiLCJ0b2dnbGUiOmZhbHNlfQ%3D%3D\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Demande de devis<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7849f576 elementor-widget elementor-widget-text-editor\" data-id=\"7849f576\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Vous avez des questions sur ce produit ? Notre \u00e9quipe est l\u00e0 pour vous aider. Pour les demandes concernant plusieurs ingr\u00e9dients, veuillez utiliser le formulaire de demande de renseignements.\u00a0<a href=\"https:\/\/collagensei.com\/fr\/nous-contacter\/\">Nous contacter<\/a>\u00a0et inclure la liste des ingr\u00e9dients dans votre message.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-1434e85b e-con-full e-flex e-con e-child\" data-id=\"1434e85b\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-2c49ddeb e-con-full e-flex e-con e-child\" data-id=\"2c49ddeb\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-432c0b91 elementor-widget elementor-widget-text-editor\" data-id=\"432c0b91\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<table data-path-to-node=\"13\"><thead><tr><td><strong>Param\u00e8tre<\/strong><\/td><td><strong>Sp\u00e9cifications<\/strong><\/td><\/tr><\/thead><tbody><tr><td><span data-path-to-node=\"13,1,0,0\"><b data-path-to-node=\"13,1,0,0\" data-index-in-node=\"0\">Nom du produit<\/b><\/span><\/td><td><span data-path-to-node=\"13,1,1,0\">Trans-Resveratrol en poudre<\/span><\/td><\/tr><tr><td><span data-path-to-node=\"13,2,0,0\"><b data-path-to-node=\"13,2,0,0\" data-index-in-node=\"0\">No CAS<\/b><\/span><\/td><td><span data-path-to-node=\"13,2,1,0\">501-36-0<\/span><\/td><\/tr><tr><td><span data-path-to-node=\"13,3,0,0\"><b data-path-to-node=\"13,3,0,0\" data-index-in-node=\"0\">Nom chimique<\/b><\/span><\/td><td><span data-path-to-node=\"13,3,1,0\">3,4\u2032,5-Trihydroxystilb\u00e8ne<\/span><\/td><\/tr><tr><td><span data-path-to-node=\"13,4,0,0\"><b data-path-to-node=\"13,4,0,0\" data-index-in-node=\"0\">Synonymes<\/b><\/span><\/td><td><span data-path-to-node=\"13,4,1,0\">Trans-Resv\u00e9ratrol ; Resv\u00e9ratrol ; Protykin<\/span><\/td><\/tr><tr><td><span data-path-to-node=\"13,5,0,0\"><b data-path-to-node=\"13,5,0,0\" data-index-in-node=\"0\">Num\u00e9ro CB<\/b><\/span><\/td><td><span data-path-to-node=\"13,5,1,0\">CB4128503<\/span><\/td><\/tr><tr><td><span data-path-to-node=\"13,6,0,0\"><b data-path-to-node=\"13,6,0,0\" data-index-in-node=\"0\">Formule mol\u00e9culaire<\/b><\/span><\/td><td><span data-path-to-node=\"13,6,1,0\"><span class=\"math-inline\" data-math=\"C_{14}H_{12}O_{3}\" data-index-in-node=\"0\">C14H12O3<\/span><\/span><\/td><\/tr><tr><td><span data-path-to-node=\"13,7,0,0\"><b data-path-to-node=\"13,7,0,0\" data-index-in-node=\"0\">Poids mol\u00e9culaire<\/b><\/span><\/td><td><span data-path-to-node=\"13,7,1,0\">228,24 g\/mol<\/span><\/td><\/tr><tr><td><span data-path-to-node=\"13,8,0,0\"><b data-path-to-node=\"13,8,0,0\" data-index-in-node=\"0\">Num\u00e9ro MDL<\/b><\/span><\/td><td><span data-path-to-node=\"13,8,1,0\">MFCD00133502<\/span><\/td><\/tr><tr><td><span data-path-to-node=\"13,9,0,0\"><b data-path-to-node=\"13,9,0,0\" data-index-in-node=\"0\">Essai (puret\u00e9)<\/b><\/span><\/td><td><span data-path-to-node=\"13,9,1,0\">98% (HPLC)<\/span><\/td><\/tr><tr><td><span data-path-to-node=\"13,10,0,0\"><b data-path-to-node=\"13,10,0,0\" data-index-in-node=\"0\">Apparence<\/b><\/span><\/td><td><span data-path-to-node=\"13,10,1,0\">Poudre blanc cass\u00e9 \u00e0 blanc pur<\/span><\/td><\/tr><tr><td><span data-path-to-node=\"13,11,0,0\"><b data-path-to-node=\"13,11,0,0\" data-index-in-node=\"0\">Solvant utilis\u00e9<\/b><\/span><\/td><td><span data-path-to-node=\"13,11,1,0\">\u00c9thanol et eau (pas de m\u00e9thanol)<\/span><\/td><\/tr><tr><td><span data-path-to-node=\"13,12,0,0\"><b data-path-to-node=\"13,12,0,0\" data-index-in-node=\"0\">Taille des particules<\/b><\/span><\/td><td><span data-path-to-node=\"13,12,1,0\">95% pass 80 mesh (Micronis\u00e9 disponible)<\/span><\/td><\/tr><tr><td><span data-path-to-node=\"13,13,0,0\"><b data-path-to-node=\"13,13,0,0\" data-index-in-node=\"0\">Stockage<\/b><\/span><\/td><td><span data-path-to-node=\"13,13,1,0\">Stocker dans un endroit frais et sec, \u00e0 l'abri de la lumi\u00e8re<\/span><\/td><\/tr><\/tbody><\/table>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-105786b1 e-con-full e-flex e-con e-child\" data-id=\"105786b1\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-65279bd8 elementor-widget elementor-widget-image\" data-id=\"65279bd8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"500\" height=\"500\" src=\"https:\/\/collagensei.com\/wp-content\/uploads\/2026\/01\/Resveratrol-1.webp\" class=\"attachment-large size-large wp-image-14747\" alt=\"\" srcset=\"https:\/\/collagensei.com\/wp-content\/uploads\/2026\/01\/Resveratrol-1.webp 500w, https:\/\/collagensei.com\/wp-content\/uploads\/2026\/01\/Resveratrol-1-300x300.webp 300w, https:\/\/collagensei.com\/wp-content\/uploads\/2026\/01\/Resveratrol-1-150x150.webp 150w, https:\/\/collagensei.com\/wp-content\/uploads\/2026\/01\/Resveratrol-1-12x12.webp 12w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-3375f0bf e-flex e-con-boxed e-con e-parent\" data-id=\"3375f0bf\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-1564974e elementor-widget__width-inherit elementor-widget elementor-widget-html\" data-id=\"1564974e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<!DOCTYPE html>\r\n<html lang=\"en\">\r\n<head>\r\n<meta charset=\"UTF-8\">\r\n<style>\r\n    .flow-wrapper {\r\n        font-family: 'Segoe UI', Roboto, Helvetica, Arial, sans-serif;\r\n        max-width: 800px;\r\n        margin: 40px auto;\r\n        color: #333;\r\n    }\r\n    .flow-title {\r\n        text-align: center;\r\n        color: #5e2a84; \/* Grape\/Resveratrol Purple *\/\r\n        font-size: 24px;\r\n        margin-bottom: 30px;\r\n        border-bottom: 2px solid #5e2a84;\r\n        display: inline-block;\r\n        padding-bottom: 10px;\r\n        position: relative;\r\n        left: 50%;\r\n        transform: translateX(-50%);\r\n    }\r\n    .flow-step {\r\n        display: flex;\r\n        align-items: center;\r\n        background: #fdfdfd;\r\n        border: 1px solid #e0e0e0;\r\n        border-radius: 8px;\r\n        padding: 15px;\r\n        margin-bottom: 20px;\r\n        box-shadow: 0 4px 6px rgba(0,0,0,0.05);\r\n        transition: transform 0.2s;\r\n        position: relative;\r\n    }\r\n    .flow-step:hover {\r\n        transform: translateY(-3px);\r\n        box-shadow: 0 6px 12px rgba(94, 42, 132, 0.15);\r\n        border-color: #5e2a84;\r\n    }\r\n    .step-number {\r\n        background-color: #5e2a84;\r\n        color: white;\r\n        width: 40px;\r\n        height: 40px;\r\n        border-radius: 50%;\r\n        display: flex;\r\n        justify-content: center;\r\n        align-items: center;\r\n        font-weight: bold;\r\n        font-size: 18px;\r\n        margin-right: 20px;\r\n        flex-shrink: 0;\r\n    }\r\n    .step-content {\r\n        flex-grow: 1;\r\n    }\r\n    .step-title {\r\n        font-weight: bold;\r\n        font-size: 18px;\r\n        color: #2c3e50;\r\n        margin-bottom: 5px;\r\n    }\r\n    .step-desc {\r\n        font-size: 14px;\r\n        color: #666;\r\n        line-height: 1.5;\r\n    }\r\n    .arrow-down {\r\n        text-align: center;\r\n        color: #ccc;\r\n        font-size: 24px;\r\n        margin-top: -15px;\r\n        margin-bottom: 5px;\r\n        font-weight: bold;\r\n    }\r\n    \/* Mobile responsive *\/\r\n    @media (max-width: 600px) {\r\n        .flow-step {\r\n            flex-direction: column;\r\n            text-align: center;\r\n        }\r\n        .step-number {\r\n            margin-right: 0;\r\n            margin-bottom: 10px;\r\n        }\r\n    }\r\n<\/style>\r\n<\/head>\r\n<body>\r\n\r\n<div class=\"flow-wrapper\">\r\n    <h2 class=\"flow-title\">Processus d'extraction de haute puret\u00e9 de Gensei<\/h2>\r\n\r\n    <div class=\"flow-step\">\r\n        <div class=\"step-number\">1<\/div>\r\n        <div class=\"step-content\">\r\n            <div class=\"step-title\">Pr\u00e9paration des mati\u00e8res premi\u00e8res<\/div>\r\n            <div class=\"step-desc\">S\u00e9lection de la prime <i>Polygonum cuspidatum<\/i> racines. Lavage, s\u00e9chage et broyage grossier pour augmenter la surface d'extraction.<\/div>\r\n        <\/div>\r\n    <\/div>\r\n    <div class=\"arrow-down\">\u2193<\/div>\r\n\r\n    <div class=\"flow-step\">\r\n        <div class=\"step-number\">2<\/div>\r\n        <div class=\"step-content\">\r\n            <div class=\"step-title\">Extraction par solvant (Reflux)<\/div>\r\n            <div class=\"step-desc\">Extraction \u00e0 reflux en plusieurs \u00e9tapes \u00e0 l'aide d'un m\u00e9lange d'\u00e9thanol et d'eau de qualit\u00e9 alimentaire. Ce processus doux prot\u00e8ge la bioactivit\u00e9 du resv\u00e9ratrol.<\/div>\r\n        <\/div>\r\n    <\/div>\r\n    <div class=\"arrow-down\">\u2193<\/div>\r\n\r\n    <div class=\"flow-step\">\r\n        <div class=\"step-number\">3<\/div>\r\n        <div class=\"step-content\">\r\n            <div class=\"step-title\">Concentration et filtration<\/div>\r\n            <div class=\"step-desc\">\u00c9vaporation sous vide pour r\u00e9cup\u00e9rer le solvant \u00e9thanol. L'extrait liquide est filtr\u00e9 pour \u00e9liminer les fibres v\u00e9g\u00e9tales et les insolubles.<\/div>\r\n        <\/div>\r\n    <\/div>\r\n    <div class=\"arrow-down\">\u2193<\/div>\r\n\r\n    <div class=\"flow-step\">\r\n        <div class=\"step-number\">4<\/div>\r\n        <div class=\"step-content\">\r\n            <div class=\"step-title\">Purification (Chromatographie)<\/div>\r\n            <div class=\"step-desc\"><strong>\u00c9tape critique :<\/strong> Passage dans des colonnes de r\u00e9sine macroporeuse pour s\u00e9parer le trans-resv\u00e9ratrol des impuret\u00e9s telles que l'\u00e9modine et les sucres.<\/div>\r\n        <\/div>\r\n    <\/div>\r\n    <div class=\"arrow-down\">\u2193<\/div>\r\n\r\n    <div class=\"flow-step\">\r\n        <div class=\"step-number\">5<\/div>\r\n        <div class=\"step-content\">\r\n            <div class=\"step-title\">Cristallisation et centrifugation<\/div>\r\n            <div class=\"step-desc\">Refroidissement contr\u00f4l\u00e9 pour former des cristaux de haute puret\u00e9. La centrifugation permet de s\u00e9parer les cristaux de la liqueur m\u00e8re.<\/div>\r\n        <\/div>\r\n    <\/div>\r\n    <div class=\"arrow-down\">\u2193<\/div>\r\n\r\n    <div class=\"flow-step\">\r\n        <div class=\"step-number\">6<\/div>\r\n        <div class=\"step-content\">\r\n            <div class=\"step-title\">S\u00e9chage sous vide<\/div>\r\n            <div class=\"step-desc\">S\u00e9chage \u00e0 basse temp\u00e9rature sous vide pour \u00e9viter l'oxydation et garantir un faible r\u00e9sidu de solvant (&lt; 5000ppm).<\/div>\r\n        <\/div>\r\n    <\/div>\r\n    <div class=\"arrow-down\">\u2193<\/div>\r\n\r\n    <div class=\"flow-step\">\r\n        <div class=\"step-number\">7<\/div>\r\n        <div class=\"step-content\">\r\n            <div class=\"step-title\">Broyage et tamisage<\/div>\r\n            <div class=\"step-desc\">Micronisation pour obtenir une taille de particule standard (95% pass 80 mesh) pour un m\u00e9lange uniforme dans les suppl\u00e9ments.<\/div>\r\n        <\/div>\r\n    <\/div>\r\n    <div class=\"arrow-down\">\u2193<\/div>\r\n\r\n    <div class=\"flow-step\" style=\"border-left: 5px solid #27ae60;\">\r\n        <div class=\"step-number\" style=\"background-color: #27ae60;\">8<\/div>\r\n        <div class=\"step-content\">\r\n            <div class=\"step-title\">Contr\u00f4le de qualit\u00e9 final et emballage<\/div>\r\n            <div class=\"step-desc\">Tests complets (analyse HPLC, m\u00e9taux lourds, microbes). Emball\u00e9s dans des doubles sacs LDPE \u00e0 l'int\u00e9rieur de f\u00fbts en fibre.<\/div>\r\n        <\/div>\r\n    <\/div>\r\n\r\n<\/div>\r\n\r\n<\/body>\r\n<\/html>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-6c07c5ab e-flex e-con-boxed e-con e-parent\" data-id=\"6c07c5ab\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-6661b77d elementor-widget elementor-widget-heading\" data-id=\"6661b77d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Pourquoi choisir Gensei comme fournisseur de resv\u00e9ratrol ?<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-30ed52be elementor-widget elementor-widget-text-editor\" data-id=\"30ed52be\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p data-path-to-node=\"22\">Nos normes de fabrication rigoureuses garantissent que <b data-path-to-node=\"22\" data-index-in-node=\"49\">Gensei<\/b>\u2018Le resv\u00e9ratrol d'Erika est adapt\u00e9 aux industries les plus exigeantes :<\/p><ul><li style=\"list-style-type: none;\"><ul data-path-to-node=\"23\"><li><p data-path-to-node=\"23,0,0\"><b data-path-to-node=\"23,0,0\" data-index-in-node=\"0\">\ud83d\udc8a Compl\u00e9ments alimentaires (c\u0153ur et long\u00e9vit\u00e9)<\/b> En tant qu'activateur puissant de SIRT1, notre <b data-path-to-node=\"23,0,0\" data-index-in-node=\"76\">resv\u00e9ratrol en poudre<\/b> est un produit de base dans les g\u00e9lules anti-\u00e2ge et les comprim\u00e9s de soutien cardiovasculaire. La densit\u00e9 \u00e9lev\u00e9e de notre poudre garantit un remplissage efficace des g\u00e9lules dures.<\/p><\/li><li><p data-path-to-node=\"23,1,0\"><b data-path-to-node=\"23,1,0\" data-index-in-node=\"0\">\ud83d\udc84 Cosm\u00e9tiques et soins de la peau (blanchiment et anti-oxydation)<\/b> Notre prime <b data-path-to-node=\"23,1,0\" data-index-in-node=\"65\">resv\u00e9ratrol poudre blanche<\/b> (99%) est sp\u00e9cialement con\u00e7u pour les formulations cosm\u00e9tiques. Contrairement aux extraits de moindre puret\u00e9 (50%) qui sont bruns, notre poudre blanche n'alt\u00e8re pas la couleur des cr\u00e8mes ou des s\u00e9rums tout en offrant de puissants effets antioxydants et \u00e9claircissants pour la peau.<\/p><\/li><li><p data-path-to-node=\"23,2,0\"><b data-path-to-node=\"23,2,0\" data-index-in-node=\"0\">\ud83e\udd64 Aliments fonctionnels<\/b> Incorpor\u00e9 dans les barres \u00e9nerg\u00e9tiques et les boissons fonctionnelles pour ses bienfaits sur la sant\u00e9 m\u00e9tabolique.<\/p><\/li><\/ul><\/li><\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-294d80b e-flex e-con-boxed e-con e-parent\" data-id=\"294d80b\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-dc5f321 elementor-widget elementor-widget-heading\" data-id=\"dc5f321\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Applications et solutions<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-52c4834 elementor-widget elementor-widget-text-editor\" data-id=\"52c4834\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<ul><li><p data-path-to-node=\"26,0,0\"><b data-path-to-node=\"26,0,0\" data-index-in-node=\"0\">Contr\u00f4le sup\u00e9rieur des couleurs :<\/b> De nombreux fournisseurs proposent le resv\u00e9ratrol 98% qui est encore l\u00e9g\u00e8rement beige. <b data-path-to-node=\"26,0,0\" data-index-in-node=\"91\">Gensei<\/b> utilise une technologie de recristallisation avanc\u00e9e pour obtenir un taux d'humidit\u00e9 de l'ordre de 1 %. <b data-path-to-node=\"26,0,0\" data-index-in-node=\"158\">resv\u00e9ratrol poudre blanche<\/b> qui r\u00e9pond aux exigences esth\u00e9tiques strictes des marques de soins de luxe.<\/p><\/li><li><p data-path-to-node=\"26,1,0\"><b data-path-to-node=\"26,1,0\" data-index-in-node=\"0\">Isom\u00e8re \u201cTrans\u201d garanti :<\/b> Nous contr\u00f4lons strictement le processus de conversion afin de garantir que le produit est conforme \u00e0 la norme. <i data-path-to-node=\"26,1,0\" data-index-in-node=\"109\">Trans<\/i>-Le resv\u00e9ratrol, la forme bioactive, plut\u00f4t que la forme inactive. <i data-path-to-node=\"26,1,0\" data-index-in-node=\"173\">Cis<\/i>-forme.<\/p><\/li><li><p data-path-to-node=\"26,2,0\"><b data-path-to-node=\"26,2,0\" data-index-in-node=\"0\">Fabricant fiable :<\/b> En tant que professionnel <b data-path-to-node=\"26,2,0\" data-index-in-node=\"41\">resv\u00e9ratrol <a class=\"wpil_keyword_link\" href=\"https:\/\/collagensei.com\/fr\/fabricant-de-complements-en-poudre\/\" target=\"_blank\"  rel=\"noopener\" title=\"Fabricant de suppl\u00e9ments en poudre\" data-wpil-keyword-link=\"linked\"  data-wpil-monitor-id=\"1041\">fabricant de poudre<\/a><\/b>, Nous disposons d'une tra\u00e7abilit\u00e9 compl\u00e8te depuis l'herbe brute (<i data-path-to-node=\"26,2,0\" data-index-in-node=\"119\">Polygonum cuspidatum<\/i>) jusqu'au tambour fini.<\/p><\/li><li><p data-path-to-node=\"26,3,0\"><b data-path-to-node=\"26,3,0\" data-index-in-node=\"0\">La s\u00e9curit\u00e9 avant tout :<\/b> Notre processus d'extraction r\u00e9duit l'Emodin (un compos\u00e9 laxatif pr\u00e9sent dans la plante brute) \u00e0 des niveaux s\u00fbrs, \u00e0 l'\u00e9tat de traces (&lt;0,1%), \u00e9vitant ainsi les effets secondaires digestifs chez les consommateurs finaux.<\/p><\/li><\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-4dccc3a8 e-flex e-con-boxed e-con e-parent\" data-id=\"4dccc3a8\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-70909159 e-con-full e-flex e-con e-child\" data-id=\"70909159\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-2c242a10 elementor-widget elementor-widget-heading\" data-id=\"2c242a10\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Nos installations de fabrication ultramodernes<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c5924e6 elementor-widget elementor-widget-text-editor\" data-id=\"c5924e6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>D\u00e9couvrez nos installations modernes dot\u00e9es d'une technologie de pointe pour garantir la plus haute qualit\u00e9 dans la production de vos vitamines, extraits de plantes, min\u00e9raux et acides amin\u00e9s.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-55139ac5 e-con-full e-flex e-con e-child\" data-id=\"55139ac5\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-5063306c elementor-arrows-position-inside elementor-pagination-position-outside elementor-widget elementor-widget-image-carousel\" data-id=\"5063306c\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;slides_to_show&quot;:&quot;3&quot;,&quot;slides_to_scroll&quot;:&quot;1&quot;,&quot;lazyload&quot;:&quot;yes&quot;,&quot;image_spacing_custom&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:5,&quot;sizes&quot;:[]},&quot;navigation&quot;:&quot;both&quot;,&quot;autoplay&quot;:&quot;yes&quot;,&quot;pause_on_hover&quot;:&quot;yes&quot;,&quot;pause_on_interaction&quot;:&quot;yes&quot;,&quot;autoplay_speed&quot;:5000,&quot;infinite&quot;:&quot;yes&quot;,&quot;speed&quot;:500,&quot;image_spacing_custom_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;image_spacing_custom_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]}}\" data-widget_type=\"image-carousel.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-image-carousel-wrapper swiper\" role=\"region\" aria-roledescription=\"carousel\" aria-label=\"Carrousel d&#039;images\" dir=\"rtl\">\n\t\t\t<div class=\"elementor-image-carousel swiper-wrapper swiper-image-stretch\" aria-live=\"off\">\n\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"1 \u0438\u0437 11\" data-no-translation-aria-label=\"\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image swiper-lazy\" data-src=\"https:\/\/collagensei.com\/wp-content\/uploads\/2025\/04\/Machining-machine-12-768x576.webp\" alt=\"Machine d&#039;usinage (12)\" \/><div class=\"swiper-lazy-preloader\"><\/div><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"2 \u0438\u0437 11\" data-no-translation-aria-label=\"\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image swiper-lazy\" data-src=\"https:\/\/collagensei.com\/wp-content\/uploads\/2025\/04\/Machining-machine-11-768x576.webp\" alt=\"Machine d&#039;usinage (11)\" \/><div class=\"swiper-lazy-preloader\"><\/div><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"3 \u0438\u0437 11\" data-no-translation-aria-label=\"\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image swiper-lazy\" data-src=\"https:\/\/collagensei.com\/wp-content\/uploads\/2025\/04\/Machining-machine-10-768x576.webp\" alt=\"Machine d&#039;usinage (10)\" \/><div class=\"swiper-lazy-preloader\"><\/div><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"4 \u0438\u0437 11\" data-no-translation-aria-label=\"\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image swiper-lazy\" data-src=\"https:\/\/collagensei.com\/wp-content\/uploads\/2025\/04\/Machining-machine-9-768x576.webp\" alt=\"Machine d&#039;usinage (9)\" \/><div class=\"swiper-lazy-preloader\"><\/div><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"5 \u0438\u0437 11\" data-no-translation-aria-label=\"\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image swiper-lazy\" data-src=\"https:\/\/collagensei.com\/wp-content\/uploads\/2025\/04\/Machining-machine-8-768x576.webp\" alt=\"Machine d&#039;usinage (8)\" \/><div class=\"swiper-lazy-preloader\"><\/div><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"6 \u0438\u0437 11\" data-no-translation-aria-label=\"\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image swiper-lazy\" data-src=\"https:\/\/collagensei.com\/wp-content\/uploads\/2025\/04\/Machining-machine-7-768x576.webp\" alt=\"Machine d&#039;usinage (7)\" \/><div class=\"swiper-lazy-preloader\"><\/div><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"7 \u0438\u0437 11\" data-no-translation-aria-label=\"\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image swiper-lazy\" data-src=\"https:\/\/collagensei.com\/wp-content\/uploads\/2025\/04\/Machining-machine-6-768x576.webp\" alt=\"Machine d&#039;usinage (6)\" \/><div class=\"swiper-lazy-preloader\"><\/div><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"8 \u0438\u0437 11\" data-no-translation-aria-label=\"\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image swiper-lazy\" data-src=\"https:\/\/collagensei.com\/wp-content\/uploads\/2025\/04\/Machining-machine-5-768x576.webp\" alt=\"Machine d&#039;usinage (5)\" \/><div class=\"swiper-lazy-preloader\"><\/div><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"9 \u0438\u0437 11\" data-no-translation-aria-label=\"\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image swiper-lazy\" data-src=\"https:\/\/collagensei.com\/wp-content\/uploads\/2025\/04\/Machining-machine-4-768x575.webp\" alt=\"Machine d&#039;usinage (4)\" \/><div class=\"swiper-lazy-preloader\"><\/div><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"10 \u0438\u0437 11\" data-no-translation-aria-label=\"\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image swiper-lazy\" data-src=\"https:\/\/collagensei.com\/wp-content\/uploads\/2025\/04\/Machining-machine-2-768x576.webp\" alt=\"Machine d&#039;usinage (2)\" \/><div class=\"swiper-lazy-preloader\"><\/div><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"11 \u0438\u0437 11\" data-no-translation-aria-label=\"\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image swiper-lazy\" data-src=\"https:\/\/collagensei.com\/wp-content\/uploads\/2025\/04\/Machining-machine-1-768x576.webp\" alt=\"Machine d&#039;usinage (1)\" \/><div class=\"swiper-lazy-preloader\"><\/div><\/figure><\/div>\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-prev\" role=\"button\" tabindex=\"0\">\n\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-eicon-chevron-left\" viewbox=\"0 0 1000 1000\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M646 125C629 125 613 133 604 142L308 442C296 454 292 471 292 487 292 504 296 521 308 533L604 854C617 867 629 875 646 875 663 875 679 871 692 858 704 846 713 829 713 812 713 796 708 779 692 767L438 487 692 225C700 217 708 204 708 187 708 171 704 154 692 142 675 129 663 125 646 125Z\"><\/path><\/svg>\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-next\" role=\"button\" tabindex=\"0\">\n\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-eicon-chevron-right\" viewbox=\"0 0 1000 1000\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M696 533C708 521 713 504 713 487 713 471 708 454 696 446L400 146C388 133 375 125 354 125 338 125 325 129 313 142 300 154 292 171 292 187 292 204 296 221 308 233L563 492 304 771C292 783 288 800 288 817 288 833 296 850 308 863 321 871 338 875 354 875 371 875 388 867 400 854L696 533Z\"><\/path><\/svg>\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"swiper-pagination\"><\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-4ee0d328 e-flex e-con-boxed e-con e-parent\" data-id=\"4ee0d328\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-6e9d71a3 elementor-widget elementor-widget-heading\" data-id=\"6e9d71a3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">FAQ<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5744d1e4 uael-faq-box-layout-yes align-at-left elementor-widget elementor-widget-uael-faq\" data-id=\"5744d1e4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"uael-faq.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n\t\t\t<div id='uael-faq-wrapper-146' class=\"uael-faq-wrapper\">\n\t\t\t\t<div class=\"uael-faq-container uael-faq-layout-accordion\" data-layout=\"accordion\" >\n\t\t\t\t\t\t\t\t\t\t\t\t<div id=\"uael-accordion-d2d342b\" class=\"uael-faq-accordion\" role=\"tablist\">\n\t\t\t\t\t\t\t\t<div class= \"uael-accordion-title\" aria-expanded=\"false\" role=\"tab\">\n\t\t\t\t\t\t\t\t\t<span class=\"uael-accordion-icon uael-accordion-icon-left\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"uael-accordion-icon-closed\"><svg class=\"e-font-icon-svg e-fas-angle-right\" viewbox=\"0 0 256 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M224.3 273l-136 136c-9.4 9.4-24.6 9.4-33.9 0l-22.6-22.6c-9.4-9.4-9.4-24.6 0-33.9l96.4-96.4-96.4-96.4c-9.4-9.4-9.4-24.6 0-33.9L54.3 103c9.4-9.4 24.6-9.4 33.9 0l136 136c9.5 9.4 9.5 24.6.1 34z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"uael-accordion-icon-opened\"><svg class=\"e-font-icon-svg e-fas-angle-up\" viewbox=\"0 0 320 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M177 159.7l136 136c9.4 9.4 9.4 24.6 0 33.9l-22.6 22.6c-9.4 9.4-24.6 9.4-33.9 0L160 255.9l-96.4 96.4c-9.4 9.4-24.6 9.4-33.9 0L7 329.7c-9.4-9.4-9.4-24.6 0-33.9l136-136c9.4-9.5 24.6-9.5 34-.1z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"uael-question-d2d342b uael-question-span\" tabindex=\"0\" id=\"uael-faq-1-6a03e9b7606d6\">Quelle est la source de votre resv\u00e9ratrol ?<\/span>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"uael-accordion-content\" role=\"tabpanel\">\n\t\t\t\t\t\t\t\t\t<span>\n\t\t\t\t\t\t\t\t\t<span><p><b data-path-to-node=\"33\" data-index-in-node=\"47\">Gensei<\/b>'La norme de l <b data-path-to-node=\"33\" data-index-in-node=\"65\">extrait de resv\u00e9ratrol en poudre<\/b> est d\u00e9riv\u00e9 de la racine de <i data-path-to-node=\"33\" data-index-in-node=\"120\">Polygonum cuspidatum<\/i> (Renou\u00e9e g\u00e9ante). Nous pouvons \u00e9galement fournir de l'extrait de peau de raisin ou du resv\u00e9ratrol issu de la fermentation sur demande pour des besoins marketing sp\u00e9cifiques.<\/p><\/span>\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div id=\"uael-accordion-e9b8d2f\" class=\"uael-faq-accordion\" role=\"tablist\">\n\t\t\t\t\t\t\t\t<div class= \"uael-accordion-title\" aria-expanded=\"false\" role=\"tab\">\n\t\t\t\t\t\t\t\t\t<span class=\"uael-accordion-icon uael-accordion-icon-left\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"uael-accordion-icon-closed\"><svg class=\"e-font-icon-svg e-fas-angle-right\" viewbox=\"0 0 256 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M224.3 273l-136 136c-9.4 9.4-24.6 9.4-33.9 0l-22.6-22.6c-9.4-9.4-9.4-24.6 0-33.9l96.4-96.4-96.4-96.4c-9.4-9.4-9.4-24.6 0-33.9L54.3 103c9.4-9.4 24.6-9.4 33.9 0l136 136c9.5 9.4 9.5 24.6.1 34z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"uael-accordion-icon-opened\"><svg class=\"e-font-icon-svg e-fas-angle-up\" viewbox=\"0 0 320 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M177 159.7l136 136c9.4 9.4 9.4 24.6 0 33.9l-22.6 22.6c-9.4 9.4-24.6 9.4-33.9 0L160 255.9l-96.4 96.4c-9.4 9.4-24.6 9.4-33.9 0L7 329.7c-9.4-9.4-9.4-24.6 0-33.9l136-136c9.4-9.5 24.6-9.5 34-.1z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"uael-question-e9b8d2f uael-question-span\" tabindex=\"0\" id=\"uael-faq-2-6a03e9b76073e\">Pourquoi la couleur de la poudre est-elle importante ?<\/span>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"uael-accordion-content\" role=\"tabpanel\">\n\t\t\t\t\t\t\t\t\t<span>\n\t\t\t\t\t\t\t\t\t<span><p>La couleur indique la puret\u00e9 et l'\u00e9limination des impuret\u00e9s comme les anthraquinones (Emodin). Notre <b data-path-to-node=\"34\" data-index-in-node=\"136\">resv\u00e9ratrol poudre blanche<\/b> (99%) signifie le plus haut niveau de purification, ce qui le rend id\u00e9al pour les cosm\u00e9tiques o\u00f9 l'apparence du produit est cruciale.<\/p><\/span>\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div id=\"uael-accordion-a4b829f\" class=\"uael-faq-accordion\" role=\"tablist\">\n\t\t\t\t\t\t\t\t<div class= \"uael-accordion-title\" aria-expanded=\"false\" role=\"tab\">\n\t\t\t\t\t\t\t\t\t<span class=\"uael-accordion-icon uael-accordion-icon-left\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"uael-accordion-icon-closed\"><svg class=\"e-font-icon-svg e-fas-angle-right\" viewbox=\"0 0 256 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M224.3 273l-136 136c-9.4 9.4-24.6 9.4-33.9 0l-22.6-22.6c-9.4-9.4-9.4-24.6 0-33.9l96.4-96.4-96.4-96.4c-9.4-9.4-9.4-24.6 0-33.9L54.3 103c9.4-9.4 24.6-9.4 33.9 0l136 136c9.5 9.4 9.5 24.6.1 34z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"uael-accordion-icon-opened\"><svg class=\"e-font-icon-svg e-fas-angle-up\" viewbox=\"0 0 320 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M177 159.7l136 136c9.4 9.4 9.4 24.6 0 33.9l-22.6 22.6c-9.4 9.4-24.6 9.4-33.9 0L160 255.9l-96.4 96.4c-9.4 9.4-24.6 9.4-33.9 0L7 329.7c-9.4-9.4-9.4-24.6 0-33.9l136-136c9.4-9.5 24.6-9.5 34-.1z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"uael-question-a4b829f uael-question-span\" tabindex=\"0\" id=\"uael-faq-3-6a03e9b76077d\">Puis-je obtenir un \u00e9chantillon de votre poudre de resv\u00e9ratrol en vrac ?<\/span>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"uael-accordion-content\" role=\"tabpanel\">\n\t\t\t\t\t\t\t\t\t<span>\n\t\t\t\t\t\t\t\t\t<span><p>Oui, nous proposons des \u00e9chantillons gratuits (10g-20g) \u00e0 des fins de test. En tant que <b data-path-to-node=\"35\" data-index-in-node=\"118\">Fabricant de poudre de resv\u00e9ratrol<\/b>, Nous sommes convaincus que vous serez satisfaits de notre qualit\u00e9.<\/p><\/span>\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div id=\"uael-accordion-d9f7632\" class=\"uael-faq-accordion\" role=\"tablist\">\n\t\t\t\t\t\t\t\t<div class= \"uael-accordion-title\" aria-expanded=\"false\" role=\"tab\">\n\t\t\t\t\t\t\t\t\t<span class=\"uael-accordion-icon uael-accordion-icon-left\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"uael-accordion-icon-closed\"><svg class=\"e-font-icon-svg e-fas-angle-right\" viewbox=\"0 0 256 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M224.3 273l-136 136c-9.4 9.4-24.6 9.4-33.9 0l-22.6-22.6c-9.4-9.4-9.4-24.6 0-33.9l96.4-96.4-96.4-96.4c-9.4-9.4-9.4-24.6 0-33.9L54.3 103c9.4-9.4 24.6-9.4 33.9 0l136 136c9.5 9.4 9.5 24.6.1 34z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"uael-accordion-icon-opened\"><svg class=\"e-font-icon-svg e-fas-angle-up\" viewbox=\"0 0 320 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M177 159.7l136 136c9.4 9.4 9.4 24.6 0 33.9l-22.6 22.6c-9.4 9.4-24.6 9.4-33.9 0L160 255.9l-96.4 96.4c-9.4 9.4-24.6 9.4-33.9 0L7 329.7c-9.4-9.4-9.4-24.6 0-33.9l136-136c9.4-9.5 24.6-9.5 34-.1z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"uael-question-d9f7632 uael-question-span\" tabindex=\"0\" id=\"uael-faq-4-6a03e9b7607b9\">Votre resv\u00e9ratrol est-il micronis\u00e9 ?<\/span>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"uael-accordion-content\" role=\"tabpanel\">\n\t\t\t\t\t\t\t\t\t<span>\n\t\t\t\t\t\t\t\t\t<span><p>Oui, nous proposons des mailles standard (80 mesh) ainsi que des versions micronis\u00e9es pour une meilleure biodisponibilit\u00e9 et absorption dans l'organisme.<\/p><\/span>\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-23705053 e-flex e-con-boxed e-con e-parent\" data-id=\"23705053\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-1f9ad1b9 e-con-full e-flex e-con e-child\" data-id=\"1f9ad1b9\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-6e4dbe28 elementor-widget elementor-widget-heading\" data-id=\"6e4dbe28\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Un grand nombre de personnes nous font confiance, nous sommes pr\u00eats pour vous : Lire les t\u00e9moignages et s'informer<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-5db66110 e-con-full e-flex e-con e-child\" data-id=\"5db66110\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-4c764ace e-con-full e-flex e-con e-child\" data-id=\"4c764ace\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-21d49761 elementor-testimonial--skin-default elementor-testimonial--layout-image_inline elementor-testimonial--align-center elementor-arrows-yes elementor-pagination-type-bullets elementor-widget elementor-widget-testimonial-carousel\" data-id=\"21d49761\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;show_arrows&quot;:&quot;yes&quot;,&quot;pagination&quot;:&quot;bullets&quot;,&quot;speed&quot;:500,&quot;autoplay&quot;:&quot;yes&quot;,&quot;autoplay_speed&quot;:5000,&quot;loop&quot;:&quot;yes&quot;,&quot;pause_on_hover&quot;:&quot;yes&quot;,&quot;pause_on_interaction&quot;:&quot;yes&quot;,&quot;space_between&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:10,&quot;sizes&quot;:[]},&quot;space_between_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:10,&quot;sizes&quot;:[]},&quot;space_between_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:10,&quot;sizes&quot;:[]}}\" data-widget_type=\"testimonial-carousel.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper\">\n\t\t\t\t\t<div class=\"elementor-main-swiper swiper\" role=\"region\" aria-roledescription=\"carousel\" aria-label=\"Diapositives\">\n\t\t\t\t<div class=\"swiper-wrapper\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-testimonial\">\n\t\t\t\t\t\t\t<div class=\"elementor-testimonial__content\">\n\t\t\t\t\t<div class=\"elementor-testimonial__text\">\n\t\t\t\t\t\tNous avons eu du mal \u00e0 trouver un fournisseur de poudre de resv\u00e9ratrol en Chine capable de fournir de mani\u00e8re constante de la poudre blanche pure pour notre ligne de cr\u00e8mes pour le visage. La plupart \u00e9taient trop jaunes. Gensei nous a fourni exactement ce dont nous avions besoin - une poudre blanche comme neige qui se dissout parfaitement.\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"elementor-testimonial__footer\">\n\t\t\t\t\t\t\t\t<cite class=\"elementor-testimonial__cite\"><span class=\"elementor-testimonial__name\">John Davis<\/span><span class=\"elementor-testimonial__title\">Responsable des achats, JointCare Solutions<\/span><\/cite>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-testimonial\">\n\t\t\t\t\t\t\t<div class=\"elementor-testimonial__content\">\n\t\t\t\t\t<div class=\"elementor-testimonial__text\">\n\t\t\t\t\t\tNous achetons la poudre de resv\u00e9ratrol en vrac \u00e0 la tonne pour nos compl\u00e9ments alimentaires destin\u00e9s \u00e0 la sant\u00e9 cardiaque. La constance de Gensei d'un lot \u00e0 l'autre en mati\u00e8re de dosage et de m\u00e9taux lourds est impressionnante. C'est un partenaire fiable pour les affaires \u00e0 long terme.\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"elementor-testimonial__footer\">\n\t\t\t\t\t\t\t\t<cite class=\"elementor-testimonial__cite\"><span class=\"elementor-testimonial__name\">Emily Carter<\/span><span class=\"elementor-testimonial__title\">Chef du d\u00e9veloppement des produits, Global Sports Supplements<\/span><\/cite>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-testimonial\">\n\t\t\t\t\t\t\t<div class=\"elementor-testimonial__content\">\n\t\t\t\t\t<div class=\"elementor-testimonial__text\">\n\t\t\t\t\t\tLa poudre d'extrait de resv\u00e9ratrol que nous avons re\u00e7ue de Gensei pr\u00e9sente une excellente fluidit\u00e9. Elle passe sans probl\u00e8me sur nos machines d'encapsulation \u00e0 grande vitesse, sans se bloquer. Hautement recommand\u00e9.\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"elementor-testimonial__footer\">\n\t\t\t\t\t\t\t\t<cite class=\"elementor-testimonial__cite\"><span class=\"elementor-testimonial__name\">Lisa Green<\/span><span class=\"elementor-testimonial__title\">Responsable de production, NutraBio Labs<\/span><\/cite>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-prev\" role=\"button\" tabindex=\"0\" aria-label=\"\u041f\u0440\u0435\u0434\u044b\u0434\u0443\u0449\u0430\u044f\" data-no-translation-aria-label=\"\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-eicon-chevron-left\" viewbox=\"0 0 1000 1000\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M646 125C629 125 613 133 604 142L308 442C296 454 292 471 292 487 292 504 296 521 308 533L604 854C617 867 629 875 646 875 663 875 679 871 692 858 704 846 713 829 713 812 713 796 708 779 692 767L438 487 692 225C700 217 708 204 708 187 708 171 704 154 692 142 675 129 663 125 646 125Z\"><\/path><\/svg>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-next\" role=\"button\" tabindex=\"0\" aria-label=\"\u0421\u043b\u0435\u0434\u0443\u044e\u0449\u0430\u044f\" data-no-translation-aria-label=\"\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-eicon-chevron-right\" viewbox=\"0 0 1000 1000\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M696 533C708 521 713 504 713 487 713 471 708 454 696 446L400 146C388 133 375 125 354 125 338 125 325 129 313 142 300 154 292 171 292 187 292 204 296 221 308 233L563 492 304 771C292 783 288 800 288 817 288 833 296 850 308 863 321 871 338 875 354 875 371 875 388 867 400 854L696 533Z\"><\/path><\/svg>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-pagination\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-1d73fdd e-con-full e-flex e-con e-child\" data-id=\"1d73fdd\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-7aecf4b6 uael-cf7-btn-size-xs uael-cf7-style-box uael-cf7-input-size-sm uael-cf7-button-left uael-cf7-highlight-style-default elementor-widget elementor-widget-uael-cf7-styler\" data-id=\"7aecf4b6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"uael-cf7-styler.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class = \"uael-cf7-container\">\n\t\t\t\t\t\t<div class = \"uael-cf7 uael-cf7-style elementor-clickable\">\n\t\t\t\t\t\t\n<div class=\"wpcf7 no-js\" id=\"wpcf7-f74-o1\" lang=\"zh-CN\" dir=\"ltr\" data-wpcf7-id=\"74\">\n<div class=\"screen-reader-response\"><p role=\"status\" aria-live=\"polite\" aria-atomic=\"true\"><\/p> <ul><\/ul><\/div>\n<form action=\"\/fr\/wp-json\/wp\/v2\/pages\/14822#wpcf7-f74-o1\" method=\"post\" class=\"wpcf7-form init\" aria-label=\"\u7559\u8a00\u8868\u5355\" novalidate=\"novalidate\" data-status=\"init\" data-trp-original-action=\"\/fr\/wp-json\/wp\/v2\/pages\/14822#wpcf7-f74-o1\">\n<fieldset class=\"hidden-fields-container\"><input type=\"hidden\" name=\"_wpcf7\" value=\"74\" \/><input type=\"hidden\" name=\"_wpcf7_version\" value=\"6.1.5\" \/><input type=\"hidden\" name=\"_wpcf7_locale\" value=\"zh_CN\" \/><input type=\"hidden\" name=\"_wpcf7_unit_tag\" value=\"wpcf7-f74-o1\" \/><input type=\"hidden\" name=\"_wpcf7_container_post\" value=\"0\" \/><input type=\"hidden\" name=\"_wpcf7_posted_data_hash\" value=\"\" \/>\n<\/fieldset>\n<div class=\"stay-touch\">\n\t<ul>\n\t\t<li>\n\t\t\t<p><label> Nom : <span class=\"wpcf7-form-control-wrap\" data-name=\"your-name\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"text\" name=\"your-name\" \/><\/span><\/label>\n\t\t\t<\/p>\n\t\t<\/li>\n\t\t<li>\n\t\t\t<p><label> Nom de l'entreprise : <span class=\"wpcf7-form-control-wrap\" data-name=\"your-company\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"text\" name=\"your-company\" \/><\/span><\/label>\n\t\t\t<\/p>\n\t\t<\/li>\n\t\t<li>\n\t\t\t<p><label> Courriel : <span class=\"wpcf7-form-control-wrap\" data-name=\"your-email\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"text\" name=\"your-email\" \/><\/span><\/label>\n\t\t\t<\/p>\n\t\t<\/li>\n\t\t<li>\n\t\t\t<p><label> T\u00e9l : <span class=\"wpcf7-form-control-wrap\" data-name=\"your-tel\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"text\" name=\"your-tel\" \/><\/span><\/label>\n\t\t\t<\/p>\n\t\t<\/li>\n\t\t<li>\n\t\t\t<p><label> Message : <span class=\"wpcf7-form-control-wrap\" data-name=\"your-message\"><textarea cols=\"40\" rows=\"10\" maxlength=\"2000\" class=\"wpcf7-form-control wpcf7-textarea wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" name=\"your-message\"><\/textarea><\/span><\/label>\n\t\t\t<\/p>\n\t\t<\/li>\n\t\t<li style=\"text-align:center\">\n\t\t\t<p><input class=\"wpcf7-form-control wpcf7-submit has-spinner\" type=\"submit\" value=\"ENVOYER\" \/>\n\t\t\t<\/p>\n\t\t<\/li>\n\t<\/ul>\n<\/div><div class=\"wpcf7-response-output\" aria-hidden=\"true\"><\/div>\n<input type=\"hidden\" name=\"trp-form-language\" value=\"fr\"\/><\/form>\n<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>Harness the Power of Longevity with Gensei&#8217;s Trans-Resveratrol Powder In the global market for natural antioxidants, Gensei has established itself [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"parent":4827,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_uag_custom_page_level_css":"","site-sidebar-layout":"no-sidebar","site-content-layout":"","ast-site-content-layout":"full-width-container","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"disabled","ast-breadcrumbs-content":"","ast-featured-img":"disabled","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"class_list":["post-14822","page","type-page","status-publish","hentry"],"uagb_featured_image_src":{"full":false,"thumbnail":false,"medium":false,"medium_large":false,"large":false,"1536x1536":false,"2048x2048":false,"trp-custom-language-flag":false},"uagb_author_info":{"display_name":"jiang, xu","author_link":"https:\/\/collagensei.com\/fr\/author\/j-xu\/"},"uagb_comment_info":0,"uagb_excerpt":"Harness the Power of Longevity with Gensei&#8217;s Trans-Resveratrol Powder In the global market for natural antioxidants, Gensei has established itself [&hellip;]","_links":{"self":[{"href":"https:\/\/collagensei.com\/fr\/wp-json\/wp\/v2\/pages\/14822","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/collagensei.com\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/collagensei.com\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/collagensei.com\/fr\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/collagensei.com\/fr\/wp-json\/wp\/v2\/comments?post=14822"}],"version-history":[{"count":9,"href":"https:\/\/collagensei.com\/fr\/wp-json\/wp\/v2\/pages\/14822\/revisions"}],"predecessor-version":[{"id":15616,"href":"https:\/\/collagensei.com\/fr\/wp-json\/wp\/v2\/pages\/14822\/revisions\/15616"}],"up":[{"embeddable":true,"href":"https:\/\/collagensei.com\/fr\/wp-json\/wp\/v2\/pages\/4827"}],"wp:attachment":[{"href":"https:\/\/collagensei.com\/fr\/wp-json\/wp\/v2\/media?parent=14822"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}