{"id":4785,"date":"2025-03-21T14:09:32","date_gmt":"2025-03-21T06:09:32","guid":{"rendered":"https:\/\/collagensei.com\/?page_id=4785"},"modified":"2025-10-30T16:26:23","modified_gmt":"2025-10-30T08:26:23","slug":"esportatore-di-cheratina-idrolizzata-sfusa","status":"publish","type":"page","link":"https:\/\/collagensei.com\/it\/sports-nutrition-manufacturer\/bulk-hydrolyzed-keratin-exporter\/","title":{"rendered":"Cheratina idrolizzata"},"content":{"rendered":"<div data-elementor-type=\"wp-post\" data-elementor-id=\"4785\" class=\"elementor elementor-4785\" data-elementor-post-type=\"page\">\n\t\t\t\t<div class=\"elementor-element elementor-element-1908d3a e-flex e-con-boxed e-con e-parent\" data-id=\"1908d3a\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-5696f44c e-con-full e-flex e-con e-child\" data-id=\"5696f44c\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-6fcda9dc e-con-full e-flex e-con e-child\" data-id=\"6fcda9dc\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-260e6a0e elementor-widget__width-initial elementor-widget elementor-widget-image\" data-id=\"260e6a0e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"743\" height=\"492\" src=\"https:\/\/collagensei.com\/wp-content\/uploads\/2024\/12\/Hydrolyzed-Keratin-and-Silkworm-Pupa-Protein-Peptide.png\" class=\"attachment-large size-large wp-image-4287\" alt=\"Cheratina idrolizzata\" srcset=\"https:\/\/collagensei.com\/wp-content\/uploads\/2024\/12\/Hydrolyzed-Keratin-and-Silkworm-Pupa-Protein-Peptide.png 743w, https:\/\/collagensei.com\/wp-content\/uploads\/2024\/12\/Hydrolyzed-Keratin-and-Silkworm-Pupa-Protein-Peptide-300x199.png 300w\" sizes=\"(max-width: 743px) 100vw, 743px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-56837208 e-con-full e-flex e-con e-child\" data-id=\"56837208\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-3d86cd9f elementor-widget elementor-widget-heading\" data-id=\"3d86cd9f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">esportatore di cheratina idrolizzata sfusa<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-64c273d7 elementor-widget elementor-widget-text-editor\" data-id=\"64c273d7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Cercate un esportatore di cheratina idrolizzata all'ingrosso per migliorare le vostre linee di prodotti per la cura dei capelli e della pelle? Gensei offre cheratina idrolizzata di prima qualit\u00e0. Sottoposta a idrolisi, la grande proteina della cheratina viene spezzata in frammenti pi\u00f9 piccoli che possono essere assorbiti pi\u00f9 facilmente. La cheratina idrolizzata \u00e8 ampiamente utilizzata per le sue propriet\u00e0 condizionanti, leviganti e protettive. Aiuta a migliorare l'elasticit\u00e0 e la lucentezza dei capelli e fornisce effetti idratanti alla pelle. Collaborate con Gensei per ottenere cheratina idrolizzata di alta qualit\u00e0 e migliorare le prestazioni delle vostre formulazioni cosmetiche.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-5711d8b0 e-con-full e-flex e-con e-child\" data-id=\"5711d8b0\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-567783f1 elementor-widget elementor-widget-text-editor\" data-id=\"567783f1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><i><b>Si prega di notare:<\/b>\u00a0Siamo un fornitore all'ingrosso e abbiamo quantit\u00e0 minime d'ordine.<\/i><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-403cba0e elementor-align-left elementor-widget elementor-widget-button\" data-id=\"403cba0e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"#elementor-action%3Aaction%3Dpopup%3Aopen%26settings%3DeyJpZCI6IjQ5OTIiLCJ0b2dnbGUiOmZhbHNlfQ%3D%3D\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Richiesta di preventivo<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-57fc1874 elementor-widget elementor-widget-text-editor\" data-id=\"57fc1874\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Avete domande su questo prodotto? Il nostro team \u00e8 qui per aiutarvi. Per richieste relative a pi\u00f9 ingredienti, utilizzare l'opzione\u00a0<a href=\"https:\/\/collagensei.com\/it\/contattateci\/\">Contatto<\/a>\u00a0e includere l'elenco degli ingredienti nel messaggio.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-466a457d e-con-full e-flex e-con e-child\" data-id=\"466a457d\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-6530e01c e-con-full e-flex e-con e-child\" data-id=\"6530e01c\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-33961a43 elementor-widget elementor-widget-text-editor\" data-id=\"33961a43\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p data-sourcepos=\"147:1-147:95\"><strong>Cheratina idrolizzata N. CAS:<\/strong> 69430-36-0 (\u00e8 un numero CAS comune per la cheratina idrolizzata)<\/p><p data-sourcepos=\"149:1-149:41\"><strong>Nome chimico:<\/strong> Cheratine, idrolizzati<\/p><p data-sourcepos=\"151:1-151:13\"><strong>Sinonimi:<\/strong><\/p><ul data-sourcepos=\"152:1-154:0\"><li data-sourcepos=\"152:1-152:21\"><a class=\"wpil_keyword_link\" href=\"https:\/\/collagensei.com\/it\/cose-la-cheratina-idrolizzata\/\"   title=\"Che cos&#039;\u00e8 la cheratina idrolizzata\" data-wpil-keyword-link=\"linked\"  data-wpil-monitor-id=\"368\">Idrolizzato di cheratina<\/a><\/li><li data-sourcepos=\"153:1-154:0\">Proteine animali idrolizzate (se la fonte \u00e8 specificata come animale)<\/li><\/ul><p data-sourcepos=\"155:1-155:24\"><strong>Numero CB:<\/strong> CB4852570<\/p><p data-sourcepos=\"157:1-157:134\"><strong>Formula molecolare:<\/strong> Non applicabile. La cheratina idrolizzata \u00e8 una miscela complessa di peptidi e aminoacidi con catene di lunghezza variabile.<\/p><p data-sourcepos=\"159:1-159:197\"><strong>Peso molecolare:<\/strong> Non applicabile. Il peso molecolare \u00e8 descritto come un intervallo di distribuzione, tipicamente compreso tra poche centinaia e diverse migliaia di Dalton, a seconda del grado di idrolisi.<\/p><p data-sourcepos=\"161:1-161:62\"><strong>Numero MDL:<\/strong> Non prontamente disponibile per la miscela complessa.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-3f0d50f3 e-con-full e-flex e-con e-child\" data-id=\"3f0d50f3\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-3095a293 elementor-widget elementor-widget-image\" data-id=\"3095a293\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"500\" height=\"500\" src=\"https:\/\/collagensei.com\/wp-content\/uploads\/2025\/04\/Keratins-structure.png\" class=\"attachment-large size-large wp-image-6379\" alt=\"\" srcset=\"https:\/\/collagensei.com\/wp-content\/uploads\/2025\/04\/Keratins-structure.png 500w, https:\/\/collagensei.com\/wp-content\/uploads\/2025\/04\/Keratins-structure-300x300.png 300w, https:\/\/collagensei.com\/wp-content\/uploads\/2025\/04\/Keratins-structure-150x150.png 150w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-dddbc52 elementor-widget elementor-widget-text-editor\" data-id=\"dddbc52\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: center;\"><em><strong>Struttura delle cheratine.<\/strong><\/em><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-470678fa e-flex e-con-boxed e-con e-parent\" data-id=\"470678fa\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-7944a0f7 elementor-widget__width-inherit elementor-widget elementor-widget-html\" data-id=\"7944a0f7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<!DOCTYPE html>\r\n  <title>Processo di produzione della cheratina idrolizzata<\/title>\r\n  <style>\r\n    body {\r\n      font-family: 'Segoe UI', Tahoma, Geneva, Verdana, sans-serif;\r\n      margin: 0;\r\n      padding: 20px;\r\n      line-height: 1.6;\r\n      color: #333;\r\n      background-color: #f8f9fa;\r\n    }\r\n    .container {\r\n      max-width: 1200px;\r\n      margin: 0 auto;\r\n      background: white;\r\n      padding: 30px;\r\n      border-radius: 12px;\r\n      box-shadow: 0 4px 12px rgba(0, 0, 0, 0.1);\r\n    }\r\n    .flowchart-section {\r\n      margin-bottom: 40px;\r\n    }\r\n    .flowchart-title {\r\n      font-size: 1.8em;\r\n      margin-bottom: 20px;\r\n      color: #2c3e50;\r\n      text-align: center;\r\n      font-weight: 600;\r\n    }\r\n    .intro-paragraph {\r\n      margin-bottom: 25px;\r\n      font-size: 1.1em;\r\n      text-align: center;\r\n      color: #555;\r\n    }\r\n    .flowchart {\r\n      display: flex;\r\n      flex-wrap: wrap;\r\n      justify-content: center;\r\n      align-items: flex-start;\r\n      gap: 15px;\r\n      list-style: none;\r\n      padding: 0;\r\n    }\r\n    .flowchart li {\r\n      display: flex;\r\n      flex-direction: column;\r\n      align-items: center;\r\n      min-width: 280px;\r\n      flex: 1;\r\n    }\r\n    .node {\r\n      border: 2px solid #ddd;\r\n      padding: 20px;\r\n      text-align: center;\r\n      border-radius: 12px;\r\n      background: linear-gradient(135deg, #ffffff 0%, #f8f9fa 100%);\r\n      box-shadow: 0 4px 8px rgba(0, 0, 0, 0.1);\r\n      flex: 1;\r\n      max-width: 320px;\r\n      white-space: normal;\r\n      transition: transform 0.2s ease, box-shadow 0.2s ease;\r\n      position: relative;\r\n    }\r\n    .node:hover {\r\n      transform: translateY(-5px);\r\n      box-shadow: 0 8px 16px rgba(0, 0, 0, 0.15);\r\n    }\r\n    .input-node {\r\n      background: linear-gradient(135deg, #e3f2fd 0%, #bbdefb 100%);\r\n      border-color: #2196f3;\r\n    }\r\n    .process-node {\r\n      background: linear-gradient(135deg, #fffde7 0%, #fff9c4 100%);\r\n      border-color: #ff9800;\r\n    }\r\n    .output-node {\r\n      background: linear-gradient(135deg, #e1f5fe 0%, #b3e5fc 100%);\r\n      border-color: #03a9f4;\r\n    }\r\n    .node strong {\r\n      display: block;\r\n      font-size: 1.1em;\r\n      margin-bottom: 8px;\r\n      color: #2c3e50;\r\n    }\r\n    .node br {\r\n      margin-bottom: 4px;\r\n    }\r\n    .arrow {\r\n      font-size: 28px;\r\n      color: #666;\r\n      margin: 15px 0;\r\n      align-self: center;\r\n      font-weight: bold;\r\n      transition: color 0.2s ease;\r\n    }\r\n    .arrow:hover {\r\n      color: #2196f3;\r\n    }\r\n    @media (max-width: 768px) {\r\n      .flowchart {\r\n        flex-direction: column;\r\n        align-items: center;\r\n        gap: 20px;\r\n      }\r\n      .node {\r\n        max-width: 100%;\r\n        min-width: 250px;\r\n      }\r\n      .container {\r\n        padding: 20px;\r\n      }\r\n    }\r\n    .sr-only {\r\n      position: absolute;\r\n      width: 1px;\r\n      height: 1px;\r\n      padding: 0;\r\n      margin: -1px;\r\n      overflow: hidden;\r\n      clip: rect(0, 0, 0, 0);\r\n      white-space: nowrap;\r\n      border: 0;\r\n    }\r\n  <\/style>\r\n<\/head>\r\n<body>\r\n  <div class=\"container\">\r\n    <h2 class=\"flowchart-title\">Processo di produzione della cheratina idrolizzata<\/h2>\r\n    <p class=\"intro-paragraph\">La cheratina idrolizzata viene prodotta mediante la scomposizione <a class=\"wpil_keyword_link\" href=\"https:\/\/collagensei.com\/it\/proteina-di-cheratina-in-polvere\/\" target=\"_blank\"  rel=\"noopener\" title=\"Proteine della cheratina in polvere\" data-wpil-keyword-link=\"linked\"  data-wpil-monitor-id=\"1592\">proteina cheratina<\/a> da fonti animali in peptidi pi\u00f9 piccoli e aminoacidi.<\/p>\r\n    \r\n    <section class=\"flowchart-section\" aria-labelledby=\"flowchart-title\">\r\n      <h3 id=\"flowchart-title\" class=\"sr-only\">Diagramma di flusso della produzione<\/h3>\r\n      <ul class=\"flowchart\" role=\"list\">\r\n        <li>\r\n          <div class=\"node input-node\" role=\"img\" aria-label=\"Materia prima: Fonte di cheratina\">\r\n            <strong>Materia prima: Fonte di cheratina<\/strong><br>\r\n            (ad es. lana, piume, peli, zoccoli)\r\n          <\/div>\r\n        <\/li>\r\n        <li>\r\n          <span class=\"arrow\" aria-hidden=\"true\">\u2192<\/span>\r\n          <div class=\"node process-node\" role=\"img\" aria-label=\"Pulizia e preparazione\">\r\n            <strong>Pulizia e preparazione<\/strong><br>\r\n            (Rimozione delle impurit\u00e0 e lavorazione della materia prima)\r\n          <\/div>\r\n        <\/li>\r\n        <li>\r\n          <span class=\"arrow\" aria-hidden=\"true\">\u2192<\/span>\r\n          <div class=\"node process-node\" role=\"img\" aria-label=\"Idrolisi\">\r\n            <strong>Idrolisi<\/strong><br>\r\n            (Scomposizione delle catene proteiche della cheratina con metodi acidi, alcalini o enzimatici in condizioni controllate)\r\n          <\/div>\r\n        <\/li>\r\n        <li>\r\n          <span class=\"arrow\" aria-hidden=\"true\">\u2192<\/span>\r\n          <div class=\"node process-node\" role=\"img\" aria-label=\"Neutralizzazione (se si utilizzano acidi\/alcali)\">\r\n            <strong>Neutralizzazione (se si utilizzano acidi\/alcali)<\/strong><br>\r\n            (Regolazione del pH della soluzione)\r\n          <\/div>\r\n        <\/li>\r\n        <li>\r\n          <span class=\"arrow\" aria-hidden=\"true\">\u2192<\/span>\r\n          <div class=\"node process-node\" role=\"img\" aria-label=\"Filtrazione\">\r\n            <strong>Filtrazione<\/strong><br>\r\n            (rimozione di eventuali materiali insolubili)\r\n          <\/div>\r\n        <\/li>\r\n        <li>\r\n          <span class=\"arrow\" aria-hidden=\"true\">\u2192<\/span>\r\n          <div class=\"node process-node\" role=\"img\" aria-label=\"Purificazione (opzionale)\">\r\n            <strong>Purificazione (opzionale)<\/strong><br>\r\n            (Ulteriore raffinazione dell'idrolizzato)\r\n          <\/div>\r\n        <\/li>\r\n        <li>\r\n          <span class=\"arrow\" aria-hidden=\"true\">\u2192<\/span>\r\n          <div class=\"node process-node\" role=\"img\" aria-label=\"Concentrazione\">\r\n            <strong>Concentrazione<\/strong><br>\r\n            (Eliminazione dell'acqua in eccesso per concentrare la soluzione di cheratina idrolizzata)\r\n          <\/div>\r\n        <\/li>\r\n        <li>\r\n          <span class=\"arrow\" aria-hidden=\"true\">\u2192<\/span>\r\n          <div class=\"node process-node\" role=\"img\" aria-label=\"Essiccazione (per la polvere)\">\r\n            <strong>Essiccazione (per la polvere)<\/strong><br>\r\n            (Essiccazione della soluzione concentrata in polvere, spesso utilizzando l'essiccazione a spruzzo)\r\n          <\/div>\r\n        <\/li>\r\n        <li>\r\n          <span class=\"arrow\" aria-hidden=\"true\">\u2192<\/span>\r\n          <div class=\"node process-node\" role=\"img\" aria-label=\"Controllo qualit\u00e0\">\r\n            <strong>Controllo qualit\u00e0<\/strong><br>\r\n            (Analisi della distribuzione del peso molecolare, della composizione aminoacidica, della purezza e di altre specifiche)\r\n          <\/div>\r\n        <\/li>\r\n        <li>\r\n          <span class=\"arrow\" aria-hidden=\"true\">\u2192<\/span>\r\n          <div class=\"node output-node\" role=\"img\" aria-label=\"Imballaggio\">\r\n            <strong>Imballaggio<\/strong><br>\r\n            (La polvere o il liquido di cheratina idrolizzata sono confezionati)\r\n          <\/div>\r\n        <\/li>\r\n      <\/ul>\r\n    <\/section>\r\n  <\/div>\r\n<\/body>\r\n<\/html>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-28eb3015 e-flex e-con-boxed e-con e-parent\" data-id=\"28eb3015\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-57e3e440 elementor-widget elementor-widget-heading\" data-id=\"57e3e440\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Perch\u00e9 scegliere Gensei come fornitore di cheratina idrolizzata?<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3fbc7c04 elementor-widget elementor-widget-text-editor\" data-id=\"3fbc7c04\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p data-sourcepos=\"167:1-167:269\">Scegliere Gensei come fornitore di cheratina idrolizzata garantisce un ingrediente di alta qualit\u00e0 per i vostri prodotti cosmetici e per la cura della persona. Siamo specializzati nella produzione di cheratina idrolizzata di alta qualit\u00e0, nota per la sua efficacia nel riparare e condizionare i capelli e la pelle.<\/p><p data-sourcepos=\"169:1-169:349\">Il nostro processo di produzione garantisce una purezza eccezionale e una distribuzione coerente del peso molecolare, fondamentale per ottenere prestazioni ottimali. In qualit\u00e0 di fornitore affidabile di cheratina idrolizzata, offriamo forniture affidabili e prezzi competitivi. Collaborate con Gensei per le vostre esigenze di cheratina idrolizzata e migliorate la qualit\u00e0 e l'efficacia delle vostre formulazioni.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6cbbdc27 elementor-widget elementor-widget-text-editor\" data-id=\"6cbbdc27\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><b>Caratteristiche e vantaggi<\/b><\/p><ul><li data-sourcepos=\"175:1-175:69\"><strong>Composizione:<\/strong> Consiste in una miscela di peptidi e aminoacidi.<\/li><li data-sourcepos=\"176:1-176:99\"><strong>Solubilit\u00e0:<\/strong> Altamente solubile in acqua, \u00e8 facile da incorporare in formulazioni acquose.<\/li><li data-sourcepos=\"177:1-177:79\"><strong>Formazione di film:<\/strong> Pu\u00f2 formare una pellicola protettiva sulla superficie dei capelli e della pelle.<\/li><li data-sourcepos=\"178:1-178:54\"><strong>Idratante:<\/strong> Aiuta ad attirare e trattenere l'umidit\u00e0.<\/li><li data-sourcepos=\"179:1-180:0\"><strong>Capacit\u00e0 di penetrazione:<\/strong> I peptidi di dimensioni pi\u00f9 piccole possono penetrare in qualche misura la cuticola del capello e la superficie della pelle.<\/li><\/ul><p><strong>Applicazioni<\/strong><\/p><ul><li data-sourcepos=\"185:1-185:175\"><strong>Cura dei capelli:<\/strong> Utilizzato in shampoo, balsami, maschere, prodotti per lo styling e trattamenti per rafforzare i capelli, ridurre la rottura, migliorare l'elasticit\u00e0, aggiungere lucentezza e riparare i danni.<\/li><li data-sourcepos=\"186:1-186:123\"><strong>Cura della pelle:<\/strong> Incluso in lozioni, creme, sieri e maschere per le sue propriet\u00e0 idratanti, leviganti e protettive.<\/li><li data-sourcepos=\"187:1-188:0\"><strong>Cura delle unghie:<\/strong> Si trova nei trattamenti per le unghie per contribuire al loro rafforzamento e condizionamento.<\/li><\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-4ababeb2 e-flex e-con-boxed e-con e-parent\" data-id=\"4ababeb2\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-7ea553f e-con-full e-flex e-con e-child\" data-id=\"7ea553f\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-5ab86f54 elementor-widget elementor-widget-heading\" data-id=\"5ab86f54\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">I nostri impianti di produzione all'avanguardia<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5010c282 elementor-widget elementor-widget-text-editor\" data-id=\"5010c282\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Esplorate le nostre moderne strutture dotate di tecnologie avanzate per garantire la massima qualit\u00e0 nella produzione di vitamine, estratti di erbe, minerali e aminoacidi.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-cfe6a7b e-con-full e-flex e-con e-child\" data-id=\"cfe6a7b\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-1321e48a elementor-arrows-position-inside elementor-pagination-position-outside elementor-widget elementor-widget-image-carousel\" data-id=\"1321e48a\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;slides_to_show&quot;:&quot;3&quot;,&quot;slides_to_scroll&quot;:&quot;1&quot;,&quot;lazyload&quot;:&quot;yes&quot;,&quot;image_spacing_custom&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:5,&quot;sizes&quot;:[]},&quot;navigation&quot;:&quot;both&quot;,&quot;autoplay&quot;:&quot;yes&quot;,&quot;pause_on_hover&quot;:&quot;yes&quot;,&quot;pause_on_interaction&quot;:&quot;yes&quot;,&quot;autoplay_speed&quot;:5000,&quot;infinite&quot;:&quot;yes&quot;,&quot;speed&quot;:500,&quot;image_spacing_custom_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;image_spacing_custom_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]}}\" data-widget_type=\"image-carousel.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-image-carousel-wrapper swiper\" role=\"region\" aria-roledescription=\"carousel\" aria-label=\"Carosello di immagini\" dir=\"rtl\">\n\t\t\t<div class=\"elementor-image-carousel swiper-wrapper swiper-image-stretch\" aria-live=\"off\">\n\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"1 sur 11\" data-no-translation-aria-label=\"\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image swiper-lazy\" data-src=\"https:\/\/collagensei.com\/wp-content\/uploads\/2025\/04\/Machining-machine-12-768x576.webp\" alt=\"Macchina per la lavorazione (12)\" \/><div class=\"swiper-lazy-preloader\"><\/div><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"2 sur 11\" data-no-translation-aria-label=\"\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image swiper-lazy\" data-src=\"https:\/\/collagensei.com\/wp-content\/uploads\/2025\/04\/Machining-machine-11-768x576.webp\" alt=\"Macchina per la lavorazione (11)\" \/><div class=\"swiper-lazy-preloader\"><\/div><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"3 sur 11\" data-no-translation-aria-label=\"\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image swiper-lazy\" data-src=\"https:\/\/collagensei.com\/wp-content\/uploads\/2025\/04\/Machining-machine-10-768x576.webp\" alt=\"Macchina per la lavorazione (10)\" \/><div class=\"swiper-lazy-preloader\"><\/div><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"4 sur 11\" data-no-translation-aria-label=\"\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image swiper-lazy\" data-src=\"https:\/\/collagensei.com\/wp-content\/uploads\/2025\/04\/Machining-machine-9-768x576.webp\" alt=\"Macchina per la lavorazione (9)\" \/><div class=\"swiper-lazy-preloader\"><\/div><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"5 sur 11\" data-no-translation-aria-label=\"\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image swiper-lazy\" data-src=\"https:\/\/collagensei.com\/wp-content\/uploads\/2025\/04\/Machining-machine-8-768x576.webp\" alt=\"Macchina per la lavorazione (8)\" \/><div class=\"swiper-lazy-preloader\"><\/div><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"6 sur 11\" data-no-translation-aria-label=\"\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image swiper-lazy\" data-src=\"https:\/\/collagensei.com\/wp-content\/uploads\/2025\/04\/Machining-machine-7-768x576.webp\" alt=\"Macchina per la lavorazione (7)\" \/><div class=\"swiper-lazy-preloader\"><\/div><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"7 sur 11\" data-no-translation-aria-label=\"\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image swiper-lazy\" data-src=\"https:\/\/collagensei.com\/wp-content\/uploads\/2025\/04\/Machining-machine-6-768x576.webp\" alt=\"Macchina per la lavorazione (6)\" \/><div class=\"swiper-lazy-preloader\"><\/div><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"8 sur 11\" data-no-translation-aria-label=\"\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image swiper-lazy\" data-src=\"https:\/\/collagensei.com\/wp-content\/uploads\/2025\/04\/Machining-machine-5-768x576.webp\" alt=\"Macchina per la lavorazione (5)\" \/><div class=\"swiper-lazy-preloader\"><\/div><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"9 sur 11\" data-no-translation-aria-label=\"\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image swiper-lazy\" data-src=\"https:\/\/collagensei.com\/wp-content\/uploads\/2025\/04\/Machining-machine-4-768x575.webp\" alt=\"Macchina per la lavorazione (4)\" \/><div class=\"swiper-lazy-preloader\"><\/div><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"10 sur 11\" data-no-translation-aria-label=\"\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image swiper-lazy\" data-src=\"https:\/\/collagensei.com\/wp-content\/uploads\/2025\/04\/Machining-machine-2-768x576.webp\" alt=\"Macchina per la lavorazione (2)\" \/><div class=\"swiper-lazy-preloader\"><\/div><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"11 sur 11\" data-no-translation-aria-label=\"\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image swiper-lazy\" data-src=\"https:\/\/collagensei.com\/wp-content\/uploads\/2025\/04\/Machining-machine-1-768x576.webp\" alt=\"Macchina per la lavorazione (1)\" \/><div class=\"swiper-lazy-preloader\"><\/div><\/figure><\/div>\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-prev\" role=\"button\" tabindex=\"0\">\n\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-eicon-chevron-left\" viewbox=\"0 0 1000 1000\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M646 125C629 125 613 133 604 142L308 442C296 454 292 471 292 487 292 504 296 521 308 533L604 854C617 867 629 875 646 875 663 875 679 871 692 858 704 846 713 829 713 812 713 796 708 779 692 767L438 487 692 225C700 217 708 204 708 187 708 171 704 154 692 142 675 129 663 125 646 125Z\"><\/path><\/svg>\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-next\" role=\"button\" tabindex=\"0\">\n\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-eicon-chevron-right\" viewbox=\"0 0 1000 1000\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M696 533C708 521 713 504 713 487 713 471 708 454 696 446L400 146C388 133 375 125 354 125 338 125 325 129 313 142 300 154 292 171 292 187 292 204 296 221 308 233L563 492 304 771C292 783 288 800 288 817 288 833 296 850 308 863 321 871 338 875 354 875 371 875 388 867 400 854L696 533Z\"><\/path><\/svg>\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"swiper-pagination\"><\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-4353fba1 e-flex e-con-boxed e-con e-parent\" data-id=\"4353fba1\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-62f825fb elementor-widget elementor-widget-heading\" data-id=\"62f825fb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Domande frequenti<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2cb40fff uael-faq-box-layout-yes align-at-left elementor-widget elementor-widget-uael-faq\" data-id=\"2cb40fff\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"uael-faq.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n\t\t\t<div id='uael-faq-wrapper-749' class=\"uael-faq-wrapper\">\n\t\t\t\t<div class=\"uael-faq-container uael-faq-layout-accordion\" data-layout=\"accordion\" >\n\t\t\t\t\t\t\t\t\t\t\t\t<div id=\"uael-accordion-7f96b0b\" class=\"uael-faq-accordion\" role=\"tablist\">\n\t\t\t\t\t\t\t\t<div class= \"uael-accordion-title\" aria-expanded=\"false\" role=\"tab\">\n\t\t\t\t\t\t\t\t\t<span class=\"uael-accordion-icon uael-accordion-icon-left\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"uael-accordion-icon-closed\"><svg class=\"e-font-icon-svg e-fas-angle-right\" viewbox=\"0 0 256 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M224.3 273l-136 136c-9.4 9.4-24.6 9.4-33.9 0l-22.6-22.6c-9.4-9.4-9.4-24.6 0-33.9l96.4-96.4-96.4-96.4c-9.4-9.4-9.4-24.6 0-33.9L54.3 103c9.4-9.4 24.6-9.4 33.9 0l136 136c9.5 9.4 9.5 24.6.1 34z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"uael-accordion-icon-opened\"><svg class=\"e-font-icon-svg e-fas-angle-up\" viewbox=\"0 0 320 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M177 159.7l136 136c9.4 9.4 9.4 24.6 0 33.9l-22.6 22.6c-9.4 9.4-24.6 9.4-33.9 0L160 255.9l-96.4 96.4c-9.4 9.4-24.6 9.4-33.9 0L7 329.7c-9.4-9.4-9.4-24.6 0-33.9l136-136c9.4-9.5 24.6-9.5 34-.1z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"uael-question-7f96b0b uael-question-span\" tabindex=\"0\" id=\"uael-faq-1-6a03e4ed90e2a\">Che cos'\u00e8 la cheratina idrolizzata?<\/span>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"uael-accordion-content\" role=\"tabpanel\">\n\t\t\t\t\t\t\t\t\t<span>\n\t\t\t\t\t\t\t\t\t<span><p>La cheratina idrolizzata \u00e8 una forma di proteina derivata dalla cheratina (presente nei capelli, nella pelle e nelle unghie) che \u00e8 stata scomposta in pezzi pi\u00f9 piccoli (peptidi e aminoacidi) attraverso un processo chiamato idrolisi. Questo processo rende la cheratina solubile in acqua e le permette di essere assorbita pi\u00f9 facilmente dai capelli e dalla pelle.<\/p><\/span>\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div id=\"uael-accordion-a8d3cbe\" class=\"uael-faq-accordion\" role=\"tablist\">\n\t\t\t\t\t\t\t\t<div class= \"uael-accordion-title\" aria-expanded=\"false\" role=\"tab\">\n\t\t\t\t\t\t\t\t\t<span class=\"uael-accordion-icon uael-accordion-icon-left\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"uael-accordion-icon-closed\"><svg class=\"e-font-icon-svg e-fas-angle-right\" viewbox=\"0 0 256 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M224.3 273l-136 136c-9.4 9.4-24.6 9.4-33.9 0l-22.6-22.6c-9.4-9.4-9.4-24.6 0-33.9l96.4-96.4-96.4-96.4c-9.4-9.4-9.4-24.6 0-33.9L54.3 103c9.4-9.4 24.6-9.4 33.9 0l136 136c9.5 9.4 9.5 24.6.1 34z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"uael-accordion-icon-opened\"><svg class=\"e-font-icon-svg e-fas-angle-up\" viewbox=\"0 0 320 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M177 159.7l136 136c9.4 9.4 9.4 24.6 0 33.9l-22.6 22.6c-9.4 9.4-24.6 9.4-33.9 0L160 255.9l-96.4 96.4c-9.4 9.4-24.6 9.4-33.9 0L7 329.7c-9.4-9.4-9.4-24.6 0-33.9l136-136c9.4-9.5 24.6-9.5 34-.1z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"uael-question-a8d3cbe uael-question-span\" tabindex=\"0\" id=\"uael-faq-2-6a03e4ed90e96\">Quali sono i benefici della cheratina idrolizzata per i capelli?<\/span>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"uael-accordion-content\" role=\"tabpanel\">\n\t\t\t\t\t\t\t\t\t<span>\n\t\t\t\t\t\t\t\t\t<span><p>La cheratina idrolizzata apporta benefici ai capelli rafforzandone il fusto, riducendone la rottura, migliorandone l'elasticit\u00e0, aumentandone la lucentezza, levigando la cuticola e aiutando a riparare i danni causati da styling a caldo, trattamenti chimici o fattori ambientali. Ha anche propriet\u00e0 idratanti.<\/p><\/span>\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div id=\"uael-accordion-c71531d\" class=\"uael-faq-accordion\" role=\"tablist\">\n\t\t\t\t\t\t\t\t<div class= \"uael-accordion-title\" aria-expanded=\"false\" role=\"tab\">\n\t\t\t\t\t\t\t\t\t<span class=\"uael-accordion-icon uael-accordion-icon-left\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"uael-accordion-icon-closed\"><svg class=\"e-font-icon-svg e-fas-angle-right\" viewbox=\"0 0 256 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M224.3 273l-136 136c-9.4 9.4-24.6 9.4-33.9 0l-22.6-22.6c-9.4-9.4-9.4-24.6 0-33.9l96.4-96.4-96.4-96.4c-9.4-9.4-9.4-24.6 0-33.9L54.3 103c9.4-9.4 24.6-9.4 33.9 0l136 136c9.5 9.4 9.5 24.6.1 34z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"uael-accordion-icon-opened\"><svg class=\"e-font-icon-svg e-fas-angle-up\" viewbox=\"0 0 320 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M177 159.7l136 136c9.4 9.4 9.4 24.6 0 33.9l-22.6 22.6c-9.4 9.4-24.6 9.4-33.9 0L160 255.9l-96.4 96.4c-9.4 9.4-24.6 9.4-33.9 0L7 329.7c-9.4-9.4-9.4-24.6 0-33.9l136-136c9.4-9.5 24.6-9.5 34-.1z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"uael-question-c71531d uael-question-span\" tabindex=\"0\" id=\"uael-faq-3-6a03e4ed90ed3\">Quali sono i benefici della cheratina idrolizzata per la pelle?<\/span>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"uael-accordion-content\" role=\"tabpanel\">\n\t\t\t\t\t\t\t\t\t<span>\n\t\t\t\t\t\t\t\t\t<span><p>La cheratina idrolizzata pu\u00f2 apportare benefici alla pelle fornendo idratazione, migliorando l'idratazione, formando un film protettivo e contribuendo potenzialmente a rendere la pelle pi\u00f9 liscia ed elastica.<\/p><\/span>\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div id=\"uael-accordion-b567dbb\" class=\"uael-faq-accordion\" role=\"tablist\">\n\t\t\t\t\t\t\t\t<div class= \"uael-accordion-title\" aria-expanded=\"false\" role=\"tab\">\n\t\t\t\t\t\t\t\t\t<span class=\"uael-accordion-icon uael-accordion-icon-left\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"uael-accordion-icon-closed\"><svg class=\"e-font-icon-svg e-fas-angle-right\" viewbox=\"0 0 256 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M224.3 273l-136 136c-9.4 9.4-24.6 9.4-33.9 0l-22.6-22.6c-9.4-9.4-9.4-24.6 0-33.9l96.4-96.4-96.4-96.4c-9.4-9.4-9.4-24.6 0-33.9L54.3 103c9.4-9.4 24.6-9.4 33.9 0l136 136c9.5 9.4 9.5 24.6.1 34z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"uael-accordion-icon-opened\"><svg class=\"e-font-icon-svg e-fas-angle-up\" viewbox=\"0 0 320 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M177 159.7l136 136c9.4 9.4 9.4 24.6 0 33.9l-22.6 22.6c-9.4 9.4-24.6 9.4-33.9 0L160 255.9l-96.4 96.4c-9.4 9.4-24.6 9.4-33.9 0L7 329.7c-9.4-9.4-9.4-24.6 0-33.9l136-136c9.4-9.5 24.6-9.5 34-.1z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"uael-question-b567dbb uael-question-span\" tabindex=\"0\" id=\"uael-faq-4-6a03e4ed90f08\">La cheratina idrolizzata \u00e8 la stessa cosa della cheratina?<\/span>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"uael-accordion-content\" role=\"tabpanel\">\n\t\t\t\t\t\t\t\t\t<span>\n\t\t\t\t\t\t\t\t\t<span><p>No, la cheratina idrolizzata non \u00e8 uguale alla cheratina intatta. La cheratina \u00e8 una grande proteina fibrosa insolubile in acqua. La cheratina idrolizzata \u00e8 il risultato della scomposizione di questa grande proteina in frammenti pi\u00f9 piccoli e solubili in acqua (peptidi e aminoacidi), che la rendono adatta all'uso in formulazioni cosmetiche dove pu\u00f2 essere assorbita pi\u00f9 facilmente o legarsi alle superfici dei capelli e della pelle.<\/p><\/span>\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div id=\"uael-accordion-94fa3bc\" class=\"uael-faq-accordion\" role=\"tablist\">\n\t\t\t\t\t\t\t\t<div class= \"uael-accordion-title\" aria-expanded=\"false\" role=\"tab\">\n\t\t\t\t\t\t\t\t\t<span class=\"uael-accordion-icon uael-accordion-icon-left\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"uael-accordion-icon-closed\"><svg class=\"e-font-icon-svg e-fas-angle-right\" viewbox=\"0 0 256 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M224.3 273l-136 136c-9.4 9.4-24.6 9.4-33.9 0l-22.6-22.6c-9.4-9.4-9.4-24.6 0-33.9l96.4-96.4-96.4-96.4c-9.4-9.4-9.4-24.6 0-33.9L54.3 103c9.4-9.4 24.6-9.4 33.9 0l136 136c9.5 9.4 9.5 24.6.1 34z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"uael-accordion-icon-opened\"><svg class=\"e-font-icon-svg e-fas-angle-up\" viewbox=\"0 0 320 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M177 159.7l136 136c9.4 9.4 9.4 24.6 0 33.9l-22.6 22.6c-9.4 9.4-24.6 9.4-33.9 0L160 255.9l-96.4 96.4c-9.4 9.4-24.6 9.4-33.9 0L7 329.7c-9.4-9.4-9.4-24.6 0-33.9l136-136c9.4-9.5 24.6-9.5 34-.1z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"uael-question-94fa3bc uael-question-span\" tabindex=\"0\" id=\"uael-faq-5-6a03e4ed90f3f\">Da dove proviene la cheratina idrolizzata?<\/span>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"uael-accordion-content\" role=\"tabpanel\">\n\t\t\t\t\t\t\t\t\t<span>\n\t\t\t\t\t\t\t\t\t<span><p>La cheratina idrolizzata proviene in genere da sottoprodotti animali ricchi di proteine di cheratina, come lana, piume, peli di animali o zoccoli.<\/p><\/span>\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div id=\"uael-accordion-d192ade\" class=\"uael-faq-accordion\" role=\"tablist\">\n\t\t\t\t\t\t\t\t<div class= \"uael-accordion-title\" aria-expanded=\"false\" role=\"tab\">\n\t\t\t\t\t\t\t\t\t<span class=\"uael-accordion-icon uael-accordion-icon-left\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"uael-accordion-icon-closed\"><svg class=\"e-font-icon-svg e-fas-angle-right\" viewbox=\"0 0 256 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M224.3 273l-136 136c-9.4 9.4-24.6 9.4-33.9 0l-22.6-22.6c-9.4-9.4-9.4-24.6 0-33.9l96.4-96.4-96.4-96.4c-9.4-9.4-9.4-24.6 0-33.9L54.3 103c9.4-9.4 24.6-9.4 33.9 0l136 136c9.5 9.4 9.5 24.6.1 34z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"uael-accordion-icon-opened\"><svg class=\"e-font-icon-svg e-fas-angle-up\" viewbox=\"0 0 320 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M177 159.7l136 136c9.4 9.4 9.4 24.6 0 33.9l-22.6 22.6c-9.4 9.4-24.6 9.4-33.9 0L160 255.9l-96.4 96.4c-9.4 9.4-24.6 9.4-33.9 0L7 329.7c-9.4-9.4-9.4-24.6 0-33.9l136-136c9.4-9.5 24.6-9.5 34-.1z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"uael-question-d192ade uael-question-span\" tabindex=\"0\" id=\"uael-faq-6-6a03e4ed90f67\">La cheratina idrolizzata \u00e8 vegana?<\/span>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"uael-accordion-content\" role=\"tabpanel\">\n\t\t\t\t\t\t\t\t\t<span>\n\t\t\t\t\t\t\t\t\t<span><p>No, la cheratina idrolizzata tradizionale ricavata da sottoprodotti animali non \u00e8 vegana. Le alternative vegane derivano da fonti vegetali come il grano, il mais o la soia, anche se tecnicamente si tratta di proteine vegetali idrolizzate, non di vera cheratina.<\/p><\/span>\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div id=\"uael-accordion-89a2bf9\" class=\"uael-faq-accordion\" role=\"tablist\">\n\t\t\t\t\t\t\t\t<div class= \"uael-accordion-title\" aria-expanded=\"false\" role=\"tab\">\n\t\t\t\t\t\t\t\t\t<span class=\"uael-accordion-icon uael-accordion-icon-left\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"uael-accordion-icon-closed\"><svg class=\"e-font-icon-svg e-fas-angle-right\" viewbox=\"0 0 256 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M224.3 273l-136 136c-9.4 9.4-24.6 9.4-33.9 0l-22.6-22.6c-9.4-9.4-9.4-24.6 0-33.9l96.4-96.4-96.4-96.4c-9.4-9.4-9.4-24.6 0-33.9L54.3 103c9.4-9.4 24.6-9.4 33.9 0l136 136c9.5 9.4 9.5 24.6.1 34z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"uael-accordion-icon-opened\"><svg class=\"e-font-icon-svg e-fas-angle-up\" viewbox=\"0 0 320 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M177 159.7l136 136c9.4 9.4 9.4 24.6 0 33.9l-22.6 22.6c-9.4 9.4-24.6 9.4-33.9 0L160 255.9l-96.4 96.4c-9.4 9.4-24.6 9.4-33.9 0L7 329.7c-9.4-9.4-9.4-24.6 0-33.9l136-136c9.4-9.5 24.6-9.5 34-.1z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"uael-question-89a2bf9 uael-question-span\" tabindex=\"0\" id=\"uael-faq-7-6a03e4ed90f8c\">La cheratina idrolizzata \u00e8 sicura?<\/span>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"uael-accordion-content\" role=\"tabpanel\">\n\t\t\t\t\t\t\t\t\t<span>\n\t\t\t\t\t\t\t\t\t<span><p>La cheratina idrolizzata \u00e8 generalmente considerata sicura per l'uso in prodotti cosmetici e per la cura della persona, se usata come indicato.<\/p><\/span>\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div id=\"uael-accordion-dc64af0\" class=\"uael-faq-accordion\" role=\"tablist\">\n\t\t\t\t\t\t\t\t<div class= \"uael-accordion-title\" aria-expanded=\"false\" role=\"tab\">\n\t\t\t\t\t\t\t\t\t<span class=\"uael-accordion-icon uael-accordion-icon-left\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"uael-accordion-icon-closed\"><svg class=\"e-font-icon-svg e-fas-angle-right\" viewbox=\"0 0 256 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M224.3 273l-136 136c-9.4 9.4-24.6 9.4-33.9 0l-22.6-22.6c-9.4-9.4-9.4-24.6 0-33.9l96.4-96.4-96.4-96.4c-9.4-9.4-9.4-24.6 0-33.9L54.3 103c9.4-9.4 24.6-9.4 33.9 0l136 136c9.5 9.4 9.5 24.6.1 34z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"uael-accordion-icon-opened\"><svg class=\"e-font-icon-svg e-fas-angle-up\" viewbox=\"0 0 320 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M177 159.7l136 136c9.4 9.4 9.4 24.6 0 33.9l-22.6 22.6c-9.4 9.4-24.6 9.4-33.9 0L160 255.9l-96.4 96.4c-9.4 9.4-24.6 9.4-33.9 0L7 329.7c-9.4-9.4-9.4-24.6 0-33.9l136-136c9.4-9.5 24.6-9.5 34-.1z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"uael-question-dc64af0 uael-question-span\" tabindex=\"0\" id=\"uael-faq-8-6a03e4ed90fb0\">Qual \u00e8 la differenza tra i diversi tipi di cheratina idrolizzata?<\/span>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"uael-accordion-content\" role=\"tabpanel\">\n\t\t\t\t\t\t\t\t\t<span>\n\t\t\t\t\t\t\t\t\t<span><p>La cheratina idrolizzata pu\u00f2 variare in base al materiale di partenza (lana, piume, ecc.) e al grado di idrolisi (quanto \u00e8 stata scomposta), che influisce sulla distribuzione del peso molecolare. Pesi molecolari diversi possono offrire propriet\u00e0 e capacit\u00e0 di penetrazione leggermente diverse per i capelli e la pelle.<\/p><\/span>\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div id=\"uael-accordion-1f0f649\" class=\"uael-faq-accordion\" role=\"tablist\">\n\t\t\t\t\t\t\t\t<div class= \"uael-accordion-title\" aria-expanded=\"false\" role=\"tab\">\n\t\t\t\t\t\t\t\t\t<span class=\"uael-accordion-icon uael-accordion-icon-left\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"uael-accordion-icon-closed\"><svg class=\"e-font-icon-svg e-fas-angle-right\" viewbox=\"0 0 256 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M224.3 273l-136 136c-9.4 9.4-24.6 9.4-33.9 0l-22.6-22.6c-9.4-9.4-9.4-24.6 0-33.9l96.4-96.4-96.4-96.4c-9.4-9.4-9.4-24.6 0-33.9L54.3 103c9.4-9.4 24.6-9.4 33.9 0l136 136c9.5 9.4 9.5 24.6.1 34z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"uael-accordion-icon-opened\"><svg class=\"e-font-icon-svg e-fas-angle-up\" viewbox=\"0 0 320 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M177 159.7l136 136c9.4 9.4 9.4 24.6 0 33.9l-22.6 22.6c-9.4 9.4-24.6 9.4-33.9 0L160 255.9l-96.4 96.4c-9.4 9.4-24.6 9.4-33.9 0L7 329.7c-9.4-9.4-9.4-24.6 0-33.9l136-136c9.4-9.5 24.6-9.5 34-.1z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"uael-question-1f0f649 uael-question-span\" tabindex=\"0\" id=\"uael-faq-9-6a03e4ed90fd4\">La cheratina idrolizzata aiuta a riparare i capelli danneggiati?<\/span>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"uael-accordion-content\" role=\"tabpanel\">\n\t\t\t\t\t\t\t\t\t<span>\n\t\t\t\t\t\t\t\t\t<span><p>S\u00ec, la cheratina idrolizzata \u00e8 ampiamente utilizzata nei prodotti per capelli proprio per aiutare a riparare i capelli danneggiati. I frammenti proteici possono temporaneamente colmare le lacune e rafforzare le aree indebolite della cuticola del capello, riducendo la rottura e migliorando la salute generale dei capelli.<\/p><\/span>\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div id=\"uael-accordion-b5f1c2e\" class=\"uael-faq-accordion\" role=\"tablist\">\n\t\t\t\t\t\t\t\t<div class= \"uael-accordion-title\" aria-expanded=\"false\" role=\"tab\">\n\t\t\t\t\t\t\t\t\t<span class=\"uael-accordion-icon uael-accordion-icon-left\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"uael-accordion-icon-closed\"><svg class=\"e-font-icon-svg e-fas-angle-right\" viewbox=\"0 0 256 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M224.3 273l-136 136c-9.4 9.4-24.6 9.4-33.9 0l-22.6-22.6c-9.4-9.4-9.4-24.6 0-33.9l96.4-96.4-96.4-96.4c-9.4-9.4-9.4-24.6 0-33.9L54.3 103c9.4-9.4 24.6-9.4 33.9 0l136 136c9.5 9.4 9.5 24.6.1 34z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"uael-accordion-icon-opened\"><svg class=\"e-font-icon-svg e-fas-angle-up\" viewbox=\"0 0 320 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M177 159.7l136 136c9.4 9.4 9.4 24.6 0 33.9l-22.6 22.6c-9.4 9.4-24.6 9.4-33.9 0L160 255.9l-96.4 96.4c-9.4 9.4-24.6 9.4-33.9 0L7 329.7c-9.4-9.4-9.4-24.6 0-33.9l136-136c9.4-9.5 24.6-9.5 34-.1z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"uael-question-b5f1c2e uael-question-span\" tabindex=\"0\" id=\"uael-faq-10-6a03e4ed90ff8\">Come utilizzare la cheratina idrolizzata?<\/span>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"uael-accordion-content\" role=\"tabpanel\">\n\t\t\t\t\t\t\t\t\t<span>\n\t\t\t\t\t\t\t\t\t<span><p>La cheratina idrolizzata \u00e8 un ingrediente presente in diversi prodotti per la cura dei capelli (shampoo, balsami, trattamenti leave-in) e della pelle. Utilizzare i prodotti contenenti cheratina idrolizzata come indicato sulla confezione.<\/p><\/span>\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-6d3c6f15 e-flex e-con-boxed e-con e-parent\" data-id=\"6d3c6f15\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-233b4283 e-con-full e-flex e-con e-child\" data-id=\"233b4283\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-3a5a891c elementor-widget elementor-widget-heading\" data-id=\"3a5a891c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Affidata da molti, pronta per voi: Leggi le testimonianze e chiedi subito informazioni<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-550e2296 e-con-full e-flex e-con e-child\" data-id=\"550e2296\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-3bc0f334 e-con-full e-flex e-con e-child\" data-id=\"3bc0f334\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-34f3bb7 elementor-testimonial--skin-default elementor-testimonial--layout-image_inline elementor-testimonial--align-center elementor-arrows-yes elementor-pagination-type-bullets elementor-widget elementor-widget-testimonial-carousel\" data-id=\"34f3bb7\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;show_arrows&quot;:&quot;yes&quot;,&quot;pagination&quot;:&quot;bullets&quot;,&quot;speed&quot;:500,&quot;autoplay&quot;:&quot;yes&quot;,&quot;autoplay_speed&quot;:5000,&quot;loop&quot;:&quot;yes&quot;,&quot;pause_on_hover&quot;:&quot;yes&quot;,&quot;pause_on_interaction&quot;:&quot;yes&quot;,&quot;space_between&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:10,&quot;sizes&quot;:[]},&quot;space_between_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:10,&quot;sizes&quot;:[]},&quot;space_between_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:10,&quot;sizes&quot;:[]}}\" data-widget_type=\"testimonial-carousel.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper\">\n\t\t\t\t\t<div class=\"elementor-main-swiper swiper\" role=\"region\" aria-roledescription=\"carousel\" aria-label=\"Diapositive\">\n\t\t\t\t<div class=\"swiper-wrapper\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-testimonial\">\n\t\t\t\t\t\t\t<div class=\"elementor-testimonial__content\">\n\t\t\t\t\t<div class=\"elementor-testimonial__text\">\n\t\t\t\t\t\tGensei fornisce la cheratina idrolizzata di alta qualit\u00e0 di cui abbiamo bisogno per i nostri prodotti idratanti per la pelle. La consistenza e l'efficacia sono sempre eccellenti. Come fornitore, Gensei \u00e8 affidabile e ci garantisce sempre la cheratina idrolizzata necessaria per la produzione.\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"elementor-testimonial__footer\">\n\t\t\t\t\t\t\t\t<cite class=\"elementor-testimonial__cite\"><span class=\"elementor-testimonial__name\">John Davis<\/span><span class=\"elementor-testimonial__title\">Responsabile acquisti, Soluzioni JointCare<\/span><\/cite>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-testimonial\">\n\t\t\t\t\t\t\t<div class=\"elementor-testimonial__content\">\n\t\t\t\t\t<div class=\"elementor-testimonial__text\">\n\t\t\t\t\t\tIn qualit\u00e0 di produttore di ingredienti cosmetici specializzati, la purezza delle nostre materie prime \u00e8 fondamentale. La cheratina idrolizzata di Gensei soddisfa i nostri rigorosi standard. \u00c8 un fornitore affidabile e la sua cheratina idrolizzata \u00e8 un componente chiave dei prodotti che sviluppiamo.\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"elementor-testimonial__footer\">\n\t\t\t\t\t\t\t\t<cite class=\"elementor-testimonial__cite\"><span class=\"elementor-testimonial__name\">Emily Carter<\/span><span class=\"elementor-testimonial__title\">Responsabile Sviluppo Prodotti, Integratori Sportivi Globali<\/span><\/cite>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-testimonial\">\n\t\t\t\t\t\t\t<div class=\"elementor-testimonial__content\">\n\t\t\t\t\t<div class=\"elementor-testimonial__text\">\n\t\t\t\t\t\tLa cheratina idrolizzata di Gensei \u00e8 stata una fantastica aggiunta ai nostri trattamenti di rafforzamento delle unghie. La qualit\u00e0 \u00e8 eccellente e i nostri clienti hanno visto risultati concreti. \u00c8 un fornitore di fiducia per le nostre esigenze di cheratina idrolizzata.\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"elementor-testimonial__footer\">\n\t\t\t\t\t\t\t\t<cite class=\"elementor-testimonial__cite\"><span class=\"elementor-testimonial__name\">Lisa Green<\/span><span class=\"elementor-testimonial__title\">Direttore di produzione, Laboratori NutraBio<\/span><\/cite>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-prev\" role=\"button\" tabindex=\"0\" aria-label=\"Pr\u00e9c\u00e9dent\" data-no-translation-aria-label=\"\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-eicon-chevron-left\" viewbox=\"0 0 1000 1000\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M646 125C629 125 613 133 604 142L308 442C296 454 292 471 292 487 292 504 296 521 308 533L604 854C617 867 629 875 646 875 663 875 679 871 692 858 704 846 713 829 713 812 713 796 708 779 692 767L438 487 692 225C700 217 708 204 708 187 708 171 704 154 692 142 675 129 663 125 646 125Z\"><\/path><\/svg>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-next\" role=\"button\" tabindex=\"0\" aria-label=\"Suivant\" data-no-translation-aria-label=\"\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-eicon-chevron-right\" viewbox=\"0 0 1000 1000\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M696 533C708 521 713 504 713 487 713 471 708 454 696 446L400 146C388 133 375 125 354 125 338 125 325 129 313 142 300 154 292 171 292 187 292 204 296 221 308 233L563 492 304 771C292 783 288 800 288 817 288 833 296 850 308 863 321 871 338 875 354 875 371 875 388 867 400 854L696 533Z\"><\/path><\/svg>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-pagination\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-1e740656 e-con-full e-flex e-con e-child\" data-id=\"1e740656\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-11d68e83 uael-cf7-btn-size-xs uael-cf7-style-box uael-cf7-input-size-sm uael-cf7-button-left uael-cf7-highlight-style-default elementor-widget elementor-widget-uael-cf7-styler\" data-id=\"11d68e83\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"uael-cf7-styler.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class = \"uael-cf7-container\">\n\t\t\t\t\t\t<div class = \"uael-cf7 uael-cf7-style elementor-clickable\">\n\t\t\t\t\t\t\n<div class=\"wpcf7 no-js\" id=\"wpcf7-f74-o1\" lang=\"zh-CN\" dir=\"ltr\" data-wpcf7-id=\"74\">\n<div class=\"screen-reader-response\"><p role=\"status\" aria-live=\"polite\" aria-atomic=\"true\"><\/p> <ul><\/ul><\/div>\n<form action=\"\/it\/wp-json\/wp\/v2\/pages\/4785#wpcf7-f74-o1\" method=\"post\" class=\"wpcf7-form init\" aria-label=\"\u7559\u8a00\u8868\u5355\" novalidate=\"novalidate\" data-status=\"init\" data-trp-original-action=\"\/it\/wp-json\/wp\/v2\/pages\/4785#wpcf7-f74-o1\">\n<fieldset class=\"hidden-fields-container\"><input type=\"hidden\" name=\"_wpcf7\" value=\"74\" \/><input type=\"hidden\" name=\"_wpcf7_version\" value=\"6.1.5\" \/><input type=\"hidden\" name=\"_wpcf7_locale\" value=\"zh_CN\" \/><input type=\"hidden\" name=\"_wpcf7_unit_tag\" value=\"wpcf7-f74-o1\" \/><input type=\"hidden\" name=\"_wpcf7_container_post\" value=\"0\" \/><input type=\"hidden\" name=\"_wpcf7_posted_data_hash\" value=\"\" \/>\n<\/fieldset>\n<div class=\"stay-touch\">\n\t<ul>\n\t\t<li>\n\t\t\t<p><label> Nome: <span class=\"wpcf7-form-control-wrap\" data-name=\"your-name\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"text\" name=\"your-name\" \/><\/span><\/label>\n\t\t\t<\/p>\n\t\t<\/li>\n\t\t<li>\n\t\t\t<p><label> Nome della societ\u00e0: <span class=\"wpcf7-form-control-wrap\" data-name=\"your-company\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"text\" name=\"your-company\" \/><\/span><\/label>\n\t\t\t<\/p>\n\t\t<\/li>\n\t\t<li>\n\t\t\t<p><label> E-mail: <span class=\"wpcf7-form-control-wrap\" data-name=\"your-email\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"text\" name=\"your-email\" \/><\/span><\/label>\n\t\t\t<\/p>\n\t\t<\/li>\n\t\t<li>\n\t\t\t<p><label> Tel: <span class=\"wpcf7-form-control-wrap\" data-name=\"your-tel\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"text\" name=\"your-tel\" \/><\/span><\/label>\n\t\t\t<\/p>\n\t\t<\/li>\n\t\t<li>\n\t\t\t<p><label> Messaggio: <span class=\"wpcf7-form-control-wrap\" data-name=\"your-message\"><textarea cols=\"40\" rows=\"10\" maxlength=\"2000\" class=\"wpcf7-form-control wpcf7-textarea wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" name=\"your-message\"><\/textarea><\/span><\/label>\n\t\t\t<\/p>\n\t\t<\/li>\n\t\t<li style=\"text-align:center\">\n\t\t\t<p><input class=\"wpcf7-form-control wpcf7-submit has-spinner\" type=\"submit\" value=\"INVIO\" \/>\n\t\t\t<\/p>\n\t\t<\/li>\n\t<\/ul>\n<\/div><div class=\"wpcf7-response-output\" aria-hidden=\"true\"><\/div>\n<input type=\"hidden\" name=\"trp-form-language\" value=\"it\"\/><\/form>\n<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>bulk hydrolyzed keratin exporter Looking for a bulk hydrolyzed keratin exporter \u00a0to enhance your hair and skin care lines? Gensei [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":4813,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_uag_custom_page_level_css":"","site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"disabled","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"class_list":["post-4785","page","type-page","status-publish","hentry"],"uagb_featured_image_src":{"full":false,"thumbnail":false,"medium":false,"medium_large":false,"large":false,"1536x1536":false,"2048x2048":false,"trp-custom-language-flag":false},"uagb_author_info":{"display_name":"collagensei.com","author_link":"https:\/\/collagensei.com\/it\/author\/collagensei\/"},"uagb_comment_info":0,"uagb_excerpt":"bulk hydrolyzed keratin exporter Looking for a bulk hydrolyzed keratin exporter \u00a0to enhance your hair and skin care lines? Gensei [&hellip;]","_links":{"self":[{"href":"https:\/\/collagensei.com\/it\/wp-json\/wp\/v2\/pages\/4785","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/collagensei.com\/it\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/collagensei.com\/it\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/collagensei.com\/it\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/collagensei.com\/it\/wp-json\/wp\/v2\/comments?post=4785"}],"version-history":[{"count":19,"href":"https:\/\/collagensei.com\/it\/wp-json\/wp\/v2\/pages\/4785\/revisions"}],"predecessor-version":[{"id":15703,"href":"https:\/\/collagensei.com\/it\/wp-json\/wp\/v2\/pages\/4785\/revisions\/15703"}],"up":[{"embeddable":true,"href":"https:\/\/collagensei.com\/it\/wp-json\/wp\/v2\/pages\/4813"}],"wp:attachment":[{"href":"https:\/\/collagensei.com\/it\/wp-json\/wp\/v2\/media?parent=4785"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}