{"id":4861,"date":"2025-03-20T15:44:50","date_gmt":"2025-03-20T07:44:50","guid":{"rendered":"https:\/\/collagensei.com\/?page_id=4861"},"modified":"2025-07-17T15:40:53","modified_gmt":"2025-07-17T07:40:53","slug":"vitamina-un-produttore","status":"publish","type":"page","link":"https:\/\/collagensei.com\/it\/vitamins-supplier\/vitamin-a-manufacturer\/","title":{"rendered":"Vitamina A Produttore"},"content":{"rendered":"<div data-elementor-type=\"wp-page\" data-elementor-id=\"4861\" class=\"elementor elementor-4861\" data-elementor-post-type=\"page\">\n\t\t\t\t<div class=\"elementor-element elementor-element-661f899 e-flex e-con-boxed e-con e-parent\" data-id=\"661f899\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-5c17510a e-con-full e-flex e-con e-child\" data-id=\"5c17510a\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-37b2f621 e-con-full e-flex e-con e-child\" data-id=\"37b2f621\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-52541508 elementor-widget__width-initial elementor-widget elementor-widget-image\" data-id=\"52541508\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"898\" height=\"916\" src=\"https:\/\/collagensei.com\/wp-content\/uploads\/2025\/02\/Vitamin-A-Palmitate-1.png\" class=\"attachment-large size-large wp-image-4546\" alt=\"Materia prima vitamina A\" srcset=\"https:\/\/collagensei.com\/wp-content\/uploads\/2025\/02\/Vitamin-A-Palmitate-1.png 898w, https:\/\/collagensei.com\/wp-content\/uploads\/2025\/02\/Vitamin-A-Palmitate-1-294x300.png 294w, https:\/\/collagensei.com\/wp-content\/uploads\/2025\/02\/Vitamin-A-Palmitate-1-768x783.png 768w\" sizes=\"(max-width: 898px) 100vw, 898px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-1983f235 e-con-full e-flex e-con e-child\" data-id=\"1983f235\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-2230701d elementor-widget elementor-widget-heading\" data-id=\"2230701d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">Produttore di materie prime di vitamina A<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5efad000 elementor-widget elementor-widget-text-editor\" data-id=\"5efad000\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p data-sourcepos=\"21:1-21:366\">La vitamina A \u00e8 una vitamina liposolubile fondamentale per il mantenimento di una visione sana, della funzione immunitaria e della crescita cellulare. Svolge un ruolo fondamentale nella fotorecezione della retina, garantendo una buona vista, soprattutto in condizioni di scarsa illuminazione. Oltre alla salute oculare, la vitamina A favorisce l'integrit\u00e0 della pelle, i processi riproduttivi e agisce come antiossidante, proteggendo l'organismo dallo stress ossidativo.<\/p><p data-sourcepos=\"23:1-23:499\">Gensei offre un'alta qualit\u00e0 <a class=\"wpil_keyword_link\" href=\"https:\/\/collagensei.com\/it\/fornitore-di-vitamine\/vitamina-a-acetato-in-polvere\/\" target=\"_blank\"  rel=\"noopener\" title=\"Acetato di vitamina A in polvere\" data-wpil-keyword-link=\"linked\"  data-wpil-monitor-id=\"763\">Materia prima vitamina A<\/a>, ideale per varie applicazioni. In qualit\u00e0 di produttore leader di materie prime di vitamina A, siamo specializzati nella vendita all'ingrosso di vitamina A, fornendo un prodotto coerente e puro. <a class=\"wpil_keyword_link\" href=\"https:\/\/collagensei.com\/it\/fornitore-di-vitamine\/vitamina-a-palmitato-in-polvere\/\"   title=\"Vitamina A Palmitato in polvere\" data-wpil-keyword-link=\"linked\"  data-wpil-monitor-id=\"233\">Vitamina A in polvere<\/a> alla rinfusa. I nostri processi di produzione avanzati garantiscono che la nostra vitamina A soddisfi rigorosi standard di qualit\u00e0, rendendola una scelta affidabile per integratori alimentari, alimenti fortificati e formulazioni cosmetiche. Scegli Gensei per le tue esigenze di vitamina A e approfitta del nostro impegno verso l'eccellenza e la soddisfazione del cliente.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-2b1051c e-con-full e-flex e-con e-child\" data-id=\"2b1051c\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-3925e04e elementor-widget elementor-widget-text-editor\" data-id=\"3925e04e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><i><b>Si prega di notare:<\/b>\u00a0Siamo un fornitore all'ingrosso e abbiamo quantit\u00e0 minime d'ordine.<\/i><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2b46715c elementor-align-left elementor-widget elementor-widget-button\" data-id=\"2b46715c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"#elementor-action%3Aaction%3Dpopup%3Aopen%26settings%3DeyJpZCI6IjQ5OTIiLCJ0b2dnbGUiOmZhbHNlfQ%3D%3D\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Richiesta di preventivo<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-12d97f41 elementor-widget elementor-widget-text-editor\" data-id=\"12d97f41\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Avete domande su questo prodotto? Il nostro team \u00e8 qui per aiutarvi. Per richieste relative a pi\u00f9 ingredienti, utilizzare l'opzione\u00a0<a href=\"https:\/\/collagensei.com\/it\/contattateci\/\">Contatto<\/a>\u00a0e includere l'elenco degli ingredienti nel messaggio.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-4c7f653c e-con-full e-flex e-con e-child\" data-id=\"4c7f653c\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-678bd321 e-con-full e-flex e-con e-child\" data-id=\"678bd321\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-85f6211 elementor-widget elementor-widget-text-editor\" data-id=\"85f6211\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<ul><li data-sourcepos=\"131:1-131:56\"><strong>Vitamina A Numero CAS:<\/strong> 79-81-2 (per il palmitato di retinile)<\/li><li data-sourcepos=\"132:1-132:38\"><strong>Nome chimico:<\/strong> Retinil palmitato<\/li><li data-sourcepos=\"133:1-133:76\"><strong>Sinonimi:<\/strong> Palmitato di vitamina A, palmitato di retinolo, palmitato di axeroftolo<\/li><li data-sourcepos=\"134:1-134:325\"><strong>Numero CB:<\/strong> Sebbene non esista un \"numero CB\" universale per tutte le sostanze chimiche, per il Retinil palmitato si possono utilizzare i numeri di catalogo correlati dei fornitori (ad esempio, i numeri di articolo specifici dei fornitori di sostanze chimiche). Non esiste un unico numero CB standardizzato per la vitamina A che sia ampiamente riconosciuto come un numero CAS.<\/li><li data-sourcepos=\"135:1-135:72\"><strong>Formula molecolare:<\/strong> C$_{36}$H$_{60}$O$_{2}$ (per il palmitato di retinile)<\/li><li data-sourcepos=\"136:1-136:60\"><strong>Peso molecolare:<\/strong> 524,86 g\/mol (per il Retinil Palmitato)<\/li><li data-sourcepos=\"137:1-138:0\"><strong>Numero MDL:<\/strong> MFCD00001579 (per il palmitato di retinile)<\/li><\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-59938897 e-con-full e-flex e-con e-child\" data-id=\"59938897\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-444a651f elementor-widget elementor-widget-image\" data-id=\"444a651f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/collagensei.com\/wp-content\/uploads\/2025\/05\/vitamin-A-myristate.png\" title=\"\" alt=\"\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-70e63c2 e-flex e-con-boxed e-con e-parent\" data-id=\"70e63c2\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-2325c67 elementor-widget elementor-widget-html\" data-id=\"2325c67\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<!DOCTYPE html>\r\n<html lang=\"en\">\r\n<head>\r\n    <meta charset=\"UTF-8\">\r\n    <meta name=\"viewport\" content=\"width=device-width, initial-scale=1.0\">\r\n    <title>Processo di produzione della vitamina A<\/title>\r\n    <style>\r\n        h2 {\r\n            color: #2E638C; \/* Changed to #2E638C *\/\r\n            text-align: center;\r\n        }\r\n        .flowchart {\r\n            display: flex;\r\n            flex-direction: row; \/* Changed to row for left-to-right *\/\r\n            justify-content: center; \/* Center items horizontally *\/\r\n            align-items: flex-start; \/* Align items to the top for consistent flow *\/\r\n            font-family: Arial, sans-serif;\r\n            margin-top: 20px;\r\n            flex-wrap: wrap; \/* Allow steps to wrap to the next line on smaller screens *\/\r\n        }\r\n        .step {\r\n            border: 2px solid #ccc;\r\n            border-radius: 8px;\r\n            padding: 15px 25px;\r\n            margin: 10px; \/* Adjusted margin for horizontal layout *\/\r\n            text-align: center;\r\n            background-color: #f9f9f9;\r\n            box-shadow: 2px 2px 5px rgba(0,0,0,0.1);\r\n            position: relative;\r\n            width: 250px; \/* Fixed width for consistency *\/\r\n            flex-shrink: 0; \/* Prevent steps from shrinking *\/\r\n        }\r\n        .step h3 {\r\n            color: #2E638C; \/* Applied color to H3 titles *\/\r\n        }\r\n        .arrow {\r\n            width: 20px; \/* Width for horizontal arrow *\/\r\n            height: 0;\r\n            border-top: 10px solid transparent;\r\n            border-bottom: 10px solid transparent;\r\n            border-left: 20px solid #ccc; \/* Arrow pointing right *\/\r\n            margin: 0 -2px; \/* Adjust to connect steps closer horizontally *\/\r\n            align-self: center; \/* Center arrow vertically between steps *\/\r\n        }\r\n        .step:not(:last-child) + .arrow { \/* Only display arrow if it's not the last step *\/\r\n            display: block;\r\n        }\r\n        .flowchart > .step:last-child + .arrow {\r\n            display: none; \/* Hide arrow after the last step *\/\r\n        }\r\n    <\/style>\r\n<\/head>\r\n<body>\r\n\r\n    <h2 style=\"color: #2E638C;\">Processo di produzione della vitamina A<\/h2>\r\n\r\n    <div class=\"flowchart\">\r\n        <div class=\"step\">\r\n            <h3>Fase 1: Approvvigionamento di materie prime (precursori isoprenoidi)<\/h3>\r\n            <p>Vengono acquistati precursori di alta qualit\u00e0, come il beta-ionone. Questi sono tipicamente derivati da fonti naturali come l'olio di citronella o tramite sintesi chimica.<\/p>\r\n        <\/div>\r\n        <div class=\"arrow\"><\/div>\r\n\r\n        <div class=\"step\">\r\n            <h3>Fase 2: Sintesi chimica a pi\u00f9 fasi<\/h3>\r\n            <p>Viene eseguita una complessa serie di reazioni organiche per costruire la molecola di vitamina A a partire dai precursori isoprenoidi. Ci\u00f2 comporta tipicamente diverse fasi di condensazione, riduzione e ciclizzazione.<\/p>\r\n        <\/div>\r\n        <div class=\"arrow\"><\/div>\r\n\r\n        <div class=\"step\">\r\n            <h3>Fase 3: Purificazione e isolamento<\/h3>\r\n            <p>L'intermedio di vitamina A grezzo viene purificato con tecniche come la cristallizzazione, la distillazione o la cromatografia per rimuovere le impurit\u00e0 e i sottoprodotti indesiderati, ottenendo una forma pi\u00f9 pura.<\/p>\r\n        <\/div>\r\n        <div class=\"arrow\"><\/div>\r\n\r\n        <div class=\"step\">\r\n            <h3>Fase 4: Esterificazione (ad esempio, retinil palmitato, retinil acetato)<\/h3>\r\n            <p>L'alcol di vitamina A purificato (retinolo) viene fatto reagire con un acido grasso (ad esempio, acido palmitico o acido acetico) per formare una forma estere pi\u00f9 stabile, come il Retinil Palmitato o il Retinil Acetato.<\/p>\r\n        <\/div>\r\n        <div class=\"arrow\"><\/div>\r\n\r\n        <div class=\"step\">\r\n            <h3>Fase 5: Micronizzazione o incapsulamento (per le forme in polvere)<\/h3>\r\n            <p>Per la vitamina A in polvere, l'estere \u00e8 spesso micronizzato (macinato in particelle fini) o incapsulato in una matrice protettiva (ad esempio, gelatina, amido) per migliorare la stabilit\u00e0, la fluidit\u00e0 e la dispersione.<\/p>\r\n        <\/div>\r\n        <div class=\"arrow\"><\/div>\r\n\r\n        <div class=\"step\">\r\n            <h3>Fase 6: Controllo qualit\u00e0 e test<\/h3>\r\n            <p>Vengono condotti numerosi test di controllo della qualit\u00e0, tra cui test di purezza, potenza, identificazione, metalli pesanti e contaminazione microbica, per garantire la sicurezza e l'efficacia del prodotto.<\/p>\r\n        <\/div>\r\n        <div class=\"arrow\"><\/div>\r\n\r\n        <div class=\"step\">\r\n            <h3>Fase 7: Imballaggio e stoccaggio<\/h3>\r\n            <p>Il prodotto finito a base di vitamina A viene accuratamente confezionato in contenitori ermetici e protetti dalla luce. Vengono mantenute specifiche condizioni di conservazione (ad esempio, luogo fresco, asciutto e buio) per preservarne la stabilit\u00e0 e la durata di conservazione.<\/p>\r\n        <\/div>\r\n    <\/div>\r\n\r\n<\/body>\r\n<\/html>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-56ea3494 e-flex e-con-boxed e-con e-parent\" data-id=\"56ea3494\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-1feb7e51 elementor-widget elementor-widget-heading\" data-id=\"1feb7e51\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Perch\u00e9 scegliere Gensei come fornitore di vitamina A?<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6f49cd8b elementor-widget elementor-widget-text-editor\" data-id=\"6f49cd8b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p data-sourcepos=\"192:1-192:280\">Gensei \u00e8 la vostra fonte affidabile di Vitamina A di qualit\u00e0 superiore, in quanto produttore leader di Vitamina A con particolare attenzione alla fornitura di Vitamina A in polvere di alta qualit\u00e0. Siamo esperti di vitamina A all'ingrosso e forniamo una fornitura costante di vitamina A in polvere di qualit\u00e0 superiore per soddisfare le richieste dell'industria degli integratori, degli alimenti e dei cosmetici. La nostra dedizione all'innovazione e al miglioramento continuo fa s\u00ec che riceviate vitamina A prodotta con tecnologie all'avanguardia e in base a rigorose linee guida di qualit\u00e0. Conosciamo le sfumature di questo nutriente vitale e garantiamo che il nostro prodotto offra un'eccellente biodisponibilit\u00e0 e stabilit\u00e0, rendendo Gensei la scelta intelligente per la vostra fornitura di Vitamina A a lungo termine.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9753e57 elementor-widget elementor-widget-text-editor\" data-id=\"9753e57\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>La vitamina A si riferisce a un gruppo di retinoidi liposolubili, tra cui il retinolo, il retinale e l'acido retinoico. \u00c8 fondamentale per mantenere una buona visione, soprattutto in condizioni di scarsa illuminazione, in quanto \u00e8 un componente chiave della rodopsina, una molecola che assorbe la luce nella retina. Oltre alla vista, la vitamina A svolge un ruolo fondamentale nella funzione immunitaria, sostenendo la crescita e la differenziazione di varie cellule immunitarie. Promuove inoltre la salute della pelle e delle mucose, favorisce la crescita delle ossa ed \u00e8 essenziale per la salute riproduttiva. \u00c8 un potente antiossidante che protegge le cellule dai danni.<\/p><p data-sourcepos=\"156:1-156:40\">Scenari di applicazione della vitamina A:<\/p><ul data-sourcepos=\"158:1-163:0\"><li data-sourcepos=\"158:1-158:161\">Integratori alimentari: Ampiamente utilizzata negli integratori multivitaminici e negli integratori di vitamina A a s\u00e9 stanti per favorire la vista, la salute immunitaria e il benessere generale.<\/li><li data-sourcepos=\"159:1-159:149\">Fortificazione alimentare: Aggiunta agli alimenti di base come latte, cereali e margarina per combattere la carenza di vitamina A, soprattutto nelle regioni in via di sviluppo.<\/li><li data-sourcepos=\"160:1-160:266\">Cosmetici e trattamenti per la pelle: I retinoidi (derivati della vitamina A come il retinolo e l'acido retinoico) sono molto diffusi nelle creme anti-invecchiamento, nei trattamenti contro l'acne e nei prodotti per il ringiovanimento della pelle grazie alla loro capacit\u00e0 di promuovere il ricambio cellulare, ridurre le rughe e migliorare il tono della pelle.<\/li><li data-sourcepos=\"161:1-161:117\">Prodotti farmaceutici: Utilizzato in alcune preparazioni oftalmiche e in trattamenti dermatologici per condizioni specifiche.<\/li><li data-sourcepos=\"162:1-163:0\">Nutrizione animale: Incluso nei mangimi per sostenere la crescita, la riproduzione e la salute immunitaria del bestiame e del pollame.<\/li><\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-54060cd1 e-flex e-con-boxed e-con e-parent\" data-id=\"54060cd1\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-2282da65 e-con-full e-flex e-con e-child\" data-id=\"2282da65\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-12cb8df7 elementor-widget elementor-widget-heading\" data-id=\"12cb8df7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">I nostri impianti di produzione all'avanguardia<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1f5e8f6f elementor-widget elementor-widget-text-editor\" data-id=\"1f5e8f6f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Esplorate le nostre moderne strutture dotate di tecnologie avanzate per garantire la massima qualit\u00e0 nella produzione di vitamine, estratti di erbe, minerali e aminoacidi.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-4da4fc80 e-con-full e-flex e-con e-child\" data-id=\"4da4fc80\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-361c5f3b elementor-arrows-position-inside elementor-pagination-position-outside elementor-widget elementor-widget-image-carousel\" data-id=\"361c5f3b\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;slides_to_show&quot;:&quot;3&quot;,&quot;slides_to_scroll&quot;:&quot;1&quot;,&quot;lazyload&quot;:&quot;yes&quot;,&quot;image_spacing_custom&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:5,&quot;sizes&quot;:[]},&quot;navigation&quot;:&quot;both&quot;,&quot;autoplay&quot;:&quot;yes&quot;,&quot;pause_on_hover&quot;:&quot;yes&quot;,&quot;pause_on_interaction&quot;:&quot;yes&quot;,&quot;autoplay_speed&quot;:5000,&quot;infinite&quot;:&quot;yes&quot;,&quot;speed&quot;:500,&quot;image_spacing_custom_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;image_spacing_custom_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]}}\" data-widget_type=\"image-carousel.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-image-carousel-wrapper swiper\" role=\"region\" aria-roledescription=\"carousel\" aria-label=\"Carosello di immagini\" dir=\"rtl\">\n\t\t\t<div class=\"elementor-image-carousel swiper-wrapper swiper-image-stretch\" aria-live=\"off\">\n\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"1 di 11\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image swiper-lazy\" data-src=\"https:\/\/collagensei.com\/wp-content\/uploads\/2025\/04\/Machining-machine-12-768x576.webp\" alt=\"Macchina per la lavorazione (12)\" \/><div class=\"swiper-lazy-preloader\"><\/div><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"2 di 11\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image swiper-lazy\" data-src=\"https:\/\/collagensei.com\/wp-content\/uploads\/2025\/04\/Machining-machine-11-768x576.webp\" alt=\"Macchina per la lavorazione (11)\" \/><div class=\"swiper-lazy-preloader\"><\/div><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"3 di 11\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image swiper-lazy\" data-src=\"https:\/\/collagensei.com\/wp-content\/uploads\/2025\/04\/Machining-machine-10-768x576.webp\" alt=\"Macchina per la lavorazione (10)\" \/><div class=\"swiper-lazy-preloader\"><\/div><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"4 di 11\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image swiper-lazy\" data-src=\"https:\/\/collagensei.com\/wp-content\/uploads\/2025\/04\/Machining-machine-9-768x576.webp\" alt=\"Macchina per la lavorazione (9)\" \/><div class=\"swiper-lazy-preloader\"><\/div><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"5 di 11\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image swiper-lazy\" data-src=\"https:\/\/collagensei.com\/wp-content\/uploads\/2025\/04\/Machining-machine-8-768x576.webp\" alt=\"Macchina per la lavorazione (8)\" \/><div class=\"swiper-lazy-preloader\"><\/div><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"6 di 11\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image swiper-lazy\" data-src=\"https:\/\/collagensei.com\/wp-content\/uploads\/2025\/04\/Machining-machine-7-768x576.webp\" alt=\"Macchina per la lavorazione (7)\" \/><div class=\"swiper-lazy-preloader\"><\/div><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"7 di 11\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image swiper-lazy\" data-src=\"https:\/\/collagensei.com\/wp-content\/uploads\/2025\/04\/Machining-machine-6-768x576.webp\" alt=\"Macchina per la lavorazione (6)\" \/><div class=\"swiper-lazy-preloader\"><\/div><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"8 di 11\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image swiper-lazy\" data-src=\"https:\/\/collagensei.com\/wp-content\/uploads\/2025\/04\/Machining-machine-5-768x576.webp\" alt=\"Macchina per la lavorazione (5)\" \/><div class=\"swiper-lazy-preloader\"><\/div><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"9 di 11\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image swiper-lazy\" data-src=\"https:\/\/collagensei.com\/wp-content\/uploads\/2025\/04\/Machining-machine-4-768x575.webp\" alt=\"Macchina per la lavorazione (4)\" \/><div class=\"swiper-lazy-preloader\"><\/div><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"10 di 11\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image swiper-lazy\" data-src=\"https:\/\/collagensei.com\/wp-content\/uploads\/2025\/04\/Machining-machine-2-768x576.webp\" alt=\"Macchina per la lavorazione (2)\" \/><div class=\"swiper-lazy-preloader\"><\/div><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"11 di 11\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image swiper-lazy\" data-src=\"https:\/\/collagensei.com\/wp-content\/uploads\/2025\/04\/Machining-machine-1-768x576.webp\" alt=\"Macchina per la lavorazione (1)\" \/><div class=\"swiper-lazy-preloader\"><\/div><\/figure><\/div>\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-prev\" role=\"button\" tabindex=\"0\">\n\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-eicon-chevron-left\" viewbox=\"0 0 1000 1000\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M646 125C629 125 613 133 604 142L308 442C296 454 292 471 292 487 292 504 296 521 308 533L604 854C617 867 629 875 646 875 663 875 679 871 692 858 704 846 713 829 713 812 713 796 708 779 692 767L438 487 692 225C700 217 708 204 708 187 708 171 704 154 692 142 675 129 663 125 646 125Z\"><\/path><\/svg>\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-next\" role=\"button\" tabindex=\"0\">\n\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-eicon-chevron-right\" viewbox=\"0 0 1000 1000\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M696 533C708 521 713 504 713 487 713 471 708 454 696 446L400 146C388 133 375 125 354 125 338 125 325 129 313 142 300 154 292 171 292 187 292 204 296 221 308 233L563 492 304 771C292 783 288 800 288 817 288 833 296 850 308 863 321 871 338 875 354 875 371 875 388 867 400 854L696 533Z\"><\/path><\/svg>\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"swiper-pagination\"><\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-420a16ef e-flex e-con-boxed e-con e-parent\" data-id=\"420a16ef\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-700d6a4a elementor-widget elementor-widget-heading\" data-id=\"700d6a4a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Domande frequenti<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-663f5bba uael-faq-box-layout-yes align-at-left elementor-widget elementor-widget-uael-faq\" data-id=\"663f5bba\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"uael-faq.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n\t\t\t<div id='uael-faq-wrapper-171' class=\"uael-faq-wrapper\">\n\t\t\t\t<div class=\"uael-faq-container uael-faq-layout-accordion\" data-layout=\"accordion\" >\n\t\t\t\t\t\t\t\t\t\t\t\t<div id=\"uael-accordion-0ba1907\" class=\"uael-faq-accordion\" role=\"tablist\">\n\t\t\t\t\t\t\t\t<div class= \"uael-accordion-title\" aria-expanded=\"false\" role=\"tab\">\n\t\t\t\t\t\t\t\t\t<span class=\"uael-accordion-icon uael-accordion-icon-left\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"uael-accordion-icon-closed\"><svg class=\"e-font-icon-svg e-fas-angle-right\" viewbox=\"0 0 256 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M224.3 273l-136 136c-9.4 9.4-24.6 9.4-33.9 0l-22.6-22.6c-9.4-9.4-9.4-24.6 0-33.9l96.4-96.4-96.4-96.4c-9.4-9.4-9.4-24.6 0-33.9L54.3 103c9.4-9.4 24.6-9.4 33.9 0l136 136c9.5 9.4 9.5 24.6.1 34z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"uael-accordion-icon-opened\"><svg class=\"e-font-icon-svg e-fas-angle-up\" viewbox=\"0 0 320 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M177 159.7l136 136c9.4 9.4 9.4 24.6 0 33.9l-22.6 22.6c-9.4 9.4-24.6 9.4-33.9 0L160 255.9l-96.4 96.4c-9.4 9.4-24.6 9.4-33.9 0L7 329.7c-9.4-9.4-9.4-24.6 0-33.9l136-136c9.4-9.5 24.6-9.5 34-.1z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"uael-question-0ba1907 uael-question-span\" tabindex=\"0\" id=\"uael-faq-1-6a03dfdf1e3a8\">Che cos'\u00e8 la vitamina A e perch\u00e9 \u00e8 essenziale?<\/span>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"uael-accordion-content\" role=\"tabpanel\">\n\t\t\t\t\t\t\t\t\t<span>\n\t\t\t\t\t\t\t\t\t<span><p>La vitamina A \u00e8 una vitamina liposolubile fondamentale per numerose funzioni corporee. \u00c8 fondamentale per mantenere una visione sana, soprattutto in condizioni di scarsa illuminazione, per sostenere un sistema immunitario robusto, per promuovere la corretta crescita e differenziazione delle cellule e per mantenere sane la pelle e le membrane mucose.<\/p><\/span>\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div id=\"uael-accordion-627103d\" class=\"uael-faq-accordion\" role=\"tablist\">\n\t\t\t\t\t\t\t\t<div class= \"uael-accordion-title\" aria-expanded=\"false\" role=\"tab\">\n\t\t\t\t\t\t\t\t\t<span class=\"uael-accordion-icon uael-accordion-icon-left\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"uael-accordion-icon-closed\"><svg class=\"e-font-icon-svg e-fas-angle-right\" viewbox=\"0 0 256 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M224.3 273l-136 136c-9.4 9.4-24.6 9.4-33.9 0l-22.6-22.6c-9.4-9.4-9.4-24.6 0-33.9l96.4-96.4-96.4-96.4c-9.4-9.4-9.4-24.6 0-33.9L54.3 103c9.4-9.4 24.6-9.4 33.9 0l136 136c9.5 9.4 9.5 24.6.1 34z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"uael-accordion-icon-opened\"><svg class=\"e-font-icon-svg e-fas-angle-up\" viewbox=\"0 0 320 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M177 159.7l136 136c9.4 9.4 9.4 24.6 0 33.9l-22.6 22.6c-9.4 9.4-24.6 9.4-33.9 0L160 255.9l-96.4 96.4c-9.4 9.4-24.6 9.4-33.9 0L7 329.7c-9.4-9.4-9.4-24.6 0-33.9l136-136c9.4-9.5 24.6-9.5 34-.1z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"uael-question-627103d uael-question-span\" tabindex=\"0\" id=\"uael-faq-2-6a03dfdf1e3f7\">Quali sono le diverse forme di vitamina A?<\/span>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"uael-accordion-content\" role=\"tabpanel\">\n\t\t\t\t\t\t\t\t\t<span>\n\t\t\t\t\t\t\t\t\t<span><p data-sourcepos=\"6:5-7:39\">La vitamina A esiste in due forme principali:<\/p><ul data-sourcepos=\"8:5-10:0\"><li data-sourcepos=\"8:5-8:162\"><strong>Vitamina A preformata (retinoidi):<\/strong> Si trova nei prodotti animali come carne, pesce, pollame e latticini. I tipi pi\u00f9 comuni sono il retinolo, il retinale e l'acido retinoico.<\/li><li data-sourcepos=\"9:5-10:0\"><strong>Carotenoidi della Provitamina A:<\/strong> Si trovano negli alimenti di origine vegetale, in particolare nel betacarotene. L'organismo converte questi carotenoidi in vitamina A attiva.<\/li><\/ul><\/span>\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div id=\"uael-accordion-0dff69b\" class=\"uael-faq-accordion\" role=\"tablist\">\n\t\t\t\t\t\t\t\t<div class= \"uael-accordion-title\" aria-expanded=\"false\" role=\"tab\">\n\t\t\t\t\t\t\t\t\t<span class=\"uael-accordion-icon uael-accordion-icon-left\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"uael-accordion-icon-closed\"><svg class=\"e-font-icon-svg e-fas-angle-right\" viewbox=\"0 0 256 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M224.3 273l-136 136c-9.4 9.4-24.6 9.4-33.9 0l-22.6-22.6c-9.4-9.4-9.4-24.6 0-33.9l96.4-96.4-96.4-96.4c-9.4-9.4-9.4-24.6 0-33.9L54.3 103c9.4-9.4 24.6-9.4 33.9 0l136 136c9.5 9.4 9.5 24.6.1 34z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"uael-accordion-icon-opened\"><svg class=\"e-font-icon-svg e-fas-angle-up\" viewbox=\"0 0 320 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M177 159.7l136 136c9.4 9.4 9.4 24.6 0 33.9l-22.6 22.6c-9.4 9.4-24.6 9.4-33.9 0L160 255.9l-96.4 96.4c-9.4 9.4-24.6 9.4-33.9 0L7 329.7c-9.4-9.4-9.4-24.6 0-33.9l136-136c9.4-9.5 24.6-9.5 34-.1z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"uael-question-0dff69b uael-question-span\" tabindex=\"0\" id=\"uael-faq-3-6a03dfdf1e422\">Quali sono le buone fonti alimentari di vitamina A?<\/span>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"uael-accordion-content\" role=\"tabpanel\">\n\t\t\t\t\t\t\t\t\t<span>\n\t\t\t\t\t\t\t\t\t<span><p>Ricche fonti di vitamina A preformata sono il fegato di manzo, l'olio di fegato di merluzzo, le uova e i prodotti caseari. I carotenoidi della provitamina A sono abbondanti in frutta e verdura colorata come carote, patate dolci, spinaci, cavolo, mango e melone.<\/p><\/span>\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div id=\"uael-accordion-a1c1719\" class=\"uael-faq-accordion\" role=\"tablist\">\n\t\t\t\t\t\t\t\t<div class= \"uael-accordion-title\" aria-expanded=\"false\" role=\"tab\">\n\t\t\t\t\t\t\t\t\t<span class=\"uael-accordion-icon uael-accordion-icon-left\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"uael-accordion-icon-closed\"><svg class=\"e-font-icon-svg e-fas-angle-right\" viewbox=\"0 0 256 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M224.3 273l-136 136c-9.4 9.4-24.6 9.4-33.9 0l-22.6-22.6c-9.4-9.4-9.4-24.6 0-33.9l96.4-96.4-96.4-96.4c-9.4-9.4-9.4-24.6 0-33.9L54.3 103c9.4-9.4 24.6-9.4 33.9 0l136 136c9.5 9.4 9.5 24.6.1 34z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"uael-accordion-icon-opened\"><svg class=\"e-font-icon-svg e-fas-angle-up\" viewbox=\"0 0 320 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M177 159.7l136 136c9.4 9.4 9.4 24.6 0 33.9l-22.6 22.6c-9.4 9.4-24.6 9.4-33.9 0L160 255.9l-96.4 96.4c-9.4 9.4-24.6 9.4-33.9 0L7 329.7c-9.4-9.4-9.4-24.6 0-33.9l136-136c9.4-9.5 24.6-9.5 34-.1z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"uael-question-a1c1719 uael-question-span\" tabindex=\"0\" id=\"uael-faq-4-6a03dfdf1e449\">Quali sono i sintomi della carenza di vitamina A?<\/span>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"uael-accordion-content\" role=\"tabpanel\">\n\t\t\t\t\t\t\t\t\t<span>\n\t\t\t\t\t\t\t\t\t<span><p>La carenza di vitamina A pu\u00f2 portare a diversi problemi di salute, soprattutto per quanto riguarda la vista. I sintomi pi\u00f9 comuni includono cecit\u00e0 notturna (difficolt\u00e0 a vedere con poca luce), secchezza oculare (xeroftalmia) e, nei casi pi\u00f9 gravi, danni irreversibili alla cornea e cecit\u00e0. Pu\u00f2 anche indebolire il sistema immunitario, portando a infezioni pi\u00f9 frequenti, e causare pelle secca e squamosa.<\/p><\/span>\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div id=\"uael-accordion-0f85874\" class=\"uael-faq-accordion\" role=\"tablist\">\n\t\t\t\t\t\t\t\t<div class= \"uael-accordion-title\" aria-expanded=\"false\" role=\"tab\">\n\t\t\t\t\t\t\t\t\t<span class=\"uael-accordion-icon uael-accordion-icon-left\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"uael-accordion-icon-closed\"><svg class=\"e-font-icon-svg e-fas-angle-right\" viewbox=\"0 0 256 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M224.3 273l-136 136c-9.4 9.4-24.6 9.4-33.9 0l-22.6-22.6c-9.4-9.4-9.4-24.6 0-33.9l96.4-96.4-96.4-96.4c-9.4-9.4-9.4-24.6 0-33.9L54.3 103c9.4-9.4 24.6-9.4 33.9 0l136 136c9.5 9.4 9.5 24.6.1 34z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"uael-accordion-icon-opened\"><svg class=\"e-font-icon-svg e-fas-angle-up\" viewbox=\"0 0 320 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M177 159.7l136 136c9.4 9.4 9.4 24.6 0 33.9l-22.6 22.6c-9.4 9.4-24.6 9.4-33.9 0L160 255.9l-96.4 96.4c-9.4 9.4-24.6 9.4-33.9 0L7 329.7c-9.4-9.4-9.4-24.6 0-33.9l136-136c9.4-9.5 24.6-9.5 34-.1z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"uael-question-0f85874 uael-question-span\" tabindex=\"0\" id=\"uael-faq-5-6a03dfdf1e46f\">Si pu\u00f2 assumere troppa vitamina A? Quali sono i rischi di tossicit\u00e0?<\/span>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"uael-accordion-content\" role=\"tabpanel\">\n\t\t\t\t\t\t\t\t\t<span>\n\t\t\t\t\t\t\t\t\t<span><p>S\u00ec, l'assunzione eccessiva di vitamina A preformata (di solito da integratori ad alto dosaggio, non dalla dieta) pu\u00f2 essere dannosa, poich\u00e9 \u00e8 liposolubile e viene immagazzinata nell'organismo. I sintomi della tossicit\u00e0 della vitamina A possono includere mal di testa, nausea, vertigini, visione offuscata, perdita di capelli, pelle secca, dolori articolari e ossei e, nei casi pi\u00f9 gravi, danni al fegato o difetti alla nascita se assunta in dosi molto elevate durante la gravidanza. I carotenoidi della provitamina A (provenienti da alimenti vegetali) in genere non causano tossicit\u00e0.<\/p><\/span>\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div id=\"uael-accordion-df25cae\" class=\"uael-faq-accordion\" role=\"tablist\">\n\t\t\t\t\t\t\t\t<div class= \"uael-accordion-title\" aria-expanded=\"false\" role=\"tab\">\n\t\t\t\t\t\t\t\t\t<span class=\"uael-accordion-icon uael-accordion-icon-left\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"uael-accordion-icon-closed\"><svg class=\"e-font-icon-svg e-fas-angle-right\" viewbox=\"0 0 256 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M224.3 273l-136 136c-9.4 9.4-24.6 9.4-33.9 0l-22.6-22.6c-9.4-9.4-9.4-24.6 0-33.9l96.4-96.4-96.4-96.4c-9.4-9.4-9.4-24.6 0-33.9L54.3 103c9.4-9.4 24.6-9.4 33.9 0l136 136c9.5 9.4 9.5 24.6.1 34z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"uael-accordion-icon-opened\"><svg class=\"e-font-icon-svg e-fas-angle-up\" viewbox=\"0 0 320 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M177 159.7l136 136c9.4 9.4 9.4 24.6 0 33.9l-22.6 22.6c-9.4 9.4-24.6 9.4-33.9 0L160 255.9l-96.4 96.4c-9.4 9.4-24.6 9.4-33.9 0L7 329.7c-9.4-9.4-9.4-24.6 0-33.9l136-136c9.4-9.5 24.6-9.5 34-.1z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"uael-question-df25cae uael-question-span\" tabindex=\"0\" id=\"uael-faq-6-6a03dfdf1e493\">Di quanta vitamina A ho bisogno ogni giorno?<\/span>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"uael-accordion-content\" role=\"tabpanel\">\n\t\t\t\t\t\t\t\t\t<span>\n\t\t\t\t\t\t\t\t\t<span><p>La dose dietetica raccomandata (RDA) di vitamina A varia a seconda dell'et\u00e0, del sesso e della fase della vita. Per gli uomini adulti \u00e8 in genere di circa 900 microgrammi (mcg) RAE (Retinol Activity Equivalents) al giorno, mentre per le donne adulte \u00e8 di circa 700 mcg RAE al giorno. Il fabbisogno aumenta leggermente durante la gravidanza e l'allattamento.<\/p><\/span>\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div id=\"uael-accordion-f2eb4e4\" class=\"uael-faq-accordion\" role=\"tablist\">\n\t\t\t\t\t\t\t\t<div class= \"uael-accordion-title\" aria-expanded=\"false\" role=\"tab\">\n\t\t\t\t\t\t\t\t\t<span class=\"uael-accordion-icon uael-accordion-icon-left\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"uael-accordion-icon-closed\"><svg class=\"e-font-icon-svg e-fas-angle-right\" viewbox=\"0 0 256 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M224.3 273l-136 136c-9.4 9.4-24.6 9.4-33.9 0l-22.6-22.6c-9.4-9.4-9.4-24.6 0-33.9l96.4-96.4-96.4-96.4c-9.4-9.4-9.4-24.6 0-33.9L54.3 103c9.4-9.4 24.6-9.4 33.9 0l136 136c9.5 9.4 9.5 24.6.1 34z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"uael-accordion-icon-opened\"><svg class=\"e-font-icon-svg e-fas-angle-up\" viewbox=\"0 0 320 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M177 159.7l136 136c9.4 9.4 9.4 24.6 0 33.9l-22.6 22.6c-9.4 9.4-24.6 9.4-33.9 0L160 255.9l-96.4 96.4c-9.4 9.4-24.6 9.4-33.9 0L7 329.7c-9.4-9.4-9.4-24.6 0-33.9l136-136c9.4-9.5 24.6-9.5 34-.1z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"uael-question-f2eb4e4 uael-question-span\" tabindex=\"0\" id=\"uael-faq-7-6a03dfdf1e4b7\">La vitamina A \u00e8 utile per la salute della pelle?<\/span>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"uael-accordion-content\" role=\"tabpanel\">\n\t\t\t\t\t\t\t\t\t<span>\n\t\t\t\t\t\t\t\t\t<span><p>S\u00ec, la vitamina A e i suoi derivati (retinoidi come il retinolo e l'acido retinoico) sono ampiamente utilizzati nella cura della pelle. Favoriscono il ricambio cellulare, contribuendo a migliorare la texture della pelle, a ridurre le linee sottili e le rughe e a trattare l'acne. Tuttavia, i retinoidi topici possono rendere la pelle pi\u00f9 sensibile al sole.<\/p><\/span>\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div id=\"uael-accordion-0c98e44\" class=\"uael-faq-accordion\" role=\"tablist\">\n\t\t\t\t\t\t\t\t<div class= \"uael-accordion-title\" aria-expanded=\"false\" role=\"tab\">\n\t\t\t\t\t\t\t\t\t<span class=\"uael-accordion-icon uael-accordion-icon-left\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"uael-accordion-icon-closed\"><svg class=\"e-font-icon-svg e-fas-angle-right\" viewbox=\"0 0 256 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M224.3 273l-136 136c-9.4 9.4-24.6 9.4-33.9 0l-22.6-22.6c-9.4-9.4-9.4-24.6 0-33.9l96.4-96.4-96.4-96.4c-9.4-9.4-9.4-24.6 0-33.9L54.3 103c9.4-9.4 24.6-9.4 33.9 0l136 136c9.5 9.4 9.5 24.6.1 34z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"uael-accordion-icon-opened\"><svg class=\"e-font-icon-svg e-fas-angle-up\" viewbox=\"0 0 320 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M177 159.7l136 136c9.4 9.4 9.4 24.6 0 33.9l-22.6 22.6c-9.4 9.4-24.6 9.4-33.9 0L160 255.9l-96.4 96.4c-9.4 9.4-24.6 9.4-33.9 0L7 329.7c-9.4-9.4-9.4-24.6 0-33.9l136-136c9.4-9.5 24.6-9.5 34-.1z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"uael-question-0c98e44 uael-question-span\" tabindex=\"0\" id=\"uael-faq-8-6a03dfdf1e4dc\">La vitamina A influisce sul sistema immunitario?<\/span>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"uael-accordion-content\" role=\"tabpanel\">\n\t\t\t\t\t\t\t\t\t<span>\n\t\t\t\t\t\t\t\t\t<span><p>Assolutamente s\u00ec. La vitamina A svolge un ruolo fondamentale nel mantenimento di un sistema immunitario sano. Sostiene lo sviluppo e la funzione di varie cellule immunitarie, aiutando l'organismo a combattere le infezioni e a regolare le risposte infiammatorie.<\/p><\/span>\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div id=\"uael-accordion-66085b3\" class=\"uael-faq-accordion\" role=\"tablist\">\n\t\t\t\t\t\t\t\t<div class= \"uael-accordion-title\" aria-expanded=\"false\" role=\"tab\">\n\t\t\t\t\t\t\t\t\t<span class=\"uael-accordion-icon uael-accordion-icon-left\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"uael-accordion-icon-closed\"><svg class=\"e-font-icon-svg e-fas-angle-right\" viewbox=\"0 0 256 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M224.3 273l-136 136c-9.4 9.4-24.6 9.4-33.9 0l-22.6-22.6c-9.4-9.4-9.4-24.6 0-33.9l96.4-96.4-96.4-96.4c-9.4-9.4-9.4-24.6 0-33.9L54.3 103c9.4-9.4 24.6-9.4 33.9 0l136 136c9.5 9.4 9.5 24.6.1 34z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"uael-accordion-icon-opened\"><svg class=\"e-font-icon-svg e-fas-angle-up\" viewbox=\"0 0 320 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M177 159.7l136 136c9.4 9.4 9.4 24.6 0 33.9l-22.6 22.6c-9.4 9.4-24.6 9.4-33.9 0L160 255.9l-96.4 96.4c-9.4 9.4-24.6 9.4-33.9 0L7 329.7c-9.4-9.4-9.4-24.6 0-33.9l136-136c9.4-9.5 24.6-9.5 34-.1z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"uael-question-66085b3 uael-question-span\" tabindex=\"0\" id=\"uael-faq-9-6a03dfdf1e4ff\">Devo assumere integratori di vitamina A?<\/span>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"uael-accordion-content\" role=\"tabpanel\">\n\t\t\t\t\t\t\t\t\t<span>\n\t\t\t\t\t\t\t\t\t<span><p>La maggior parte delle persone che seguono una dieta equilibrata, ricca di frutta, verdura e prodotti animali, \u00e8 in grado di assumere una quantit\u00e0 sufficiente di vitamina A dagli alimenti. Gli integratori possono essere consigliati a persone con carenze specifiche o problemi di malassorbimento, ma \u00e8 fondamentale consultare un medico prima di assumere integratori di vitamina A ad alte dosi, a causa del rischio di tossicit\u00e0.<\/p><\/span>\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div id=\"uael-accordion-4cb1511\" class=\"uael-faq-accordion\" role=\"tablist\">\n\t\t\t\t\t\t\t\t<div class= \"uael-accordion-title\" aria-expanded=\"false\" role=\"tab\">\n\t\t\t\t\t\t\t\t\t<span class=\"uael-accordion-icon uael-accordion-icon-left\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"uael-accordion-icon-closed\"><svg class=\"e-font-icon-svg e-fas-angle-right\" viewbox=\"0 0 256 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M224.3 273l-136 136c-9.4 9.4-24.6 9.4-33.9 0l-22.6-22.6c-9.4-9.4-9.4-24.6 0-33.9l96.4-96.4-96.4-96.4c-9.4-9.4-9.4-24.6 0-33.9L54.3 103c9.4-9.4 24.6-9.4 33.9 0l136 136c9.5 9.4 9.5 24.6.1 34z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"uael-accordion-icon-opened\"><svg class=\"e-font-icon-svg e-fas-angle-up\" viewbox=\"0 0 320 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M177 159.7l136 136c9.4 9.4 9.4 24.6 0 33.9l-22.6 22.6c-9.4 9.4-24.6 9.4-33.9 0L160 255.9l-96.4 96.4c-9.4 9.4-24.6 9.4-33.9 0L7 329.7c-9.4-9.4-9.4-24.6 0-33.9l136-136c9.4-9.5 24.6-9.5 34-.1z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"uael-question-4cb1511 uael-question-span\" tabindex=\"0\" id=\"uael-faq-10-6a03dfdf1e522\">Esistono interazioni tra la vitamina A e i farmaci?<\/span>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"uael-accordion-content\" role=\"tabpanel\">\n\t\t\t\t\t\t\t\t\t<span>\n\t\t\t\t\t\t\t\t\t<span><p>S\u00ec, dosi elevate di integratori di vitamina A possono interagire con alcuni farmaci. Ad esempio, alcuni farmaci per la perdita di peso possono diminuire l'assorbimento della vitamina A, mentre alcuni farmaci per la psoriasi o il linfoma, che sono derivati della vitamina A, possono portare a livelli pericolosamente elevati di vitamina A se assunti in concomitanza con gli integratori. Discutete sempre con il vostro medico l'assunzione di integratori.<\/p><\/span>\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-31114bbb e-flex e-con-boxed e-con e-parent\" data-id=\"31114bbb\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-6b4ba34 e-con-full e-flex e-con e-child\" data-id=\"6b4ba34\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-26be6cbf elementor-widget elementor-widget-heading\" data-id=\"26be6cbf\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Affidata da molti, pronta per voi: Leggi le testimonianze e chiedi subito informazioni<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-731db220 e-con-full e-flex e-con e-child\" data-id=\"731db220\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-25a7e817 e-con-full e-flex e-con e-child\" data-id=\"25a7e817\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-6d49d592 elementor-testimonial--skin-default elementor-testimonial--layout-image_inline elementor-testimonial--align-center elementor-arrows-yes elementor-pagination-type-bullets elementor-widget elementor-widget-testimonial-carousel\" data-id=\"6d49d592\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;show_arrows&quot;:&quot;yes&quot;,&quot;pagination&quot;:&quot;bullets&quot;,&quot;speed&quot;:500,&quot;autoplay&quot;:&quot;yes&quot;,&quot;autoplay_speed&quot;:5000,&quot;loop&quot;:&quot;yes&quot;,&quot;pause_on_hover&quot;:&quot;yes&quot;,&quot;pause_on_interaction&quot;:&quot;yes&quot;,&quot;space_between&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:10,&quot;sizes&quot;:[]},&quot;space_between_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:10,&quot;sizes&quot;:[]},&quot;space_between_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:10,&quot;sizes&quot;:[]}}\" data-widget_type=\"testimonial-carousel.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper\">\n\t\t\t\t\t<div class=\"elementor-main-swiper swiper\" role=\"region\" aria-roledescription=\"carousel\" aria-label=\"Diapositive\">\n\t\t\t\t<div class=\"swiper-wrapper\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-testimonial\">\n\t\t\t\t\t\t\t<div class=\"elementor-testimonial__content\">\n\t\t\t\t\t<div class=\"elementor-testimonial__text\">\n\t\t\t\t\t\tGensei ha rivoluzionato lo sviluppo dei nostri prodotti con la sua eccezionale vitamina A in polvere. In qualit\u00e0 di produttore leader di vitamina A, la sua consistenza \u00e8 ineguagliabile. Ci affidiamo alla loro vitamina A all'ingrosso per i nostri ordini all'ingrosso e la purezza della loro vitamina A in polvere \u00e8 sempre superiore. Si integra perfettamente nei nostri integratori per il supporto della vista, migliorandone l'efficacia. Il team di Gensei \u00e8 incredibilmente di supporto e fornisce tutta la documentazione e gli approfondimenti tecnici necessari. Siamo orgogliosi di collaborare con un fornitore che garantisce una qualit\u00e0 cos\u00ec elevata per un ingrediente vitale come la vitamina A\".\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"elementor-testimonial__footer\">\n\t\t\t\t\t\t\t\t<cite class=\"elementor-testimonial__cite\"><span class=\"elementor-testimonial__name\">Ben Carter<\/span><span class=\"elementor-testimonial__title\">Direttore R&amp;S, Laboratori Vision Health<\/span><\/cite>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-testimonial\">\n\t\t\t\t\t\t\t<div class=\"elementor-testimonial__content\">\n\t\t\t\t\t<div class=\"elementor-testimonial__text\">\n\t\t\t\t\t\tPer la nostra linea di trattamenti avanzati, la qualit\u00e0 della vitamina A \u00e8 fondamentale. La polvere di Vitamina A di Gensei ha superato le nostre aspettative. In quanto produttore affidabile di vitamina A, il loro prodotto \u00e8 costantemente puro e stabile, fondamentale per le nostre formulazioni cosmetiche sensibili. Apprezziamo le loro opzioni di vendita all'ingrosso di vitamina A, che consentono di soddisfare i nostri volumi di produzione. La consistenza fine della polvere di vitamina A assicura un'eccellente dispersione nelle nostre creme. Gensei ci aiuta a fornire soluzioni anti-invecchiamento altamente efficaci ai nostri clienti, rendendoli un fornitore indispensabile.\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"elementor-testimonial__footer\">\n\t\t\t\t\t\t\t\t<cite class=\"elementor-testimonial__cite\"><span class=\"elementor-testimonial__name\">Dr. Sarah Kim<\/span><span class=\"elementor-testimonial__title\">Capo formulatore, DermaYouth Cosmeceuticals<\/span><\/cite>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-testimonial\">\n\t\t\t\t\t\t\t<div class=\"elementor-testimonial__content\">\n\t\t\t\t\t<div class=\"elementor-testimonial__text\">\n\t\t\t\t\t\tGensei \u00e8 il nostro punto di riferimento per l'arricchimento della vitamina A. In qualit\u00e0 di importante produttore di vitamina A, fornisce un'eccezionale polvere di vitamina A che si integra perfettamente nei nostri prodotti alimentari. Il loro servizio di vendita all'ingrosso di vitamina A \u00e8 efficiente e ci garantisce sempre una quantit\u00e0 di vitamina A in polvere sufficiente a soddisfare la domanda. La qualit\u00e0 e la purezza sono sempre costanti, il che \u00e8 essenziale per mantenere le indicazioni nutrizionali dei nostri prodotti e la fiducia dei consumatori. Abbiamo trovato in Gensei un partner altamente affidabile e professionale, che ha contribuito in modo significativo alle nostre iniziative di alimenti fortificati\".\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"elementor-testimonial__footer\">\n\t\t\t\t\t\t\t\t<cite class=\"elementor-testimonial__cite\"><span class=\"elementor-testimonial__name\">Michael Green<\/span><span class=\"elementor-testimonial__title\">Specialista dell'approvvigionamento, alimenti NutriFortify<\/span><\/cite>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-prev\" role=\"button\" tabindex=\"0\" aria-label=\"Precedente\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-eicon-chevron-left\" viewbox=\"0 0 1000 1000\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M646 125C629 125 613 133 604 142L308 442C296 454 292 471 292 487 292 504 296 521 308 533L604 854C617 867 629 875 646 875 663 875 679 871 692 858 704 846 713 829 713 812 713 796 708 779 692 767L438 487 692 225C700 217 708 204 708 187 708 171 704 154 692 142 675 129 663 125 646 125Z\"><\/path><\/svg>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-next\" role=\"button\" tabindex=\"0\" aria-label=\"Avanti\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-eicon-chevron-right\" viewbox=\"0 0 1000 1000\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M696 533C708 521 713 504 713 487 713 471 708 454 696 446L400 146C388 133 375 125 354 125 338 125 325 129 313 142 300 154 292 171 292 187 292 204 296 221 308 233L563 492 304 771C292 783 288 800 288 817 288 833 296 850 308 863 321 871 338 875 354 875 371 875 388 867 400 854L696 533Z\"><\/path><\/svg>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-pagination\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-5a1caa76 e-con-full e-flex e-con e-child\" data-id=\"5a1caa76\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-5a85cb39 uael-cf7-btn-size-xs uael-cf7-style-box uael-cf7-input-size-sm uael-cf7-button-left uael-cf7-highlight-style-default elementor-widget elementor-widget-uael-cf7-styler\" data-id=\"5a85cb39\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"uael-cf7-styler.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class = \"uael-cf7-container\">\n\t\t\t\t\t\t<div class = \"uael-cf7 uael-cf7-style elementor-clickable\">\n\t\t\t\t\t\t\n<div class=\"wpcf7 no-js\" id=\"wpcf7-f74-o1\" lang=\"zh-CN\" dir=\"ltr\" data-wpcf7-id=\"74\">\n<div class=\"screen-reader-response\"><p role=\"status\" aria-live=\"polite\" aria-atomic=\"true\"><\/p> <ul><\/ul><\/div>\n<form action=\"\/it\/wp-json\/wp\/v2\/pages\/4861#wpcf7-f74-o1\" method=\"post\" class=\"wpcf7-form init\" aria-label=\"\u7559\u8a00\u8868\u5355\" novalidate=\"novalidate\" data-status=\"init\" data-trp-original-action=\"\/it\/wp-json\/wp\/v2\/pages\/4861#wpcf7-f74-o1\">\n<fieldset class=\"hidden-fields-container\"><input type=\"hidden\" name=\"_wpcf7\" value=\"74\" \/><input type=\"hidden\" name=\"_wpcf7_version\" value=\"6.1.5\" \/><input type=\"hidden\" name=\"_wpcf7_locale\" value=\"zh_CN\" \/><input type=\"hidden\" name=\"_wpcf7_unit_tag\" value=\"wpcf7-f74-o1\" \/><input type=\"hidden\" name=\"_wpcf7_container_post\" value=\"0\" \/><input type=\"hidden\" name=\"_wpcf7_posted_data_hash\" value=\"\" \/>\n<\/fieldset>\n<div class=\"stay-touch\">\n\t<ul>\n\t\t<li>\n\t\t\t<p><label> Nome: <span class=\"wpcf7-form-control-wrap\" data-name=\"your-name\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"text\" name=\"your-name\" \/><\/span><\/label>\n\t\t\t<\/p>\n\t\t<\/li>\n\t\t<li>\n\t\t\t<p><label> Nome della societ\u00e0: <span class=\"wpcf7-form-control-wrap\" data-name=\"your-company\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"text\" name=\"your-company\" \/><\/span><\/label>\n\t\t\t<\/p>\n\t\t<\/li>\n\t\t<li>\n\t\t\t<p><label> E-mail: <span class=\"wpcf7-form-control-wrap\" data-name=\"your-email\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"text\" name=\"your-email\" \/><\/span><\/label>\n\t\t\t<\/p>\n\t\t<\/li>\n\t\t<li>\n\t\t\t<p><label> Tel: <span class=\"wpcf7-form-control-wrap\" data-name=\"your-tel\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"text\" name=\"your-tel\" \/><\/span><\/label>\n\t\t\t<\/p>\n\t\t<\/li>\n\t\t<li>\n\t\t\t<p><label> Messaggio: <span class=\"wpcf7-form-control-wrap\" data-name=\"your-message\"><textarea cols=\"40\" rows=\"10\" maxlength=\"2000\" class=\"wpcf7-form-control wpcf7-textarea wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" name=\"your-message\"><\/textarea><\/span><\/label>\n\t\t\t<\/p>\n\t\t<\/li>\n\t\t<li style=\"text-align:center\">\n\t\t\t<p><input class=\"wpcf7-form-control wpcf7-submit has-spinner\" type=\"submit\" value=\"INVIO\" \/>\n\t\t\t<\/p>\n\t\t<\/li>\n\t<\/ul>\n<\/div><div class=\"wpcf7-response-output\" aria-hidden=\"true\"><\/div>\n<input type=\"hidden\" name=\"trp-form-language\" value=\"it\"\/><\/form>\n<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>Vitamin A raw material manufacturer Vitamin A is a fat-soluble vitamin crucial for maintaining healthy vision, immune function, and cell [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":4842,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_uag_custom_page_level_css":"","site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"class_list":["post-4861","page","type-page","status-publish","hentry"],"uagb_featured_image_src":{"full":false,"thumbnail":false,"medium":false,"medium_large":false,"large":false,"1536x1536":false,"2048x2048":false,"trp-custom-language-flag":false},"uagb_author_info":{"display_name":"collagensei.com","author_link":"https:\/\/collagensei.com\/it\/author\/collagensei\/"},"uagb_comment_info":0,"uagb_excerpt":"Vitamin A raw material manufacturer Vitamin A is a fat-soluble vitamin crucial for maintaining healthy vision, immune function, and cell [&hellip;]","_links":{"self":[{"href":"https:\/\/collagensei.com\/it\/wp-json\/wp\/v2\/pages\/4861","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/collagensei.com\/it\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/collagensei.com\/it\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/collagensei.com\/it\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/collagensei.com\/it\/wp-json\/wp\/v2\/comments?post=4861"}],"version-history":[{"count":5,"href":"https:\/\/collagensei.com\/it\/wp-json\/wp\/v2\/pages\/4861\/revisions"}],"predecessor-version":[{"id":14566,"href":"https:\/\/collagensei.com\/it\/wp-json\/wp\/v2\/pages\/4861\/revisions\/14566"}],"up":[{"embeddable":true,"href":"https:\/\/collagensei.com\/it\/wp-json\/wp\/v2\/pages\/4842"}],"wp:attachment":[{"href":"https:\/\/collagensei.com\/it\/wp-json\/wp\/v2\/media?parent=4861"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}