{"id":4884,"date":"2025-03-21T10:51:13","date_gmt":"2025-03-21T02:51:13","guid":{"rendered":"https:\/\/collagensei.com\/?page_id=4884"},"modified":"2026-03-18T13:50:08","modified_gmt":"2026-03-18T05:50:08","slug":"fornitore-di-estratti-di-erbe","status":"publish","type":"page","link":"https:\/\/collagensei.com\/it\/herb-extracts-supplier\/","title":{"rendered":"Fornitore di estratti di erbe"},"content":{"rendered":"<div data-elementor-type=\"wp-page\" data-elementor-id=\"4884\" class=\"elementor elementor-4884\" data-elementor-post-type=\"page\">\n\t\t\t\t<div class=\"elementor-element elementor-element-1b0a9f45 e-flex e-con-boxed e-con e-parent\" data-id=\"1b0a9f45\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-6148c395 elementor-widget elementor-widget-heading\" data-id=\"6148c395\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">fornitore di estratti di erbe<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-389ff8b1 elementor-widget elementor-widget-text-editor\" data-id=\"389ff8b1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p dir=\"auto\">In qualit\u00e0 di fornitore leader di estratti di erbe e distributore di estratti di erbe cinesi, siamo specializzati nella fornitura di estratti botanici naturali di alta qualit\u00e0 per soddisfare le diverse esigenze di settori come quello nutraceutico, farmaceutico e cosmetico.<\/p><div id=\"ez-toc-container\" class=\"ez-toc-v2_0_83 ez-toc-wrap-left counter-hierarchy ez-toc-counter ez-toc-grey ez-toc-container-direction\">\n<div class=\"ez-toc-title-container\">\n<p class=\"ez-toc-title ez-toc-toggle\" style=\"cursor:pointer\">Indice dei contenuti<\/p>\n<span class=\"ez-toc-title-toggle\"><a href=\"#\" class=\"ez-toc-pull-right ez-toc-btn ez-toc-btn-xs ez-toc-btn-default ez-toc-toggle\" aria-label=\"Allinea la tabella dei contenuti\"><span class=\"ez-toc-js-icon-con\"><span class=\"\"><span class=\"eztoc-hide\" style=\"display:none;\">Toggle<\/span><span class=\"ez-toc-icon-toggle-span\"><svg style=\"fill: #999;color:#999\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" class=\"list-377408\" width=\"20px\" height=\"20px\" viewbox=\"0 0 24 24\" fill=\"none\"><path d=\"M6 6H4v2h2V6zm14 0H8v2h12V6zM4 11h2v2H4v-2zm16 0H8v2h12v-2zM4 16h2v2H4v-2zm16 0H8v2h12v-2z\" fill=\"currentColor\"><\/path><\/svg><svg style=\"fill: #999;color:#999\" class=\"arrow-unsorted-368013\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"10px\" height=\"10px\" viewbox=\"0 0 24 24\" version=\"1.2\" baseprofile=\"tiny\"><path d=\"M18.2 9.3l-6.2-6.3-6.2 6.3c-.2.2-.3.4-.3.7s.1.5.3.7c.2.2.4.3.7.3h11c.3 0 .5-.1.7-.3.2-.2.3-.5.3-.7s-.1-.5-.3-.7zM5.8 14.7l6.2 6.3 6.2-6.3c.2-.2.3-.5.3-.7s-.1-.5-.3-.7c-.2-.2-.4-.3-.7-.3h-11c-.3 0-.5.1-.7.3-.2.2-.3.5-.3.7s.1.5.3.7z\"\/><\/svg><\/span><\/span><\/span><\/a><\/span><\/div>\n<nav><ul class='ez-toc-list ez-toc-list-level-1' ><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-1\" href=\"https:\/\/collagensei.com\/it\/ashwagandha-root-powder-vs-extract\/#What_is_Ashwagandha\" >Che cos'\u00e8 l'Ashwagandha?<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-2\" href=\"https:\/\/collagensei.com\/it\/ashwagandha-root-powder-vs-extract\/#The_Difference_Between_Ashwagandha_Root_Powder_and_Extract\" >La differenza tra la polvere e l'estratto di radice di Ashwagandha<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-3\" href=\"https:\/\/collagensei.com\/it\/ashwagandha-root-powder-vs-extract\/#Benefits_of_Ashwagandha_Root_Powder_and_Extract\" >Benefici della polvere e dell'estratto di radice di Ashwagandha<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-4\" href=\"https:\/\/collagensei.com\/it\/ashwagandha-root-powder-vs-extract\/#Ashwagandha_Root_Powder_vs_Extract_Which_One_Should_You_Choose\" >Polvere di radice di Ashwagandha o estratto: quale scegliere?<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-5\" href=\"https:\/\/collagensei.com\/it\/ashwagandha-root-powder-vs-extract\/#How_to_Use_Ashwagandha\" >Come usare l'Ashwagandha<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-6\" href=\"https:\/\/collagensei.com\/it\/ashwagandha-root-powder-vs-extract\/#Safety_and_Side_Effects\" >Sicurezza ed effetti collaterali<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-7\" href=\"https:\/\/collagensei.com\/it\/ashwagandha-root-powder-vs-extract\/#FAQs\" >Domande frequenti<\/a><ul class='ez-toc-list-level-3' ><li class='ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-8\" href=\"https:\/\/collagensei.com\/it\/ashwagandha-root-powder-vs-extract\/#Which_is_the_best_form_of_ashwagandha_to_take\" >Qual \u00e8 la forma migliore di ashwagandha da assumere?<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-9\" href=\"https:\/\/collagensei.com\/it\/ashwagandha-root-powder-vs-extract\/#What_is_the_best_method_of_extraction_for_ashwagandha\" >Qual \u00e8 il metodo di estrazione migliore per l'ashwagandha?<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-10\" href=\"https:\/\/collagensei.com\/it\/ashwagandha-root-powder-vs-extract\/#Is_it_better_to_take_ashwagandha_or_ashwagandha_root\" >\u00c8 meglio assumere l'ashwagandha o la radice di ashwagandha?<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-11\" href=\"https:\/\/collagensei.com\/it\/ashwagandha-root-powder-vs-extract\/#Is_2000_mg_of_ashwagandha_root_extract_too_much\" >2000 mg di estratto di radice di ashwagandha sono troppi?<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-12\" href=\"https:\/\/collagensei.com\/it\/ashwagandha-root-powder-vs-extract\/#Which_is_better_ashwagandha_capsules_or_powder\" >Cosa \u00e8 meglio, capsule di ashwagandha o polvere?<\/a><\/li><\/ul><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-13\" href=\"https:\/\/collagensei.com\/it\/ashwagandha-root-powder-vs-extract\/#Conclusion\" >Conclusione<\/a><\/li><\/ul><\/nav><\/div>\n<p dir=\"auto\">Il nostro ampio portafoglio comprende estratti di erbe tradizionali cinesi come il ginseng, l'astragalo e le bacche di goji, oltre a una vasta gamma di soluzioni moderne a base di erbe, tutte realizzate con tecniche di estrazione avanzate per preservare i composti bioattivi e garantire la massima potenza.<\/p><p dir=\"auto\">Impegnati nella qualit\u00e0 e nella sostenibilit\u00e0, forniamo estratti di erbe all'ingrosso, consentendo alle imprese impegnate in <a href=\"https:\/\/collagensei.com\/it\/produzione-di-integratori-a-base-di-erbe\/\">produzione di integratori a base di erbe<\/a> per creare <a href=\"https:\/\/collagensei.com\/it\/integratori-alimentari-oem\/\">integratori alimentari premium<\/a>, alimenti funzionali e prodotti naturali per la salute.<\/p><p dir=\"auto\">Grazie a strutture all'avanguardia, a rigorosi test di qualit\u00e0 e all'attenzione per gli ingredienti autentici e di provenienza sostenibile, siamo il vostro partner di fiducia per soluzioni innovative e affidabili a base di estratti di erbe che soddisfano gli standard del mercato globale.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-cc07761 e-grid e-con-full e-con e-child\" data-id=\"cc07761\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-e90e3a8 elementor-position-top elementor-widget elementor-widget-image-box\" data-id=\"e90e3a8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><a href=\"https:\/\/collagensei.com\/it\/herb-extracts-supplier\/acerola-powder\/\" tabindex=\"-1\"><img decoding=\"async\" src=\"https:\/\/collagensei.com\/wp-content\/uploads\/elementor\/thumbs\/Acerola-Cherry-Powder-r3txvavwixwczy9od7raiunntiwkto8bpx017vtyic.png\" title=\"Acerola in polvere\" alt=\"Acerola in polvere\" class=\"elementor-animation-grow\" loading=\"lazy\" \/><\/a><\/figure><div class=\"elementor-image-box-content\"><p class=\"elementor-image-box-title\"><a href=\"https:\/\/collagensei.com\/it\/herb-extracts-supplier\/acerola-powder\/\">Acerola in polvere<\/a><\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d4659c7 elementor-position-top elementor-widget elementor-widget-image-box\" data-id=\"d4659c7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><a href=\"https:\/\/collagensei.com\/it\/herb-extracts-supplier\/ashwagandha-extracts-powder\/\" tabindex=\"-1\"><img decoding=\"async\" src=\"https:\/\/collagensei.com\/wp-content\/uploads\/elementor\/thumbs\/Ashwagandha-Extract-Powder-r62gayx6muihr79pmu8isl9av48xz2cxb4cyk2fp4k.webp\" title=\"Estratto di Ashwagandha in polvere\" alt=\"Estratto di Ashwagandha in polvere\" class=\"elementor-animation-grow\" loading=\"lazy\" \/><\/a><\/figure><div class=\"elementor-image-box-content\"><p class=\"elementor-image-box-title\"><a href=\"https:\/\/collagensei.com\/it\/herb-extracts-supplier\/ashwagandha-extracts-powder\/\">estratto di ashwagandha in polvere<\/a><\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0c9703c elementor-position-top elementor-widget elementor-widget-image-box\" data-id=\"0c9703c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><a href=\"https:\/\/collagensei.com\/it\/herb-extracts-supplier\/berberine-hcl-powder\/\" tabindex=\"-1\"><img decoding=\"async\" src=\"https:\/\/collagensei.com\/wp-content\/uploads\/elementor\/thumbs\/Berberine-HCL-r3tv7w9mubamksungz4ifxdd7l5djnh4lp7tmtai2c.png\" title=\"Estratti di erbe\" alt=\"Estratti di erbe\" class=\"elementor-animation-grow\" loading=\"lazy\" \/><\/a><\/figure><div class=\"elementor-image-box-content\"><p class=\"elementor-image-box-title\"><a href=\"https:\/\/collagensei.com\/it\/herb-extracts-supplier\/berberine-hcl-powder\/\">berberina hcl in polvere<\/a><\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-31c3655 elementor-position-top elementor-widget elementor-widget-image-box\" data-id=\"31c3655\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><a href=\"https:\/\/collagensei.com\/it\/herb-extracts-supplier\/curcumin-extract-manufacturer\/\" tabindex=\"-1\"><img decoding=\"async\" src=\"https:\/\/collagensei.com\/wp-content\/uploads\/elementor\/thumbs\/Curcumin1-r3ty41ru4fvf1bkaahvb8572tlsjg9yel7jozkv2lw.png\" title=\"Curcumina1\" alt=\"Curcumina\" class=\"elementor-animation-grow\" loading=\"lazy\" \/><\/a><\/figure><div class=\"elementor-image-box-content\"><p class=\"elementor-image-box-title\"><a href=\"https:\/\/collagensei.com\/it\/herb-extracts-supplier\/curcumin-extract-manufacturer\/\">estratto di curcumina in polvere<\/a><\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-730ed50 elementor-position-top elementor-widget elementor-widget-image-box\" data-id=\"730ed50\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><a href=\"https:\/\/collagensei.com\/it\/herb-extracts-supplier\/flaxseed-powder\/\" tabindex=\"-1\"><img decoding=\"async\" src=\"https:\/\/collagensei.com\/wp-content\/uploads\/elementor\/thumbs\/Flaxseed-Protein-Powder-r3ty5qvcgo71zz3jdqa287s1fnfecloyhly96kchdg.png\" title=\"Semi di lino in polvere\" alt=\"Semi di lino in polvere\" class=\"elementor-animation-grow\" loading=\"lazy\" \/><\/a><\/figure><div class=\"elementor-image-box-content\"><p class=\"elementor-image-box-title\"><a href=\"https:\/\/collagensei.com\/it\/herb-extracts-supplier\/flaxseed-powder\/\">Semi di lino in polvere<\/a><\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-707c097 elementor-position-top elementor-widget elementor-widget-image-box\" data-id=\"707c097\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><a href=\"https:\/\/collagensei.com\/it\/herb-extracts-supplier\/green-tea-extract-supplier\/\" tabindex=\"-1\"><img fetchpriority=\"high\" decoding=\"async\" width=\"744\" height=\"494\" src=\"https:\/\/collagensei.com\/wp-content\/uploads\/2025\/02\/Green-Tea-Extract.png\" class=\"elementor-animation-grow attachment-full size-full wp-image-4529\" alt=\"Fornitore di estratto di t\u00e8 verde\" srcset=\"https:\/\/collagensei.com\/wp-content\/uploads\/2025\/02\/Green-Tea-Extract.png 744w, https:\/\/collagensei.com\/wp-content\/uploads\/2025\/02\/Green-Tea-Extract-300x199.png 300w\" sizes=\"(max-width: 744px) 100vw, 744px\" \/><\/a><\/figure><div class=\"elementor-image-box-content\"><p class=\"elementor-image-box-title\"><a href=\"https:\/\/collagensei.com\/it\/herb-extracts-supplier\/green-tea-extract-supplier\/\">estratto di t\u00e8 verde in polvere<\/a><\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d68c82d elementor-position-top elementor-widget elementor-widget-image-box\" data-id=\"d68c82d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><a href=\"https:\/\/collagensei.com\/it\/herb-extracts-supplier\/vaccinium-myrtillus-fruit-extract\/\" tabindex=\"-1\"><img decoding=\"async\" width=\"768\" height=\"444\" src=\"https:\/\/collagensei.com\/wp-content\/uploads\/2025\/02\/vaccinium-myrtillus-768x444.png\" class=\"elementor-animation-grow attachment-medium_large size-medium_large wp-image-4527\" alt=\"Estratto di frutta di Vaccinium Myrtillus\" srcset=\"https:\/\/collagensei.com\/wp-content\/uploads\/2025\/02\/vaccinium-myrtillus-768x444.png 768w, https:\/\/collagensei.com\/wp-content\/uploads\/2025\/02\/vaccinium-myrtillus-300x174.png 300w, https:\/\/collagensei.com\/wp-content\/uploads\/2025\/02\/vaccinium-myrtillus.png 778w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/><\/a><\/figure><div class=\"elementor-image-box-content\"><p class=\"elementor-image-box-title\"><a href=\"https:\/\/collagensei.com\/it\/herb-extracts-supplier\/vaccinium-myrtillus-fruit-extract\/\">Estratto di frutta di Vaccinium Myrtillus<\/a><\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-f9caa45 e-flex e-con-boxed e-con e-parent\" data-id=\"f9caa45\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-6e40ee7e e-con-full e-flex e-con e-child\" data-id=\"6e40ee7e\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-623f8497 elementor-headline--style-highlight elementor-widget elementor-widget-animated-headline\" data-id=\"623f8497\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;highlighted_text&quot;:&quot;Gensei&quot;,&quot;headline_style&quot;:&quot;highlight&quot;,&quot;marker&quot;:&quot;circle&quot;,&quot;loop&quot;:&quot;yes&quot;,&quot;highlight_animation_duration&quot;:1200,&quot;highlight_iteration_delay&quot;:8000}\" data-widget_type=\"animated-headline.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<h2 class=\"elementor-headline\">\n\t\t\t\t\t<span class=\"elementor-headline-plain-text elementor-headline-text-wrapper\">Perch\u00e9 scegliere <\/span>\n\t\t\t\t<span class=\"elementor-headline-dynamic-wrapper elementor-headline-text-wrapper\">\n\t\t\t\t\t<span class=\"elementor-headline-dynamic-text elementor-headline-text-active\">Gensei<\/span>\n\t\t\t\t<\/span>\n\t\t\t\t\t<span class=\"elementor-headline-plain-text elementor-headline-text-wrapper\">come Vostro fornitore di estratti di erbe?<\/span>\n\t\t\t\t\t<\/h2>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ca6ec10 elementor-widget elementor-widget-text-editor\" data-id=\"ca6ec10\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Quando si tratta di reperire estratti di erbe efficaci e di alta qualit\u00e0, Gensei \u00e8 il vostro partner di fiducia. Offriamo una selezione completa, specializzata in soluzioni botaniche sia tradizionali che innovative, per soddisfare le diverse esigenze della vostra attivit\u00e0.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-1b5d42e1 e-con-full e-flex e-con e-child\" data-id=\"1b5d42e1\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-5c3323a1 elementor-widget elementor-widget-uael-infobox\" data-id=\"5c3323a1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"uael-infobox.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n<div class=\"uael-module-content uael-infobox uael-imgicon-style-normal  uael-infobox-left  infobox-has-icon uael-infobox-icon-left  uael-infobox-image-valign-middle  uael-infobox-stacked-tablet  uael-infobox-link-type-none\">\n\t<div class=\"uael-infobox-left-right-wrap\">\n\t\t\t\t\t\t\t\t<div class=\"uael-module-content uael-imgicon-wrap\">\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"uael-icon-wrap elementor-animation-\">\n\t\t\t\t\t\t\t\t<span class=\"uael-icon\">\n\t\t\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-far-check-circle\" viewbox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M256 8C119.033 8 8 119.033 8 256s111.033 248 248 248 248-111.033 248-248S392.967 8 256 8zm0 48c110.532 0 200 89.451 200 200 0 110.532-89.451 200-200 200-110.532 0-200-89.451-200-200 0-110.532 89.451-200 200-200m140.204 130.267l-22.536-22.718c-4.667-4.705-12.265-4.736-16.97-.068L215.346 303.697l-59.792-60.277c-4.667-4.705-12.265-4.736-16.97-.069l-22.719 22.536c-4.705 4.667-4.736 12.265-.068 16.971l90.781 91.516c4.667 4.705 12.265 4.736 16.97.068l172.589-171.204c4.704-4.668 4.734-12.266.067-16.971z\"><\/path><\/svg>\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"uael-infobox-content\">\n\t\t\t\t\t\t<div class='uael-infobox-title-wrap'><h3 class=\"uael-infobox-title elementor-inline-editing\" data-elementor-setting-key=\"infobox_title\" data-elementor-inline-editing-toolbar=\"basic\" >Ampio assortimento che include erbe cinesi di prima qualit\u00e0<\/h3><\/div>\t\t\t\t\t\t<div class=\"uael-separator-parent\">\n\t\t\t\t<div class=\"uael-separator\"><\/div>\n\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"uael-infobox-text-wrap\">\n\t\t\t\t<div class=\"uael-infobox-text elementor-inline-editing\" data-elementor-setting-key=\"infobox_description\" data-elementor-inline-editing-toolbar=\"advanced\">\n\t\t\t\t\tVantiamo un ampio catalogo che comprende una vasta gamma di estratti di erbe cinesi, provenienti da coltivatori affidabili e lavorati con cura meticolosa per preservarne la potenza naturale. Che siate alla ricerca di ingredienti classici della MTC o di composti specifici, la nostra selezione \u00e8 pensata per soddisfare i vostri standard pi\u00f9 esigenti.\t\t\t\t<\/div>\n\t\t\t\t\t\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t<\/div>\n<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7efbbe57 elementor-widget elementor-widget-uael-infobox\" data-id=\"7efbbe57\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"uael-infobox.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n<div class=\"uael-module-content uael-infobox uael-imgicon-style-normal  uael-infobox-left  infobox-has-icon uael-infobox-icon-left  uael-infobox-image-valign-middle  uael-infobox-stacked-tablet  uael-infobox-link-type-none\">\n\t<div class=\"uael-infobox-left-right-wrap\">\n\t\t\t\t\t\t\t\t<div class=\"uael-module-content uael-imgicon-wrap\">\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"uael-icon-wrap elementor-animation-\">\n\t\t\t\t\t\t\t\t<span class=\"uael-icon\">\n\t\t\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-far-check-circle\" viewbox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M256 8C119.033 8 8 119.033 8 256s111.033 248 248 248 248-111.033 248-248S392.967 8 256 8zm0 48c110.532 0 200 89.451 200 200 0 110.532-89.451 200-200 200-110.532 0-200-89.451-200-200 0-110.532 89.451-200 200-200m140.204 130.267l-22.536-22.718c-4.667-4.705-12.265-4.736-16.97-.068L215.346 303.697l-59.792-60.277c-4.667-4.705-12.265-4.736-16.97-.069l-22.719 22.536c-4.705 4.667-4.736 12.265-.068 16.971l90.781 91.516c4.667 4.705 12.265 4.736 16.97.068l172.589-171.204c4.704-4.668 4.734-12.266.067-16.971z\"><\/path><\/svg>\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"uael-infobox-content\">\n\t\t\t\t\t\t<div class='uael-infobox-title-wrap'><h3 class=\"uael-infobox-title elementor-inline-editing\" data-elementor-setting-key=\"infobox_title\" data-elementor-inline-editing-toolbar=\"basic\" >Opzioni di estratto di tisane cinesi specializzate<\/h3><\/div>\t\t\t\t\t\t<div class=\"uael-separator-parent\">\n\t\t\t\t<div class=\"uael-separator\"><\/div>\n\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"uael-infobox-text-wrap\">\n\t\t\t\t<div class=\"uael-infobox-text elementor-inline-editing\" data-elementor-setting-key=\"infobox_description\" data-elementor-inline-editing-toolbar=\"advanced\">\n\t\t\t\t\tRispondete alla crescente domanda di bevande salutari con i nostri estratti di t\u00e8 alle erbe cinesi di alta qualit\u00e0. Questi estratti sono ideali per la formulazione di t\u00e8 istantanei, integratori alimentari e alimenti funzionali, offrendo convenienza ed efficacia ai vostri clienti.\t\t\t\t<\/div>\n\t\t\t\t\t\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t<\/div>\n<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-4c49633d e-con-full e-flex e-con e-child\" data-id=\"4c49633d\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-411cbd31 elementor-widget elementor-widget-uael-infobox\" data-id=\"411cbd31\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"uael-infobox.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n<div class=\"uael-module-content uael-infobox uael-imgicon-style-normal  uael-infobox-left  infobox-has-icon uael-infobox-icon-left  uael-infobox-image-valign-middle  uael-infobox-stacked-tablet  uael-infobox-link-type-none\">\n\t<div class=\"uael-infobox-left-right-wrap\">\n\t\t\t\t\t\t\t\t<div class=\"uael-module-content uael-imgicon-wrap\">\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"uael-icon-wrap elementor-animation-\">\n\t\t\t\t\t\t\t\t<span class=\"uael-icon\">\n\t\t\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-far-check-circle\" viewbox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M256 8C119.033 8 8 119.033 8 256s111.033 248 248 248 248-111.033 248-248S392.967 8 256 8zm0 48c110.532 0 200 89.451 200 200 0 110.532-89.451 200-200 200-110.532 0-200-89.451-200-200 0-110.532 89.451-200 200-200m140.204 130.267l-22.536-22.718c-4.667-4.705-12.265-4.736-16.97-.068L215.346 303.697l-59.792-60.277c-4.667-4.705-12.265-4.736-16.97-.069l-22.719 22.536c-4.705 4.667-4.736 12.265-.068 16.971l90.781 91.516c4.667 4.705 12.265 4.736 16.97.068l172.589-171.204c4.704-4.668 4.734-12.266.067-16.971z\"><\/path><\/svg>\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"uael-infobox-content\">\n\t\t\t\t\t\t<div class='uael-infobox-title-wrap'><h3 class=\"uael-infobox-title elementor-inline-editing\" data-elementor-setting-key=\"infobox_title\" data-elementor-inline-editing-toolbar=\"basic\" >Estratto di frutta di Vaccinium Myrtillus di alta qualit\u00e0<\/h3><\/div>\t\t\t\t\t\t<div class=\"uael-separator-parent\">\n\t\t\t\t<div class=\"uael-separator\"><\/div>\n\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"uael-infobox-text-wrap\">\n\t\t\t\t<div class=\"uael-infobox-text elementor-inline-editing\" data-elementor-setting-key=\"infobox_description\" data-elementor-inline-editing-toolbar=\"advanced\">\n\t\t\t\t\tPer le formulazioni che mirano alla salute degli occhi e al supporto antiossidante, il nostro estratto di frutto di Vaccinium Myrtillus \u00e8 una scelta eccellente. Garantiamo un'elevata concentrazione di composti attivi, per offrire benefici costanti e affidabili ai vostri prodotti.\t\t\t\t<\/div>\n\t\t\t\t\t\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t<\/div>\n<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7cc85a8c elementor-widget elementor-widget-uael-infobox\" data-id=\"7cc85a8c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"uael-infobox.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n<div class=\"uael-module-content uael-infobox uael-imgicon-style-normal  uael-infobox-left  infobox-has-icon uael-infobox-icon-left  uael-infobox-image-valign-middle  uael-infobox-stacked-tablet  uael-infobox-link-type-none\">\n\t<div class=\"uael-infobox-left-right-wrap\">\n\t\t\t\t\t\t\t\t<div class=\"uael-module-content uael-imgicon-wrap\">\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"uael-icon-wrap elementor-animation-\">\n\t\t\t\t\t\t\t\t<span class=\"uael-icon\">\n\t\t\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-far-check-circle\" viewbox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M256 8C119.033 8 8 119.033 8 256s111.033 248 248 248 248-111.033 248-248S392.967 8 256 8zm0 48c110.532 0 200 89.451 200 200 0 110.532-89.451 200-200 200-110.532 0-200-89.451-200-200 0-110.532 89.451-200 200-200m140.204 130.267l-22.536-22.718c-4.667-4.705-12.265-4.736-16.97-.068L215.346 303.697l-59.792-60.277c-4.667-4.705-12.265-4.736-16.97-.069l-22.719 22.536c-4.705 4.667-4.736 12.265-.068 16.971l90.781 91.516c4.667 4.705 12.265 4.736 16.97.068l172.589-171.204c4.704-4.668 4.734-12.266.067-16.971z\"><\/path><\/svg>\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"uael-infobox-content\">\n\t\t\t\t\t\t<div class='uael-infobox-title-wrap'><h3 class=\"uael-infobox-title elementor-inline-editing\" data-elementor-setting-key=\"infobox_title\" data-elementor-inline-editing-toolbar=\"basic\" >Estratto di corteccia di pino sfuso in polvere disponibile<\/h3><\/div>\t\t\t\t\t\t<div class=\"uael-separator-parent\">\n\t\t\t\t<div class=\"uael-separator\"><\/div>\n\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"uael-infobox-text-wrap\">\n\t\t\t\t<div class=\"uael-infobox-text elementor-inline-editing\" data-elementor-setting-key=\"infobox_description\" data-elementor-inline-editing-toolbar=\"advanced\">\n\t\t\t\t\tIl nostro estratto di corteccia di pino in polvere \u00e8 un ingrediente popolare noto per le sue potenti propriet\u00e0 antiossidanti e per le sue varie applicazioni sanitarie. 1 Offriamo questo estratto in quantit\u00e0 sfuse, assicurando una fornitura costante e conveniente per le vostre esigenze di produzione.\t\t\t\t<\/div>\n\t\t\t\t\t\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t<\/div>\n<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4f7d25f1 elementor-widget elementor-widget-uael-infobox\" data-id=\"4f7d25f1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"uael-infobox.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n<div class=\"uael-module-content uael-infobox uael-imgicon-style-normal  uael-infobox-left  infobox-has-icon uael-infobox-icon-left  uael-infobox-image-valign-middle  uael-infobox-stacked-tablet  uael-infobox-link-type-none\">\n\t<div class=\"uael-infobox-left-right-wrap\">\n\t\t\t\t\t\t\t\t<div class=\"uael-module-content uael-imgicon-wrap\">\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"uael-icon-wrap elementor-animation-\">\n\t\t\t\t\t\t\t\t<span class=\"uael-icon\">\n\t\t\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-far-check-circle\" viewbox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M256 8C119.033 8 8 119.033 8 256s111.033 248 248 248 248-111.033 248-248S392.967 8 256 8zm0 48c110.532 0 200 89.451 200 200 0 110.532-89.451 200-200 200-110.532 0-200-89.451-200-200 0-110.532 89.451-200 200-200m140.204 130.267l-22.536-22.718c-4.667-4.705-12.265-4.736-16.97-.068L215.346 303.697l-59.792-60.277c-4.667-4.705-12.265-4.736-16.97-.069l-22.719 22.536c-4.705 4.667-4.736 12.265-.068 16.971l90.781 91.516c4.667 4.705 12.265 4.736 16.97.068l172.589-171.204c4.704-4.668 4.734-12.266.067-16.971z\"><\/path><\/svg>\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"uael-infobox-content\">\n\t\t\t\t\t\t<div class='uael-infobox-title-wrap'><h3 class=\"uael-infobox-title elementor-inline-editing\" data-elementor-setting-key=\"infobox_title\" data-elementor-inline-editing-toolbar=\"basic\" >Impegno costante per la qualit\u00e0 e la purezza<\/h3><\/div>\t\t\t\t\t\t<div class=\"uael-separator-parent\">\n\t\t\t\t<div class=\"uael-separator\"><\/div>\n\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"uael-infobox-text-wrap\">\n\t\t\t\t<div class=\"uael-infobox-text elementor-inline-editing\" data-elementor-setting-key=\"infobox_description\" data-elementor-inline-editing-toolbar=\"advanced\">\n\t\t\t\t\tPer Gensei la qualit\u00e0 \u00e8 fondamentale. Attuiamo rigorose misure di controllo della qualit\u00e0 in tutti i nostri processi di approvvigionamento e di estrazione, assicurando che tutti i nostri estratti di erbe, compresi gli estratti di erbe cinesi, soddisfino i pi\u00f9 elevati standard di purezza, potenza e sicurezza.\t\t\t\t<\/div>\n\t\t\t\t\t\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t<\/div>\n<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-44f7d073 elementor-widget elementor-widget-uael-infobox\" data-id=\"44f7d073\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"uael-infobox.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n<div class=\"uael-module-content uael-infobox uael-imgicon-style-normal  uael-infobox-left  infobox-has-icon uael-infobox-icon-left  uael-infobox-image-valign-middle  uael-infobox-stacked-tablet  uael-infobox-link-type-none\">\n\t<div class=\"uael-infobox-left-right-wrap\">\n\t\t\t\t\t\t\t\t<div class=\"uael-module-content uael-imgicon-wrap\">\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"uael-icon-wrap elementor-animation-\">\n\t\t\t\t\t\t\t\t<span class=\"uael-icon\">\n\t\t\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-far-check-circle\" viewbox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M256 8C119.033 8 8 119.033 8 256s111.033 248 248 248 248-111.033 248-248S392.967 8 256 8zm0 48c110.532 0 200 89.451 200 200 0 110.532-89.451 200-200 200-110.532 0-200-89.451-200-200 0-110.532 89.451-200 200-200m140.204 130.267l-22.536-22.718c-4.667-4.705-12.265-4.736-16.97-.068L215.346 303.697l-59.792-60.277c-4.667-4.705-12.265-4.736-16.97-.069l-22.719 22.536c-4.705 4.667-4.736 12.265-.068 16.971l90.781 91.516c4.667 4.705 12.265 4.736 16.97.068l172.589-171.204c4.704-4.668 4.734-12.266.067-16.971z\"><\/path><\/svg>\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"uael-infobox-content\">\n\t\t\t\t\t\t<div class='uael-infobox-title-wrap'><h3 class=\"uael-infobox-title elementor-inline-editing\" data-elementor-setting-key=\"infobox_title\" data-elementor-inline-editing-toolbar=\"basic\" >Approvvigionamento globale e prezzi competitivi<\/h3><\/div>\t\t\t\t\t\t<div class=\"uael-separator-parent\">\n\t\t\t\t<div class=\"uael-separator\"><\/div>\n\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"uael-infobox-text-wrap\">\n\t\t\t\t<div class=\"uael-infobox-text elementor-inline-editing\" data-elementor-setting-key=\"infobox_description\" data-elementor-inline-editing-toolbar=\"advanced\">\n\t\t\t\t\tLa nostra consolidata rete globale ci permette di approvvigionarci delle migliori erbe da tutto il mondo, compresi i migliori estratti di erbe cinesi. Questo ci permette di offrire prezzi competitivi senza compromettere la qualit\u00e0 dei nostri prodotti.\t\t\t\t<\/div>\n\t\t\t\t\t\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t<\/div>\n<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-26220a5f elementor-widget elementor-widget-uael-infobox\" data-id=\"26220a5f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"uael-infobox.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n<div class=\"uael-module-content uael-infobox uael-imgicon-style-normal  uael-infobox-left  infobox-has-icon uael-infobox-icon-left  uael-infobox-image-valign-middle  uael-infobox-stacked-tablet  uael-infobox-link-type-none\">\n\t<div class=\"uael-infobox-left-right-wrap\">\n\t\t\t\t\t\t\t\t<div class=\"uael-module-content uael-imgicon-wrap\">\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"uael-icon-wrap elementor-animation-\">\n\t\t\t\t\t\t\t\t<span class=\"uael-icon\">\n\t\t\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-far-check-circle\" viewbox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M256 8C119.033 8 8 119.033 8 256s111.033 248 248 248 248-111.033 248-248S392.967 8 256 8zm0 48c110.532 0 200 89.451 200 200 0 110.532-89.451 200-200 200-110.532 0-200-89.451-200-200 0-110.532 89.451-200 200-200m140.204 130.267l-22.536-22.718c-4.667-4.705-12.265-4.736-16.97-.068L215.346 303.697l-59.792-60.277c-4.667-4.705-12.265-4.736-16.97-.069l-22.719 22.536c-4.705 4.667-4.736 12.265-.068 16.971l90.781 91.516c4.667 4.705 12.265 4.736 16.97.068l172.589-171.204c4.704-4.668 4.734-12.266.067-16.971z\"><\/path><\/svg>\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"uael-infobox-content\">\n\t\t\t\t\t\t<div class='uael-infobox-title-wrap'><h3 class=\"uael-infobox-title elementor-inline-editing\" data-elementor-setting-key=\"infobox_title\" data-elementor-inline-editing-toolbar=\"basic\" >Assistenza di esperti e soluzioni personalizzate<\/h3><\/div>\t\t\t\t\t\t<div class=\"uael-separator-parent\">\n\t\t\t\t<div class=\"uael-separator\"><\/div>\n\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"uael-infobox-text-wrap\">\n\t\t\t\t<div class=\"uael-infobox-text elementor-inline-editing\" data-elementor-setting-key=\"infobox_description\" data-elementor-inline-editing-toolbar=\"advanced\">\n\t\t\t\t\tIl nostro team di esperti possiede una vasta esperienza nel settore degli estratti di erbe. Siamo in grado di fornire una guida esperta sulla selezione, l'applicazione e la formulazione del prodotto per aiutarvi a raggiungere i vostri obiettivi di sviluppo. Offriamo anche servizi di estrazione e miscelazione personalizzati per soddisfare le vostre esigenze specifiche.\n\nScegliete Gensei come fornitore di estratti di erbe e guadagnate un vantaggio competitivo con i nostri ingredienti di qualit\u00e0 superiore, tra cui gli estratti di erbe cinesi specializzati, il versatile estratto di t\u00e8 alle erbe cinesi, il potente estratto di frutta di Vaccinium Myrtillus e l'estratto di corteccia di pino in polvere di alta qualit\u00e0. Contattateci oggi stesso per esplorare la nostra gamma completa e scoprire come possiamo supportare la vostra attivit\u00e0.\t\t\t\t<\/div>\n\t\t\t\t\t\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t<\/div>\n<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-4744e8d0 e-flex e-con-boxed e-con e-parent\" data-id=\"4744e8d0\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-23a86067 e-con-full e-flex e-con e-child\" data-id=\"23a86067\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-499b260 elementor-widget elementor-widget-heading\" data-id=\"499b260\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">I nostri impianti di produzione all'avanguardia<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3b3a9127 elementor-widget elementor-widget-text-editor\" data-id=\"3b3a9127\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Esplorate le nostre moderne strutture dotate di tecnologie avanzate per garantire la massima qualit\u00e0 nella produzione di vitamine, estratti di erbe, minerali e aminoacidi.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-1453e663 e-con-full e-flex e-con e-child\" data-id=\"1453e663\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-37c10411 elementor-arrows-position-inside elementor-pagination-position-outside elementor-widget elementor-widget-image-carousel\" data-id=\"37c10411\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;slides_to_show&quot;:&quot;3&quot;,&quot;slides_to_scroll&quot;:&quot;1&quot;,&quot;lazyload&quot;:&quot;yes&quot;,&quot;image_spacing_custom&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:5,&quot;sizes&quot;:[]},&quot;navigation&quot;:&quot;both&quot;,&quot;autoplay&quot;:&quot;yes&quot;,&quot;pause_on_hover&quot;:&quot;yes&quot;,&quot;pause_on_interaction&quot;:&quot;yes&quot;,&quot;autoplay_speed&quot;:5000,&quot;infinite&quot;:&quot;yes&quot;,&quot;speed&quot;:500,&quot;image_spacing_custom_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;image_spacing_custom_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]}}\" data-widget_type=\"image-carousel.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-image-carousel-wrapper swiper\" role=\"region\" aria-roledescription=\"carousel\" aria-label=\"Carosello di immagini\" dir=\"rtl\">\n\t\t\t<div class=\"elementor-image-carousel swiper-wrapper swiper-image-stretch\" aria-live=\"off\">\n\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"1 di 11\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image swiper-lazy\" data-src=\"https:\/\/collagensei.com\/wp-content\/uploads\/2025\/04\/Machining-machine-12-768x576.webp\" alt=\"Macchina per la lavorazione (12)\" \/><div class=\"swiper-lazy-preloader\"><\/div><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"2 di 11\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image swiper-lazy\" data-src=\"https:\/\/collagensei.com\/wp-content\/uploads\/2025\/04\/Machining-machine-11-768x576.webp\" alt=\"Macchina per la lavorazione (11)\" \/><div class=\"swiper-lazy-preloader\"><\/div><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"3 di 11\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image swiper-lazy\" data-src=\"https:\/\/collagensei.com\/wp-content\/uploads\/2025\/04\/Machining-machine-10-768x576.webp\" alt=\"Macchina per la lavorazione (10)\" \/><div class=\"swiper-lazy-preloader\"><\/div><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"4 di 11\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image swiper-lazy\" data-src=\"https:\/\/collagensei.com\/wp-content\/uploads\/2025\/04\/Machining-machine-9-768x576.webp\" alt=\"Macchina per la lavorazione (9)\" \/><div class=\"swiper-lazy-preloader\"><\/div><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"5 di 11\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image swiper-lazy\" data-src=\"https:\/\/collagensei.com\/wp-content\/uploads\/2025\/04\/Machining-machine-8-768x576.webp\" alt=\"Macchina per la lavorazione (8)\" \/><div class=\"swiper-lazy-preloader\"><\/div><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"6 di 11\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image swiper-lazy\" data-src=\"https:\/\/collagensei.com\/wp-content\/uploads\/2025\/04\/Machining-machine-7-768x576.webp\" alt=\"Macchina per la lavorazione (7)\" \/><div class=\"swiper-lazy-preloader\"><\/div><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"7 di 11\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image swiper-lazy\" data-src=\"https:\/\/collagensei.com\/wp-content\/uploads\/2025\/04\/Machining-machine-6-768x576.webp\" alt=\"Macchina per la lavorazione (6)\" \/><div class=\"swiper-lazy-preloader\"><\/div><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"8 di 11\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image swiper-lazy\" data-src=\"https:\/\/collagensei.com\/wp-content\/uploads\/2025\/04\/Machining-machine-5-768x576.webp\" alt=\"Macchina per la lavorazione (5)\" \/><div class=\"swiper-lazy-preloader\"><\/div><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"9 di 11\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image swiper-lazy\" data-src=\"https:\/\/collagensei.com\/wp-content\/uploads\/2025\/04\/Machining-machine-4-768x575.webp\" alt=\"Macchina per la lavorazione (4)\" \/><div class=\"swiper-lazy-preloader\"><\/div><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"10 di 11\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image swiper-lazy\" data-src=\"https:\/\/collagensei.com\/wp-content\/uploads\/2025\/04\/Machining-machine-2-768x576.webp\" alt=\"Macchina per la lavorazione (2)\" \/><div class=\"swiper-lazy-preloader\"><\/div><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"11 di 11\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image swiper-lazy\" data-src=\"https:\/\/collagensei.com\/wp-content\/uploads\/2025\/04\/Machining-machine-1-768x576.webp\" alt=\"Macchina per la lavorazione (1)\" \/><div class=\"swiper-lazy-preloader\"><\/div><\/figure><\/div>\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-prev\" role=\"button\" tabindex=\"0\">\n\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-eicon-chevron-left\" viewbox=\"0 0 1000 1000\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M646 125C629 125 613 133 604 142L308 442C296 454 292 471 292 487 292 504 296 521 308 533L604 854C617 867 629 875 646 875 663 875 679 871 692 858 704 846 713 829 713 812 713 796 708 779 692 767L438 487 692 225C700 217 708 204 708 187 708 171 704 154 692 142 675 129 663 125 646 125Z\"><\/path><\/svg>\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-next\" role=\"button\" tabindex=\"0\">\n\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-eicon-chevron-right\" viewbox=\"0 0 1000 1000\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M696 533C708 521 713 504 713 487 713 471 708 454 696 446L400 146C388 133 375 125 354 125 338 125 325 129 313 142 300 154 292 171 292 187 292 204 296 221 308 233L563 492 304 771C292 783 288 800 288 817 288 833 296 850 308 863 321 871 338 875 354 875 371 875 388 867 400 854L696 533Z\"><\/path><\/svg>\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"swiper-pagination\"><\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-092f7b4 e-flex e-con-boxed e-con e-parent\" data-id=\"092f7b4\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-06814b8 elementor-widget elementor-widget-html\" data-id=\"06814b8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<!DOCTYPE html>\r\n<html lang=\"en\">\r\n<head>\r\n    <meta charset=\"UTF-8\">\r\n    <meta name=\"viewport\" content=\"width=device-width, initial-scale=1.0\">\r\n    <title>Diagramma di flusso dettagliato del processo di estrazione delle erbe<\/title>\r\n    <style>\r\n        :root {\r\n            --primary-green: #2d6a4f;\r\n            --secondary-green: #52b788;\r\n            --accent-blue: #3498db;\r\n            --bg-light: #f8f9fa;\r\n            --text-dark: #2c3e50;\r\n            --border-color: #dee2e6;\r\n        }\r\n\r\n        body {\r\n            font-family: 'Segoe UI', Arial, sans-serif;\r\n            background-color: var(--bg-light);\r\n            color: var(--text-dark);\r\n            line-height: 1.6;\r\n            padding: 40px 20px;\r\n            display: flex;\r\n            flex-direction: column;\r\n            align-items: center;\r\n        }\r\n\r\n        .header {\r\n            text-align: center;\r\n            margin-bottom: 50px;\r\n        }\r\n\r\n        .header h1 {\r\n            color: var(--primary-green);\r\n            font-size: 2.5rem;\r\n            margin-bottom: 10px;\r\n        }\r\n\r\n        .flowchart-container {\r\n            display: flex;\r\n            flex-direction: column;\r\n            align-items: center;\r\n            max-width: 900px;\r\n            width: 100%;\r\n        }\r\n\r\n        .node {\r\n            background: white;\r\n            border: 2px solid var(--primary-green);\r\n            border-radius: 12px;\r\n            padding: 20px;\r\n            width: 100%;\r\n            max-width: 500px;\r\n            margin-bottom: 40px;\r\n            position: relative;\r\n            box-shadow: 0 4px 15px rgba(0,0,0,0.05);\r\n            transition: transform 0.2s ease;\r\n        }\r\n\r\n        .node:hover {\r\n            transform: translateY(-5px);\r\n            box-shadow: 0 6px 20px rgba(0,0,0,0.1);\r\n        }\r\n\r\n        .node h3 {\r\n            margin: 0 0 10px 0;\r\n            color: var(--primary-green);\r\n            display: flex;\r\n            align-items: center;\r\n            font-size: 1.25rem;\r\n        }\r\n\r\n        .node .step-number {\r\n            background: var(--primary-green);\r\n            color: white;\r\n            width: 28px;\r\n            height: 28px;\r\n            border-radius: 50%;\r\n            display: inline-flex;\r\n            justify-content: center;\r\n            align-items: center;\r\n            margin-right: 12px;\r\n            font-size: 0.9rem;\r\n        }\r\n\r\n        .node p {\r\n            margin: 0;\r\n            font-size: 0.95rem;\r\n            color: #555;\r\n        }\r\n\r\n        .details {\r\n            margin-top: 10px;\r\n            font-size: 0.85rem;\r\n            background: #f1f8f5;\r\n            padding: 8px;\r\n            border-radius: 6px;\r\n            border-left: 3px solid var(--secondary-green);\r\n        }\r\n\r\n        \/* Connecting Arrows *\/\r\n        .node::after {\r\n            content: '\u2193';\r\n            position: absolute;\r\n            bottom: -35px;\r\n            left: 50%;\r\n            transform: translateX(-50%);\r\n            font-size: 28px;\r\n            color: var(--secondary-green);\r\n            font-weight: bold;\r\n        }\r\n\r\n        .node:last-child::after {\r\n            content: none;\r\n        }\r\n\r\n        \/* Category Styles *\/\r\n        .raw-material { border-color: #e67e22; }\r\n        .raw-material .step-number { background: #e67e22; }\r\n        \r\n        .qc-node { border-color: var(--accent-blue); }\r\n        .qc-node .step-number { background: var(--accent-blue); }\r\n\r\n        @media (max-width: 600px) {\r\n            .node { width: 90%; }\r\n        }\r\n    <\/style>\r\n<\/head>\r\n<body>\r\n\r\n    <div class=\"header\">\r\n        <h1>Processo di estrazione industriale delle erbe<\/h1>\r\n        <p>Flusso di lavoro standardizzato per estratti botanici di alta qualit\u00e0<\/p>\r\n    <\/div>\r\n\r\n    <div class=\"flowchart-container\">\r\n\r\n        <div class=\"node raw-material\">\r\n            <h3><span class=\"step-number\">01<\/span>Pretrattamento delle materie prime<\/h3>\r\n            <p>Selezione, pulizia e lavaggio delle erbe per rimuovere le impurit\u00e0.<\/p>\r\n            <div class=\"details\">\r\n                <strong>Azioni chiave:<\/strong> Affettatura, frantumazione o macinazione a maglie di dimensioni specifiche (per aumentare la superficie).\r\n            <\/div>\r\n        <\/div>\r\n\r\n        <div class=\"node\">\r\n            <h3><span class=\"step-number\">02<\/span>Estrazione con solvente<\/h3>\r\n            <p>Caricare il materiale negli estrattori utilizzando solventi specifici (acqua, etanolo o CO2).<\/p>\r\n            <div class=\"details\">\r\n                <strong>Metodi:<\/strong> Macerazione, percolazione o estrazione in controcorrente a pi\u00f9 stadi.\r\n            <\/div>\r\n        <\/div>\r\n\r\n        <div class=\"node\">\r\n            <h3><span class=\"step-number\">03<\/span>Separazione solido-liquido<\/h3>\r\n            <p>Filtrare la miscela per separare l'estratto liquido dalla biomassa esausta (vinacce).<\/p>\r\n            <div class=\"details\">\r\n                <strong>Attrezzatura:<\/strong> Centrifughe, filtropresse o vagli vibranti.\r\n            <\/div>\r\n        <\/div>\r\n\r\n        <div class=\"node\">\r\n            <h3><span class=\"step-number\">04<\/span>Concentrazione del vuoto<\/h3>\r\n            <p>Evaporazione del solvente a bassa pressione e temperatura per preservare i composti sensibili al calore.<\/p>\r\n            <div class=\"details\">\r\n                <strong>Risultato:<\/strong> Estratto liquido concentrato o \"spissum\"; recupero del solvente per il riutilizzo.\r\n            <\/div>\r\n        <\/div>\r\n\r\n        <div class=\"node\">\r\n            <h3><span class=\"step-number\">05<\/span>Purificazione e raffinazione<\/h3>\r\n            <p>Fase facoltativa per isolare principi attivi specifici o rimuovere cere\/clorofilla.<\/p>\r\n            <div class=\"details\">\r\n                <strong>Tecniche:<\/strong> Cromatografia con resine macroporose, estrazione liquido-liquido o decolorazione.\r\n            <\/div>\r\n        <\/div>\r\n\r\n        <div class=\"node\">\r\n            <h3><span class=\"step-number\">06<\/span>Processo di essiccazione<\/h3>\r\n            <p>Conversione del concentrato liquido in una forma stabile di polvere secca.<\/p>\r\n            <div class=\"details\">\r\n                <strong>Opzioni:<\/strong> Asciugatura a spruzzo (standard), asciugatura sottovuoto o congelamento (Premium\/Sensitive).\r\n            <\/div>\r\n        <\/div>\r\n\r\n        <div class=\"node qc-node\">\r\n            <h3><span class=\"step-number\">07<\/span>Standardizzazione e vaglio<\/h3>\r\n            <p>Test per la ricerca di marcatori attivi e miscelazione per garantire una potenza uniforme tra i lotti.<\/p>\r\n            <div class=\"details\">\r\n                <strong>Specifiche:<\/strong> Setacciamento delle dimensioni delle particelle, controllo del contenuto di umidit\u00e0 e regolazione degli eccipienti.\r\n            <\/div>\r\n        <\/div>\r\n\r\n        <div class=\"node qc-node\">\r\n            <h3><span class=\"step-number\">08<\/span>Controllo qualit\u00e0 (finale)<\/h3>\r\n            <p>Rigorosi test di laboratorio per la sicurezza e la conformit\u00e0.<\/p>\r\n            <div class=\"details\">\r\n                <strong>Parametri:<\/strong> Analisi HPLC\/GC, metalli pesanti, residui di pesticidi e limiti microbici.\r\n            <\/div>\r\n        <\/div>\r\n\r\n        <div class=\"node\">\r\n            <h3><span class=\"step-number\">09<\/span>Imballaggio e stoccaggio<\/h3>\r\n            <p>Chiusura in contenitori per alimenti, a prova di umidit\u00e0.<\/p>\r\n            <div class=\"details\">\r\n                <strong>Stoccaggio:<\/strong> Ambiente fresco e asciutto, lontano dalla luce solare diretta.\r\n            <\/div>\r\n        <\/div>\r\n\r\n    <\/div>\r\n\r\n<\/body>\r\n<\/html>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-76500cf2 e-flex e-con-boxed e-con e-parent\" data-id=\"76500cf2\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-2778b934 elementor-widget elementor-widget-heading\" data-id=\"2778b934\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">FAQ<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-10579ec3 uael-faq-box-layout-yes align-at-left elementor-widget elementor-widget-uael-faq\" data-id=\"10579ec3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"uael-faq.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n\t\t\t<div id='uael-faq-wrapper-274' class=\"uael-faq-wrapper\">\n\t\t\t\t<div class=\"uael-faq-container uael-faq-layout-accordion\" data-layout=\"accordion\" >\n\t\t\t\t\t\t\t\t\t\t\t\t<div id=\"uael-accordion-9cca0fc\" class=\"uael-faq-accordion\" role=\"tablist\">\n\t\t\t\t\t\t\t\t<div class= \"uael-accordion-title\" aria-expanded=\"false\" role=\"tab\">\n\t\t\t\t\t\t\t\t\t<span class=\"uael-accordion-icon uael-accordion-icon-left\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"uael-accordion-icon-closed\"><svg class=\"e-font-icon-svg e-fas-angle-right\" viewbox=\"0 0 256 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M224.3 273l-136 136c-9.4 9.4-24.6 9.4-33.9 0l-22.6-22.6c-9.4-9.4-9.4-24.6 0-33.9l96.4-96.4-96.4-96.4c-9.4-9.4-9.4-24.6 0-33.9L54.3 103c9.4-9.4 24.6-9.4 33.9 0l136 136c9.5 9.4 9.5 24.6.1 34z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"uael-accordion-icon-opened\"><svg class=\"e-font-icon-svg e-fas-angle-up\" viewbox=\"0 0 320 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M177 159.7l136 136c9.4 9.4 9.4 24.6 0 33.9l-22.6 22.6c-9.4 9.4-24.6 9.4-33.9 0L160 255.9l-96.4 96.4c-9.4 9.4-24.6 9.4-33.9 0L7 329.7c-9.4-9.4-9.4-24.6 0-33.9l136-136c9.4-9.5 24.6-9.5 34-.1z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"uael-question-9cca0fc uael-question-span\" tabindex=\"0\" id=\"uael-faq-1-6a03dd1b200d5\">Come estrarre l'olio dalle erbe?<\/span>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"uael-accordion-content\" role=\"tabpanel\">\n\t\t\t\t\t\t\t\t\t<span>\n\t\t\t\t\t\t\t\t\t<span><ul><li data-sourcepos=\"4:5-4:220\"><strong>Distillazione a vapore:<\/strong> \u00c8 il metodo pi\u00f9 comune. Il vapore viene fatto passare attraverso il materiale vegetale, provocando la vaporizzazione degli oli essenziali. Il vapore viene poi raffreddato e condensato, separando l'olio dall'acqua.<\/li><li data-sourcepos=\"5:5-5:144\"><strong>Idrodistillazione:<\/strong> Il materiale vegetale viene immerso in acqua e riscaldato. Il vapore e gli oli essenziali vengono poi condensati e separati.<\/li><li data-sourcepos=\"6:5-6:265\"><strong>Estrazione con solvente:<\/strong> Per sciogliere gli oli essenziali si utilizza un solvente (come esano o etanolo). Il solvente viene poi fatto evaporare, lasciando l'olio concentrato. Questo metodo \u00e8 spesso utilizzato per i fiori delicati o quando la distillazione a vapore non \u00e8 efficiente.<\/li><li data-sourcepos=\"7:5-8:0\"><strong>Espressione (pressatura a freddo):<\/strong> Utilizzato principalmente per le bucce degli agrumi, questo metodo prevede la pressatura meccanica del materiale vegetale per liberare l'olio.<\/li><\/ul><\/span>\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div id=\"uael-accordion-6ed023f\" class=\"uael-faq-accordion\" role=\"tablist\">\n\t\t\t\t\t\t\t\t<div class= \"uael-accordion-title\" aria-expanded=\"false\" role=\"tab\">\n\t\t\t\t\t\t\t\t\t<span class=\"uael-accordion-icon uael-accordion-icon-left\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"uael-accordion-icon-closed\"><svg class=\"e-font-icon-svg e-fas-angle-right\" viewbox=\"0 0 256 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M224.3 273l-136 136c-9.4 9.4-24.6 9.4-33.9 0l-22.6-22.6c-9.4-9.4-9.4-24.6 0-33.9l96.4-96.4-96.4-96.4c-9.4-9.4-9.4-24.6 0-33.9L54.3 103c9.4-9.4 24.6-9.4 33.9 0l136 136c9.5 9.4 9.5 24.6.1 34z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"uael-accordion-icon-opened\"><svg class=\"e-font-icon-svg e-fas-angle-up\" viewbox=\"0 0 320 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M177 159.7l136 136c9.4 9.4 9.4 24.6 0 33.9l-22.6 22.6c-9.4 9.4-24.6 9.4-33.9 0L160 255.9l-96.4 96.4c-9.4 9.4-24.6 9.4-33.9 0L7 329.7c-9.4-9.4-9.4-24.6 0-33.9l136-136c9.4-9.5 24.6-9.5 34-.1z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"uael-question-6ed023f uael-question-span\" tabindex=\"0\" id=\"uael-faq-2-6a03dd1b2014f\">Come estrarre le erbe?<\/span>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"uael-accordion-content\" role=\"tabpanel\">\n\t\t\t\t\t\t\t\t\t<span>\n\t\t\t\t\t\t\t\t\t<span><ul><li data-sourcepos=\"12:5-12:81\"><strong>Acqua:<\/strong> Per i composti solubili in acqua (ad esempio, t\u00e8, infusi, decotti).<\/li><li data-sourcepos=\"13:5-13:115\"><strong>Alcool:<\/strong> Per una gamma pi\u00f9 ampia di composti, compresi quelli non facilmente solubili in acqua (ad esempio, le tinture).<\/li><li data-sourcepos=\"14:5-14:70\"><strong>Glicerina:<\/strong> Un solvente dolce e non alcolico (ad esempio, gliceriti).<\/li><li data-sourcepos=\"15:5-15:86\"><strong>Aceto:<\/strong> Pu\u00f2 estrarre alcuni minerali e composti (ad esempio, aceti di erbe).<\/li><li data-sourcepos=\"16:5-17:0\"><strong>Olio:<\/strong> Per i composti liposolubili (ad esempio, oli infusi).<\/li><\/ul><\/span>\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div id=\"uael-accordion-0abcbac\" class=\"uael-faq-accordion\" role=\"tablist\">\n\t\t\t\t\t\t\t\t<div class= \"uael-accordion-title\" aria-expanded=\"false\" role=\"tab\">\n\t\t\t\t\t\t\t\t\t<span class=\"uael-accordion-icon uael-accordion-icon-left\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"uael-accordion-icon-closed\"><svg class=\"e-font-icon-svg e-fas-angle-right\" viewbox=\"0 0 256 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M224.3 273l-136 136c-9.4 9.4-24.6 9.4-33.9 0l-22.6-22.6c-9.4-9.4-9.4-24.6 0-33.9l96.4-96.4-96.4-96.4c-9.4-9.4-9.4-24.6 0-33.9L54.3 103c9.4-9.4 24.6-9.4 33.9 0l136 136c9.5 9.4 9.5 24.6.1 34z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"uael-accordion-icon-opened\"><svg class=\"e-font-icon-svg e-fas-angle-up\" viewbox=\"0 0 320 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M177 159.7l136 136c9.4 9.4 9.4 24.6 0 33.9l-22.6 22.6c-9.4 9.4-24.6 9.4-33.9 0L160 255.9l-96.4 96.4c-9.4 9.4-24.6 9.4-33.9 0L7 329.7c-9.4-9.4-9.4-24.6 0-33.9l136-136c9.4-9.5 24.6-9.5 34-.1z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"uael-question-0abcbac uael-question-span\" tabindex=\"0\" id=\"uael-faq-3-6a03dd1b20189\">Come estrarre le erbe con l'acqua?<\/span>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"uael-accordion-content\" role=\"tabpanel\">\n\t\t\t\t\t\t\t\t\t<span>\n\t\t\t\t\t\t\t\t\t<span><ul><li data-sourcepos=\"19:5-19:133\"><strong>Infusione:<\/strong> Versare acqua calda (non bollente) sull'erba e lasciarla in infusione per un certo periodo (come per la preparazione del t\u00e8 dalle foglie o dai fiori).<\/li><li data-sourcepos=\"20:5-20:135\"><strong>Decotto:<\/strong> Far sobbollire in acqua per un tempo pi\u00f9 lungo le parti pi\u00f9 dure delle piante, come radici, corteccia o semi, per estrarne i costituenti.<\/li><li data-sourcepos=\"21:5-22:0\"><strong>Percolazione:<\/strong> Versare lentamente acqua calda attraverso un contenitore di erbe, permettendo all'acqua di estrarre i composti al suo passaggio.<\/li><\/ul><\/span>\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div id=\"uael-accordion-3cdcd5a\" class=\"uael-faq-accordion\" role=\"tablist\">\n\t\t\t\t\t\t\t\t<div class= \"uael-accordion-title\" aria-expanded=\"false\" role=\"tab\">\n\t\t\t\t\t\t\t\t\t<span class=\"uael-accordion-icon uael-accordion-icon-left\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"uael-accordion-icon-closed\"><svg class=\"e-font-icon-svg e-fas-angle-right\" viewbox=\"0 0 256 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M224.3 273l-136 136c-9.4 9.4-24.6 9.4-33.9 0l-22.6-22.6c-9.4-9.4-9.4-24.6 0-33.9l96.4-96.4-96.4-96.4c-9.4-9.4-9.4-24.6 0-33.9L54.3 103c9.4-9.4 24.6-9.4 33.9 0l136 136c9.5 9.4 9.5 24.6.1 34z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"uael-accordion-icon-opened\"><svg class=\"e-font-icon-svg e-fas-angle-up\" viewbox=\"0 0 320 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M177 159.7l136 136c9.4 9.4 9.4 24.6 0 33.9l-22.6 22.6c-9.4 9.4-24.6 9.4-33.9 0L160 255.9l-96.4 96.4c-9.4 9.4-24.6 9.4-33.9 0L7 329.7c-9.4-9.4-9.4-24.6 0-33.9l136-136c9.4-9.5 24.6-9.5 34-.1z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"uael-question-3cdcd5a uael-question-span\" tabindex=\"0\" id=\"uael-faq-4-6a03dd1b201be\">Come estrarre le erbe senza alcol?<\/span>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"uael-accordion-content\" role=\"tabpanel\">\n\t\t\t\t\t\t\t\t\t<span>\n\t\t\t\t\t\t\t\t\t<span><ul><li data-sourcepos=\"24:5-24:74\"><strong>Acqua:<\/strong> Come gi\u00e0 detto (infusi, decotti, percolati).<\/li><li data-sourcepos=\"25:5-25:103\"><strong>Glicerina:<\/strong> La glicerina pu\u00f2 sciogliere molti costituenti vegetali e crea un estratto dal sapore dolce.<\/li><li data-sourcepos=\"26:5-26:111\"><strong>Aceto:<\/strong> Soprattutto l'aceto di sidro di mele pu\u00f2 essere utilizzato per estrarre minerali e alcuni altri composti.<\/li><li data-sourcepos=\"27:5-28:0\"><strong>Infusione di olio:<\/strong> Immergere le erbe in un olio vettore (come l'olio d'oliva o di mandorle) per un certo periodo di tempo, spesso con un leggero calore, per estrarre i composti liposolubili.<\/li><\/ul><\/span>\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div id=\"uael-accordion-bed4aa5\" class=\"uael-faq-accordion\" role=\"tablist\">\n\t\t\t\t\t\t\t\t<div class= \"uael-accordion-title\" aria-expanded=\"false\" role=\"tab\">\n\t\t\t\t\t\t\t\t\t<span class=\"uael-accordion-icon uael-accordion-icon-left\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"uael-accordion-icon-closed\"><svg class=\"e-font-icon-svg e-fas-angle-right\" viewbox=\"0 0 256 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M224.3 273l-136 136c-9.4 9.4-24.6 9.4-33.9 0l-22.6-22.6c-9.4-9.4-9.4-24.6 0-33.9l96.4-96.4-96.4-96.4c-9.4-9.4-9.4-24.6 0-33.9L54.3 103c9.4-9.4 24.6-9.4 33.9 0l136 136c9.5 9.4 9.5 24.6.1 34z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"uael-accordion-icon-opened\"><svg class=\"e-font-icon-svg e-fas-angle-up\" viewbox=\"0 0 320 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M177 159.7l136 136c9.4 9.4 9.4 24.6 0 33.9l-22.6 22.6c-9.4 9.4-24.6 9.4-33.9 0L160 255.9l-96.4 96.4c-9.4 9.4-24.6 9.4-33.9 0L7 329.7c-9.4-9.4-9.4-24.6 0-33.9l136-136c9.4-9.5 24.6-9.5 34-.1z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"uael-question-bed4aa5 uael-question-span\" tabindex=\"0\" id=\"uael-faq-5-6a03dd1b201f1\">Come estrarre l'olio dalle erbe secche?<\/span>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"uael-accordion-content\" role=\"tabpanel\">\n\t\t\t\t\t\t\t\t\t<span>\n\t\t\t\t\t\t\t\t\t<span><p>L'estrazione degli oli essenziali dalle erbe essiccate segue gli stessi metodi utilizzati per le erbe fresche (distillazione a vapore, idrodistillazione, estrazione con solvente, espressione). In molti casi, le erbe essiccate sono preferite per l'estrazione di oli essenziali perch\u00e9 il processo di essiccazione concentra gli oli volatili.<\/p><\/span>\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div id=\"uael-accordion-c08b67a\" class=\"uael-faq-accordion\" role=\"tablist\">\n\t\t\t\t\t\t\t\t<div class= \"uael-accordion-title\" aria-expanded=\"false\" role=\"tab\">\n\t\t\t\t\t\t\t\t\t<span class=\"uael-accordion-icon uael-accordion-icon-left\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"uael-accordion-icon-closed\"><svg class=\"e-font-icon-svg e-fas-angle-right\" viewbox=\"0 0 256 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M224.3 273l-136 136c-9.4 9.4-24.6 9.4-33.9 0l-22.6-22.6c-9.4-9.4-9.4-24.6 0-33.9l96.4-96.4-96.4-96.4c-9.4-9.4-9.4-24.6 0-33.9L54.3 103c9.4-9.4 24.6-9.4 33.9 0l136 136c9.5 9.4 9.5 24.6.1 34z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"uael-accordion-icon-opened\"><svg class=\"e-font-icon-svg e-fas-angle-up\" viewbox=\"0 0 320 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M177 159.7l136 136c9.4 9.4 9.4 24.6 0 33.9l-22.6 22.6c-9.4 9.4-24.6 9.4-33.9 0L160 255.9l-96.4 96.4c-9.4 9.4-24.6 9.4-33.9 0L7 329.7c-9.4-9.4-9.4-24.6 0-33.9l136-136c9.4-9.5 24.6-9.5 34-.1z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"uael-question-c08b67a uael-question-span\" tabindex=\"0\" id=\"uael-faq-6-6a03dd1b20223\">Come estrarre l'olio dalle erbe in casa?<\/span>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"uael-accordion-content\" role=\"tabpanel\">\n\t\t\t\t\t\t\t\t\t<span>\n\t\t\t\t\t\t\t\t\t<span><p data-sourcepos=\"31:5-31:200\">Estrarre oli essenziali puri a casa pu\u00f2 essere impegnativo e potenzialmente pericoloso senza un'attrezzatura adeguata. Tuttavia, \u00e8 possibile preparare in casa degli oli infusi:<\/p><ul data-sourcepos=\"32:5-33:0\"><li data-sourcepos=\"32:5-33:0\"><strong>Metodo dell'olio infuso:<\/strong> Scaldare delicatamente un olio vettore (come l'olio d'oliva) e aggiungere l'erba secca scelta. Lasciate in infusione per alcune ore a fuoco molto basso o per alcune settimane a temperatura ambiente. Filtrate le erbe. L'olio conterr\u00e0 alcuni dei composti oleosolubili e dell'aroma dell'erba.<\/li><\/ul><\/span>\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div id=\"uael-accordion-1eb4d4c\" class=\"uael-faq-accordion\" role=\"tablist\">\n\t\t\t\t\t\t\t\t<div class= \"uael-accordion-title\" aria-expanded=\"false\" role=\"tab\">\n\t\t\t\t\t\t\t\t\t<span class=\"uael-accordion-icon uael-accordion-icon-left\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"uael-accordion-icon-closed\"><svg class=\"e-font-icon-svg e-fas-angle-right\" viewbox=\"0 0 256 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M224.3 273l-136 136c-9.4 9.4-24.6 9.4-33.9 0l-22.6-22.6c-9.4-9.4-9.4-24.6 0-33.9l96.4-96.4-96.4-96.4c-9.4-9.4-9.4-24.6 0-33.9L54.3 103c9.4-9.4 24.6-9.4 33.9 0l136 136c9.5 9.4 9.5 24.6.1 34z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"uael-accordion-icon-opened\"><svg class=\"e-font-icon-svg e-fas-angle-up\" viewbox=\"0 0 320 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M177 159.7l136 136c9.4 9.4 9.4 24.6 0 33.9l-22.6 22.6c-9.4 9.4-24.6 9.4-33.9 0L160 255.9l-96.4 96.4c-9.4 9.4-24.6 9.4-33.9 0L7 329.7c-9.4-9.4-9.4-24.6 0-33.9l136-136c9.4-9.5 24.6-9.5 34-.1z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"uael-question-1eb4d4c uael-question-span\" tabindex=\"0\" id=\"uael-faq-7-6a03dd1b20255\">Che cos'\u00e8 l'estratto di erbe?<\/span>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"uael-accordion-content\" role=\"tabpanel\">\n\t\t\t\t\t\t\t\t\t<span>\n\t\t\t\t\t\t\t\t\t<span><p>L'estratto di erbe \u00e8 una preparazione concentrata ottenuta sciogliendo i costituenti chimici attivi di una pianta in un solvente. Il solvente viene poi spesso rimosso parzialmente o completamente, lasciando una forma concentrata dei composti benefici dell'erba. Gli estratti possono presentarsi in forma liquida, solida (polvere) o semisolida.<\/p><\/span>\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div id=\"uael-accordion-94288c9\" class=\"uael-faq-accordion\" role=\"tablist\">\n\t\t\t\t\t\t\t\t<div class= \"uael-accordion-title\" aria-expanded=\"false\" role=\"tab\">\n\t\t\t\t\t\t\t\t\t<span class=\"uael-accordion-icon uael-accordion-icon-left\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"uael-accordion-icon-closed\"><svg class=\"e-font-icon-svg e-fas-angle-right\" viewbox=\"0 0 256 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M224.3 273l-136 136c-9.4 9.4-24.6 9.4-33.9 0l-22.6-22.6c-9.4-9.4-9.4-24.6 0-33.9l96.4-96.4-96.4-96.4c-9.4-9.4-9.4-24.6 0-33.9L54.3 103c9.4-9.4 24.6-9.4 33.9 0l136 136c9.5 9.4 9.5 24.6.1 34z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"uael-accordion-icon-opened\"><svg class=\"e-font-icon-svg e-fas-angle-up\" viewbox=\"0 0 320 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M177 159.7l136 136c9.4 9.4 9.4 24.6 0 33.9l-22.6 22.6c-9.4 9.4-24.6 9.4-33.9 0L160 255.9l-96.4 96.4c-9.4 9.4-24.6 9.4-33.9 0L7 329.7c-9.4-9.4-9.4-24.6 0-33.9l136-136c9.4-9.5 24.6-9.5 34-.1z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"uael-question-94288c9 uael-question-span\" tabindex=\"0\" id=\"uael-faq-8-6a03dd1b20286\">Che cos'\u00e8 l'estratto di erba Bacopa?<\/span>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"uael-accordion-content\" role=\"tabpanel\">\n\t\t\t\t\t\t\t\t\t<span>\n\t\t\t\t\t\t\t\t\t<span><p>L'estratto di erba bacopa deriva dalla <em>Bacopa monnieri<\/em> pianta, nota anche come Brahmi. \u00c8 comunemente usata nella medicina tradizionale ayurvedica ed \u00e8 nota per le sue potenziali propriet\u00e0 di potenziamento cognitivo, come il miglioramento della memoria e della concentrazione e la riduzione dell'ansia. L'estratto contiene tipicamente composti chiamati bacosidi, che si ritiene siano responsabili di questi effetti.<\/p><\/span>\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div id=\"uael-accordion-64d7b5d\" class=\"uael-faq-accordion\" role=\"tablist\">\n\t\t\t\t\t\t\t\t<div class= \"uael-accordion-title\" aria-expanded=\"false\" role=\"tab\">\n\t\t\t\t\t\t\t\t\t<span class=\"uael-accordion-icon uael-accordion-icon-left\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"uael-accordion-icon-closed\"><svg class=\"e-font-icon-svg e-fas-angle-right\" viewbox=\"0 0 256 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M224.3 273l-136 136c-9.4 9.4-24.6 9.4-33.9 0l-22.6-22.6c-9.4-9.4-9.4-24.6 0-33.9l96.4-96.4-96.4-96.4c-9.4-9.4-9.4-24.6 0-33.9L54.3 103c9.4-9.4 24.6-9.4 33.9 0l136 136c9.5 9.4 9.5 24.6.1 34z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"uael-accordion-icon-opened\"><svg class=\"e-font-icon-svg e-fas-angle-up\" viewbox=\"0 0 320 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M177 159.7l136 136c9.4 9.4 9.4 24.6 0 33.9l-22.6 22.6c-9.4 9.4-24.6 9.4-33.9 0L160 255.9l-96.4 96.4c-9.4 9.4-24.6 9.4-33.9 0L7 329.7c-9.4-9.4-9.4-24.6 0-33.9l136-136c9.4-9.5 24.6-9.5 34-.1z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"uael-question-64d7b5d uael-question-span\" tabindex=\"0\" id=\"uael-faq-9-6a03dd1b202b9\">Che cos'\u00e8 l'estratto di erbe Kanna?<\/span>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"uael-accordion-content\" role=\"tabpanel\">\n\t\t\t\t\t\t\t\t\t<span>\n\t\t\t\t\t\t\t\t\t<span><p>L'estratto di erba Kanna proviene dalla <em>Sceletium tortuosum<\/em> pianta originaria del Sudafrica. \u00c8 stata tradizionalmente utilizzata dalle popolazioni indigene per le sue propriet\u00e0 che alterano l'umore e alleviano lo stress. L'estratto contiene alcaloidi come la mesembrina, che si ritiene influiscano sui livelli di serotonina nel cervello, contribuendo ai suoi effetti.<\/p><\/span>\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-1182c64 e-flex e-con-boxed e-con e-parent\" data-id=\"1182c64\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-6b249f8 elementor-widget elementor-widget-heading\" data-id=\"6b249f8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Articoli correlati<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-645600f elementor-widget elementor-widget-uael-posts\" data-id=\"645600f\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;classic_slides_to_show&quot;:3,&quot;classic_slides_to_show_tablet&quot;:2,&quot;classic_slides_to_show_mobile&quot;:1,&quot;classic_show_filters&quot;:&quot;no&quot;}\" data-widget_type=\"uael-posts.classic\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"uael-post__header\">\n\t\t\t\t\t<\/div>\n\t\t<div class=\"uael-post__body\">\n\t\t\t\n\t\t\n\t\t<div class=\"uael-blog-terms-position-above_content uael-post-image-top uael-post-grid uael-posts\" data-query-type=\"custom\" data-structure=\"normal\" data-layout=\"\" data-page=\"4884\" data-skin=\"classic\" data-filter-default=\"\" data-offset-top=\"30\" >\n\n\t\t\t\t\t\t\t<div class=\"uael-post-grid__inner uael-post__columns-3 uael-post__columns-tablet-2 uael-post__columns-mobile-1\">\n\t\t\t\n<div class=\"uael-post-wrapper   vaccinium-myrtillus-fruit-extract herb-extracts\">\n\t<div class=\"uael-post__bg-wrap uael-bg-wrap-disabled\">\n\n\t\t\t\t\n\t\t<div class=\"uael-post__inner-wrap uael-inner-wrap-disabled\">\n\n\t\t\t\t<div class=\"uael-post__thumbnail\">\n\t\t\t\n\t\t\t<a href=\"https:\/\/collagensei.com\/it\/vaccinium-myrtillus-fruit-extract-for-skin\/\" target=\"_self\" title=\"Estratto di frutta di Vaccinium Myrtillus per la pelle\"><img decoding=\"async\" width=\"1000\" height=\"562\" src=\"https:\/\/collagensei.com\/wp-content\/uploads\/2024\/10\/Vaccinium-Myrtillus-Fruit-Extract-for-Skin.webp\" class=\"attachment-full size-full wp-image-10545\" alt=\"Estratto di frutta di Vaccinium Myrtillus per la pelle\" srcset=\"https:\/\/collagensei.com\/wp-content\/uploads\/2024\/10\/Vaccinium-Myrtillus-Fruit-Extract-for-Skin.webp 1000w, https:\/\/collagensei.com\/wp-content\/uploads\/2024\/10\/Vaccinium-Myrtillus-Fruit-Extract-for-Skin-300x169.webp 300w, https:\/\/collagensei.com\/wp-content\/uploads\/2024\/10\/Vaccinium-Myrtillus-Fruit-Extract-for-Skin-768x432.webp 768w, https:\/\/collagensei.com\/wp-content\/uploads\/2024\/10\/Vaccinium-Myrtillus-Fruit-Extract-for-Skin-18x10.webp 18w\" sizes=\"(max-width: 1000px) 100vw, 1000px\" \/><\/a>\n\t\t\t\t\t<\/div>\n\t\t\n\t\t\t\n\t\t\t<div class=\"uael-post__content-wrap uael-content-wrap-disabled\">\n\t\t\t\t\t\t\t<div class=\"uael-post__terms-wrap\"><span class=\"uael-post__terms\"><a href=\"https:\/\/collagensei.com\/it\/category\/herb-extracts\/\" class=\"uael-listing__terms-link\" id=\"uael-post-term-herb-extracts\" aria-labelledby=\"uael-post-term-herb-extracts\">Estratti di erbe<\/a><\/span><\/div>\n\t\t\t\t\t\t<h3 class=\"uael-post__title\">\n\n\t\t\n\t\t\t\t\t\t<a href=\"https:\/\/collagensei.com\/it\/vaccinium-myrtillus-fruit-extract-for-skin\/\" target=\"_self\">\n\t\t\t\tEstratto di frutta di Vaccinium Myrtillus per la pelle\t\t\t<\/a>\n\n\t\t\t\t<\/h3>\n\t\t\t\t\t<div class=\"uael-post__meta-data\">\n\t\t\t\t\t<span class=\"uael-post__date\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fa-calendar\" viewbox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M12 192h424c6.6 0 12 5.4 12 12v260c0 26.5-21.5 48-48 48H48c-26.5 0-48-21.5-48-48V204c0-6.6 5.4-12 12-12zm436-44v-36c0-26.5-21.5-48-48-48h-48V12c0-6.6-5.4-12-12-12h-40c-6.6 0-12 5.4-12 12v52H160V12c0-6.6-5.4-12-12-12h-40c-6.6 0-12 5.4-12 12v52H48C21.5 64 0 85.5 0 112v36c0 6.6 5.4 12 12 12h424c6.6 0 12-5.4 12-12z\"><\/path><\/svg>\t\t\t\t\t\t\t\t\t\n\t\t\t2025\u5e748\u67081\u65e5\t\t<\/span>\n\t\t\t\t<span class=\"uael-post__comments\">\n\t\t\t\t\t\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fa-comments\" viewbox=\"0 0 576 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 192c0-88.4-93.1-160-208-160S0 103.6 0 192c0 34.3 14.1 65.9 38 92-13.4 30.2-35.5 54.2-35.8 54.5-2.2 2.3-2.8 5.7-1.5 8.7S4.8 352 8 352c36.6 0 66.9-12.3 88.7-25 32.2 15.7 70.3 25 111.3 25 114.9 0 208-71.6 208-160zm122 220c23.9-26 38-57.7 38-92 0-66.9-53.5-124.2-129.3-148.1.9 6.6 1.3 13.3 1.3 20.1 0 105.9-107.7 192-240 192-10.8 0-21.3-.8-31.7-1.9C207.8 439.6 281.8 480 368 480c41 0 79.1-9.2 111.3-25 21.8 12.7 52.1 25 88.7 25 3.2 0 6.1-1.9 7.3-4.8 1.3-2.9.7-6.3-1.5-8.7-.3-.3-22.4-24.2-35.8-54.5z\"><\/path><\/svg>\t\t\t\t\t\t\t\t\t\tNessun commento\t\t<\/span>\n\t\t\t\t<\/div>\n\t\t\n\t\t<div class=\"uael-post__excerpt\">\n\t\t\tIntroduzione Nel mondo in continua evoluzione della cura naturale della pelle, l'estratto di frutta Vaccinium myrtillus per la pelle, comunemente noto come estratto di mirtillo, \u00e8 emerso come ingrediente ...\t\t<\/div>\n\n\t\t\t\t\t<a class=\"uael-post__read-more elementor-button\" href=\"https:\/\/collagensei.com\/it\/vaccinium-myrtillus-fruit-extract-for-skin\/\" target=\"_self\" aria-labelledby=\"uael-post-3364\">\n\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-icon elementor-align-icon-left\">\n\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t<span class=\"elementor-button-text\" id=\"uael-post-3364\">Per saperne di pi\u00f9 \u2192<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t<\/a>\n\t\t\t\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\n\t<\/div>\n\n<\/div>\n\n<div class=\"uael-post-wrapper   ashwagandha ashwagandha-extract-powder ashwagandha-root-powder herb-extracts\">\n\t<div class=\"uael-post__bg-wrap uael-bg-wrap-disabled\">\n\n\t\t\t\t\n\t\t<div class=\"uael-post__inner-wrap uael-inner-wrap-disabled\">\n\n\t\t\t\t<div class=\"uael-post__thumbnail\">\n\t\t\t\n\t\t\t<a href=\"https:\/\/collagensei.com\/it\/ashwagandha-root-powder-vs-extract\/\" target=\"_self\" title=\"Polvere di radice di Ashwagandha o estratto: una guida completa alla scelta della forma giusta\"><img loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"562\" src=\"https:\/\/collagensei.com\/wp-content\/uploads\/2024\/09\/Ashwagandha-Root-Powder-vs-Extract.webp\" class=\"attachment-full size-full wp-image-10393\" alt=\"Polvere di radice di Ashwagandha vs. estratto\" srcset=\"https:\/\/collagensei.com\/wp-content\/uploads\/2024\/09\/Ashwagandha-Root-Powder-vs-Extract.webp 1000w, https:\/\/collagensei.com\/wp-content\/uploads\/2024\/09\/Ashwagandha-Root-Powder-vs-Extract-300x169.webp 300w, https:\/\/collagensei.com\/wp-content\/uploads\/2024\/09\/Ashwagandha-Root-Powder-vs-Extract-768x432.webp 768w\" sizes=\"(max-width: 1000px) 100vw, 1000px\" \/><\/a>\n\t\t\t\t\t<\/div>\n\t\t\n\t\t\t\n\t\t\t<div class=\"uael-post__content-wrap uael-content-wrap-disabled\">\n\t\t\t\t\t\t\t<div class=\"uael-post__terms-wrap\"><span class=\"uael-post__terms\"><a href=\"https:\/\/collagensei.com\/it\/category\/ashwagandha\/\" class=\"uael-listing__terms-link\" id=\"uael-post-term-ashwagandha\" aria-labelledby=\"uael-post-term-ashwagandha\">Ashwagandha<\/a><\/span><\/div>\n\t\t\t\t\t\t<h3 class=\"uael-post__title\">\n\n\t\t\n\t\t\t\t\t\t<a href=\"https:\/\/collagensei.com\/it\/ashwagandha-root-powder-vs-extract\/\" target=\"_self\">\n\t\t\t\tPolvere di radice di Ashwagandha o estratto: una guida completa alla scelta della forma giusta\t\t\t<\/a>\n\n\t\t\t\t<\/h3>\n\t\t\t\t\t<div class=\"uael-post__meta-data\">\n\t\t\t\t\t<span class=\"uael-post__date\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fa-calendar\" viewbox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M12 192h424c6.6 0 12 5.4 12 12v260c0 26.5-21.5 48-48 48H48c-26.5 0-48-21.5-48-48V204c0-6.6 5.4-12 12-12zm436-44v-36c0-26.5-21.5-48-48-48h-48V12c0-6.6-5.4-12-12-12h-40c-6.6 0-12 5.4-12 12v52H160V12c0-6.6-5.4-12-12-12h-40c-6.6 0-12 5.4-12 12v52H48C21.5 64 0 85.5 0 112v36c0 6.6 5.4 12 12 12h424c6.6 0 12-5.4 12-12z\"><\/path><\/svg>\t\t\t\t\t\t\t\t\t\n\t\t\t2025\u5e747\u670829\u65e5\t\t<\/span>\n\t\t\t\t<span class=\"uael-post__comments\">\n\t\t\t\t\t\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fa-comments\" viewbox=\"0 0 576 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 192c0-88.4-93.1-160-208-160S0 103.6 0 192c0 34.3 14.1 65.9 38 92-13.4 30.2-35.5 54.2-35.8 54.5-2.2 2.3-2.8 5.7-1.5 8.7S4.8 352 8 352c36.6 0 66.9-12.3 88.7-25 32.2 15.7 70.3 25 111.3 25 114.9 0 208-71.6 208-160zm122 220c23.9-26 38-57.7 38-92 0-66.9-53.5-124.2-129.3-148.1.9 6.6 1.3 13.3 1.3 20.1 0 105.9-107.7 192-240 192-10.8 0-21.3-.8-31.7-1.9C207.8 439.6 281.8 480 368 480c41 0 79.1-9.2 111.3-25 21.8 12.7 52.1 25 88.7 25 3.2 0 6.1-1.9 7.3-4.8 1.3-2.9.7-6.3-1.5-8.7-.3-.3-22.4-24.2-35.8-54.5z\"><\/path><\/svg>\t\t\t\t\t\t\t\t\t\tNessun commento\t\t<\/span>\n\t\t\t\t<\/div>\n\t\t\n\t\t<div class=\"uael-post__excerpt\">\n\t\t\tPolvere di radice di ashwagandha ed estratto: immaginate di trovarvi in un negozio di integratori, davanti a scaffali pieni di prodotti a base di ashwagandha. Una bottiglia vanta la \"polvere di radice\", un'altra ...\t\t<\/div>\n\n\t\t\t\t\t<a class=\"uael-post__read-more elementor-button\" href=\"https:\/\/collagensei.com\/it\/ashwagandha-root-powder-vs-extract\/\" target=\"_self\" aria-labelledby=\"uael-post-3074\">\n\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-icon elementor-align-icon-left\">\n\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t<span class=\"elementor-button-text\" id=\"uael-post-3074\">Per saperne di pi\u00f9 \u2192<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t<\/a>\n\t\t\t\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\n\t<\/div>\n\n<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\n\t\t<\/div>\n\n\t\t\t\t\t\t<\/div>\n\t\t<div class=\"uael-post__footer\">\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-39f9f93d e-flex e-con-boxed e-con e-parent\" data-id=\"39f9f93d\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-5ca30329 e-con-full e-flex e-con e-child\" data-id=\"5ca30329\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-73289ae5 elementor-widget elementor-widget-heading\" data-id=\"73289ae5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Affidata da molti, pronta per voi: Leggi le testimonianze e chiedi subito informazioni<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-19000059 e-con-full e-flex e-con e-child\" data-id=\"19000059\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-6c19344a e-con-full e-flex e-con e-child\" data-id=\"6c19344a\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-3e340bb3 elementor-testimonial--skin-default elementor-testimonial--layout-image_inline elementor-testimonial--align-center elementor-arrows-yes elementor-pagination-type-bullets elementor-widget elementor-widget-testimonial-carousel\" data-id=\"3e340bb3\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;show_arrows&quot;:&quot;yes&quot;,&quot;pagination&quot;:&quot;bullets&quot;,&quot;speed&quot;:500,&quot;autoplay&quot;:&quot;yes&quot;,&quot;autoplay_speed&quot;:5000,&quot;loop&quot;:&quot;yes&quot;,&quot;pause_on_hover&quot;:&quot;yes&quot;,&quot;pause_on_interaction&quot;:&quot;yes&quot;,&quot;space_between&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:10,&quot;sizes&quot;:[]},&quot;space_between_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:10,&quot;sizes&quot;:[]},&quot;space_between_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:10,&quot;sizes&quot;:[]}}\" data-widget_type=\"testimonial-carousel.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper\">\n\t\t\t\t\t<div class=\"elementor-main-swiper swiper\" role=\"region\" aria-roledescription=\"carousel\" aria-label=\"Diapositive\">\n\t\t\t\t<div class=\"swiper-wrapper\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-testimonial\">\n\t\t\t\t\t\t\t<div class=\"elementor-testimonial__content\">\n\t\t\t\t\t<div class=\"elementor-testimonial__text\">\n\t\t\t\t\t\tLa nostra azienda, Natural Health Solutions, si rifornisce di vari estratti di erbe da Gensei da diversi anni. Come la nostra responsabile degli acquisti, Sarah Chen, sono rimasta costantemente colpita dalla qualit\u00e0 dei loro estratti di erbe cinesi. Apprezziamo in particolare le opzioni di estratto di erbe cinesi per il t\u00e8, che sono un ingrediente chiave delle nostre popolari miscele di t\u00e8 per il benessere. Gensei ci fornisce anche l'estratto di frutta di Vaccinium Myrtillus, di qualit\u00e0 eccellente, per i nostri integratori per la salute degli occhi e l'estratto di corteccia di pino in polvere per le nostre formulazioni antiossidanti. L'affidabilit\u00e0 e l'ampia scelta fanno di Gensei il nostro fornitore di estratti di erbe di riferimento.\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"elementor-testimonial__footer\">\n\t\t\t\t\t\t\t\t<cite class=\"elementor-testimonial__cite\"><span class=\"elementor-testimonial__name\">Sarah Chen<\/span><span class=\"elementor-testimonial__title\">Responsabile degli acquisti, Soluzioni per la salute naturale<\/span><\/cite>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-testimonial\">\n\t\t\t\t\t\t\t<div class=\"elementor-testimonial__content\">\n\t\t\t\t\t<div class=\"elementor-testimonial__text\">\n\t\t\t\t\t\tNoi di Botanical Boosters siamo specializzati nella creazione di integratori a base di erbe di alta qualit\u00e0. Trovare un fornitore affidabile di estratti di erbe \u00e8 fondamentale per la nostra attivit\u00e0 e Gensei si \u00e8 dimostrato un partner eccellente. Mark Johnson, il nostro direttore della ricerca e sviluppo, \u00e8 rimasto molto soddisfatto della loro gamma di estratti di erbe cinesi e della potenza specifica del loro estratto di frutti di Vaccinium Myrtillus. Utilizziamo anche la loro polvere di estratto di corteccia di pino in molte delle nostre formulazioni, grazie alla loro qualit\u00e0 costante. L'offerta di estratti di t\u00e8 alle erbe cinesi ci ha permesso di ampliare la nostra linea di prodotti. L'impegno di Gensei per la qualit\u00e0 e la sua ampia scelta ne fanno un fornitore di primo livello nel mercato degli estratti di erbe.\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"elementor-testimonial__footer\">\n\t\t\t\t\t\t\t\t<cite class=\"elementor-testimonial__cite\"><span class=\"elementor-testimonial__name\">Mark Johnson<\/span><span class=\"elementor-testimonial__title\">Direttore R&amp;S, Booster botanici<\/span><\/cite>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-prev\" role=\"button\" tabindex=\"0\" aria-label=\"Precedente\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-eicon-chevron-left\" viewbox=\"0 0 1000 1000\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M646 125C629 125 613 133 604 142L308 442C296 454 292 471 292 487 292 504 296 521 308 533L604 854C617 867 629 875 646 875 663 875 679 871 692 858 704 846 713 829 713 812 713 796 708 779 692 767L438 487 692 225C700 217 708 204 708 187 708 171 704 154 692 142 675 129 663 125 646 125Z\"><\/path><\/svg>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-next\" role=\"button\" tabindex=\"0\" aria-label=\"Avanti\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-eicon-chevron-right\" viewbox=\"0 0 1000 1000\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M696 533C708 521 713 504 713 487 713 471 708 454 696 446L400 146C388 133 375 125 354 125 338 125 325 129 313 142 300 154 292 171 292 187 292 204 296 221 308 233L563 492 304 771C292 783 288 800 288 817 288 833 296 850 308 863 321 871 338 875 354 875 371 875 388 867 400 854L696 533Z\"><\/path><\/svg>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-pagination\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-a0d287f e-con-full e-flex e-con e-child\" data-id=\"a0d287f\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-732bcc7 uael-cf7-btn-size-xs uael-cf7-style-box uael-cf7-input-size-sm uael-cf7-button-left uael-cf7-highlight-style-default elementor-widget elementor-widget-uael-cf7-styler\" data-id=\"732bcc7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"uael-cf7-styler.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class = \"uael-cf7-container\">\n\t\t\t\t\t\t<div class = \"uael-cf7 uael-cf7-style elementor-clickable\">\n\t\t\t\t\t\t\n<div class=\"wpcf7 no-js\" id=\"wpcf7-f74-o1\" lang=\"zh-CN\" dir=\"ltr\" data-wpcf7-id=\"74\">\n<div class=\"screen-reader-response\"><p role=\"status\" aria-live=\"polite\" aria-atomic=\"true\"><\/p> <ul><\/ul><\/div>\n<form action=\"\/it\/wp-json\/wp\/v2\/pages\/4884#wpcf7-f74-o1\" method=\"post\" class=\"wpcf7-form init\" aria-label=\"\u7559\u8a00\u8868\u5355\" novalidate=\"novalidate\" data-status=\"init\" data-trp-original-action=\"\/it\/wp-json\/wp\/v2\/pages\/4884#wpcf7-f74-o1\">\n<fieldset class=\"hidden-fields-container\"><input type=\"hidden\" name=\"_wpcf7\" value=\"74\" \/><input type=\"hidden\" name=\"_wpcf7_version\" value=\"6.1.5\" \/><input type=\"hidden\" name=\"_wpcf7_locale\" value=\"zh_CN\" \/><input type=\"hidden\" name=\"_wpcf7_unit_tag\" value=\"wpcf7-f74-o1\" \/><input type=\"hidden\" name=\"_wpcf7_container_post\" value=\"0\" \/><input type=\"hidden\" name=\"_wpcf7_posted_data_hash\" value=\"\" \/>\n<\/fieldset>\n<div class=\"stay-touch\">\n\t<ul>\n\t\t<li>\n\t\t\t<p><label> Nome: <span class=\"wpcf7-form-control-wrap\" data-name=\"your-name\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"text\" name=\"your-name\" \/><\/span><\/label>\n\t\t\t<\/p>\n\t\t<\/li>\n\t\t<li>\n\t\t\t<p><label> Nome della societ\u00e0: <span class=\"wpcf7-form-control-wrap\" data-name=\"your-company\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"text\" name=\"your-company\" \/><\/span><\/label>\n\t\t\t<\/p>\n\t\t<\/li>\n\t\t<li>\n\t\t\t<p><label> E-mail: <span class=\"wpcf7-form-control-wrap\" data-name=\"your-email\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"text\" name=\"your-email\" \/><\/span><\/label>\n\t\t\t<\/p>\n\t\t<\/li>\n\t\t<li>\n\t\t\t<p><label> Tel: <span class=\"wpcf7-form-control-wrap\" data-name=\"your-tel\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"text\" name=\"your-tel\" \/><\/span><\/label>\n\t\t\t<\/p>\n\t\t<\/li>\n\t\t<li>\n\t\t\t<p><label> Messaggio: <span class=\"wpcf7-form-control-wrap\" data-name=\"your-message\"><textarea cols=\"40\" rows=\"10\" maxlength=\"2000\" class=\"wpcf7-form-control wpcf7-textarea wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" name=\"your-message\"><\/textarea><\/span><\/label>\n\t\t\t<\/p>\n\t\t<\/li>\n\t\t<li style=\"text-align:center\">\n\t\t\t<p><input class=\"wpcf7-form-control wpcf7-submit has-spinner\" type=\"submit\" value=\"INVIO\" \/>\n\t\t\t<\/p>\n\t\t<\/li>\n\t<\/ul>\n<\/div><div class=\"wpcf7-response-output\" aria-hidden=\"true\"><\/div>\n<input type=\"hidden\" name=\"trp-form-language\" value=\"it\"\/><\/form>\n<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>herb extracts supplier As a premier herb extracts supplier and Chinese herbal extract distributor, we specialize in delivering high-quality, natural [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_uag_custom_page_level_css":"","site-sidebar-layout":"no-sidebar","site-content-layout":"","ast-site-content-layout":"full-width-container","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"disabled","ast-breadcrumbs-content":"","ast-featured-img":"disabled","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"class_list":["post-4884","page","type-page","status-publish","hentry"],"uagb_featured_image_src":{"full":false,"thumbnail":false,"medium":false,"medium_large":false,"large":false,"1536x1536":false,"2048x2048":false,"trp-custom-language-flag":false},"uagb_author_info":{"display_name":"collagensei.com","author_link":"https:\/\/collagensei.com\/it\/author\/collagensei\/"},"uagb_comment_info":0,"uagb_excerpt":"herb extracts supplier As a premier herb extracts supplier and Chinese herbal extract distributor, we specialize in delivering high-quality, natural [&hellip;]","_links":{"self":[{"href":"https:\/\/collagensei.com\/it\/wp-json\/wp\/v2\/pages\/4884","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/collagensei.com\/it\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/collagensei.com\/it\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/collagensei.com\/it\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/collagensei.com\/it\/wp-json\/wp\/v2\/comments?post=4884"}],"version-history":[{"count":31,"href":"https:\/\/collagensei.com\/it\/wp-json\/wp\/v2\/pages\/4884\/revisions"}],"predecessor-version":[{"id":17394,"href":"https:\/\/collagensei.com\/it\/wp-json\/wp\/v2\/pages\/4884\/revisions\/17394"}],"wp:attachment":[{"href":"https:\/\/collagensei.com\/it\/wp-json\/wp\/v2\/media?parent=4884"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}