{"id":593,"count":1,"description":"","link":"https:\/\/collagensei.com\/ko\/category\/collagen-protein\/","name":"\ucf5c\ub77c\uac90 \ub2e8\ubc31\uc9c8","slug":"%ec%bd%9c%eb%9d%bc%ea%b2%90-%eb%8b%a8%eb%b0%b1%ec%a7%88","taxonomy":"category","parent":0,"meta":[],"_links":{"self":[{"href":"https:\/\/collagensei.com\/ko\/wp-json\/wp\/v2\/categories\/593","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/collagensei.com\/ko\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/collagensei.com\/ko\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/collagensei.com\/ko\/wp-json\/wp\/v2\/posts?categories=593"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}